{"id":12248,"date":"2022-12-22T11:27:19","date_gmt":"2022-12-22T11:27:19","guid":{"rendered":"https:\/\/www.public.sn\/?p=12248"},"modified":"2022-12-22T11:27:35","modified_gmt":"2022-12-22T11:27:35","slug":"niasse-pourquoi-je-nai-pas-toujours-quitte-lafp","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/","title":{"rendered":"Niasse : \u00ab\u00a0Pourquoi je n&rsquo;ai pas toujours quitt\u00e9 l&rsquo;AFP\u00a0\u00bb"},"content":{"rendered":"\n<p>Lors de la conf\u00e9rence de presse du secr\u00e9tariat ex\u00e9cutif permanent de la grande coalition de Benno Bokk Yakaar (Bby)<a href=\"https:\/\/www.public.sn\/index.php\/2022\/12\/21\/3e-mandat-presidentielle-2024-bby-en-conclave-vendredi\/\">, Moustapha Niasse<\/a> est revenu sur sa succession \u00e0 la t\u00eate de l\u2019Alliance de forces de progr\u00e8s (Afp).\u00a0<\/p><div class=\"publi-paragraphe1\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"publi-4100315918\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n\n\n\n<p>Le secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019Alliance des Forces de Progr\u00e8s (AFP) a encore \u00e9voqu\u00e9 sa succession. L\u2019ancien pr\u00e9sident de l\u2019Assembl\u00e9e nationale a une nouvelle fois \u00e9tonn\u00e9 son en soutenant que, s\u2019il reste encore au poste de secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019AFP, c\u2019est parce qu\u2019il n\u2019a pas encore trouv\u00e9 de rempla\u00e7ant (Sic). <\/p>\n\n\n\n<p>C\u2019est \u00e0 croire qu\u2019il n\u2019en trouvera jamais ! Mais, selon Moustapha Niasse, le congr\u00e8s de son parti qui est en train de se pr\u00e9parer se fera d\u00e9mocratiquement. <em>\u00ab Le 16 Juin dernier, lors de l\u2019anniversaire du parti, j\u2019ai rappel\u00e9 aux camarades du Parti que si je reste au poste de secr\u00e9taire g\u00e9n\u00e9ral national, c\u2019est parce que je n\u2019ai pas encore qui me remplacer. Le congr\u00e8s devait se tenir en Janvier, mais c\u2019est la direction du parti qui s\u2019est r\u00e9unie pendant que j\u2019\u00e9tais en France pour demander d\u2019attendre la fin de la vente des cartes. Maintenant ma succession se fera d\u00e9mocratiquement \u00e0 l\u2019issue d\u2019un congr\u00e8s qui est en train de se pr\u00e9parer. Et celui ou celle qui sera choisi va diriger le parti \u00bb, <\/em>a-t-il encore indiqu\u00e9 en marge de la conf\u00e9rence de presse du secr\u00e9tariat Ex\u00e9cutif national de la coalition BBY&#8230;<\/p>\n\n\n\n<p>Comme quoi, de toute la masse de cadres dont dispose l\u2019AFP, aucun d\u2019eux n\u2019est digne de succ\u00e9der \u00e0 Moustapha Niasse. Comme nous l\u2019\u00e9crivions ici dans ces colonnes, de son vivant Niasse ne se choisira jamais de successeur et mourra \u00e0 la barre !<\/p>\n<div class=\"publi-apres-le-contenu\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"publi-1149323618\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Lors de la conf\u00e9rence de presse du secr\u00e9tariat ex\u00e9cutif permanent de la grande coalition de Benno Bokk Yakaar (Bby), Moustapha Niasse est revenu sur sa succession \u00e0 la t\u00eate de l\u2019Alliance de forces de progr\u00e8s (Afp).\u00a0 Le secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019Alliance des Forces de Progr\u00e8s (AFP) a encore \u00e9voqu\u00e9 sa succession. L\u2019ancien pr\u00e9sident de l\u2019Assembl\u00e9e nationale a une nouvelle fois \u00e9tonn\u00e9 son en soutenant que, s\u2019il reste encore au poste de secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019AFP, c\u2019est parce qu\u2019il n\u2019a pas encore trouv\u00e9 de rempla\u00e7ant (Sic). C\u2019est \u00e0 croire qu\u2019il n\u2019en trouvera jamais ! Mais, selon Moustapha Niasse, le congr\u00e8s de son parti qui est en train de se pr\u00e9parer se fera d\u00e9mocratiquement. \u00ab Le 16 Juin dernier, lors de l\u2019anniversaire du parti, j\u2019ai rappel\u00e9 aux camarades du Parti que si je reste au poste de secr\u00e9taire g\u00e9n\u00e9ral national, c\u2019est parce que je n\u2019ai pas encore qui me remplacer. Le congr\u00e8s devait se tenir en Janvier, mais c\u2019est la direction du parti qui s\u2019est r\u00e9unie pendant que j\u2019\u00e9tais en France pour demander d\u2019attendre la fin de la vente des cartes. Maintenant ma succession se fera d\u00e9mocratiquement \u00e0 l\u2019issue d\u2019un congr\u00e8s qui est en train de se pr\u00e9parer. Et celui ou celle qui sera choisi va diriger le parti \u00bb, a-t-il encore indiqu\u00e9 en marge de la conf\u00e9rence de presse du secr\u00e9tariat Ex\u00e9cutif national de la coalition BBY&#8230; Comme quoi, de toute la masse de cadres dont dispose l\u2019AFP, aucun d\u2019eux n\u2019est digne de succ\u00e9der \u00e0 Moustapha Niasse. Comme nous l\u2019\u00e9crivions ici dans ces colonnes, de son vivant Niasse ne se choisira jamais de successeur et mourra \u00e0 la barre !<\/p>\n","protected":false},"author":1,"featured_media":12249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,3,372],"tags":[806],"class_list":["post-12248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-politique","category-vedette","tag-moustapha-niasse","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Niasse : &quot;Pourquoi je n&#039;ai pas toujours quitt\u00e9 l&#039;AFP&quot; - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Niasse : &quot;Pourquoi je n&#039;ai pas toujours quitt\u00e9 l&#039;AFP&quot; - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"Lors de la conf\u00e9rence de presse du secr\u00e9tariat ex\u00e9cutif permanent de la grande coalition de Benno Bokk Yakaar (Bby), Moustapha Niasse est revenu sur sa succession \u00e0 la t\u00eate de l\u2019Alliance de forces de progr\u00e8s (Afp).\u00a0 Le secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019Alliance des Forces de Progr\u00e8s (AFP) a encore \u00e9voqu\u00e9 sa succession. L\u2019ancien pr\u00e9sident de l\u2019Assembl\u00e9e nationale a une nouvelle fois \u00e9tonn\u00e9 son en soutenant que, s\u2019il reste encore au poste de secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019AFP, c\u2019est parce qu\u2019il n\u2019a pas encore trouv\u00e9 de rempla\u00e7ant (Sic). C\u2019est \u00e0 croire qu\u2019il n\u2019en trouvera jamais ! Mais, selon Moustapha Niasse, le congr\u00e8s de son parti qui est en train de se pr\u00e9parer se fera d\u00e9mocratiquement. \u00ab Le 16 Juin dernier, lors de l\u2019anniversaire du parti, j\u2019ai rappel\u00e9 aux camarades du Parti que si je reste au poste de secr\u00e9taire g\u00e9n\u00e9ral national, c\u2019est parce que je n\u2019ai pas encore qui me remplacer. Le congr\u00e8s devait se tenir en Janvier, mais c\u2019est la direction du parti qui s\u2019est r\u00e9unie pendant que j\u2019\u00e9tais en France pour demander d\u2019attendre la fin de la vente des cartes. Maintenant ma succession se fera d\u00e9mocratiquement \u00e0 l\u2019issue d\u2019un congr\u00e8s qui est en train de se pr\u00e9parer. Et celui ou celle qui sera choisi va diriger le parti \u00bb, a-t-il encore indiqu\u00e9 en marge de la conf\u00e9rence de presse du secr\u00e9tariat Ex\u00e9cutif national de la coalition BBY&#8230; Comme quoi, de toute la masse de cadres dont dispose l\u2019AFP, aucun d\u2019eux n\u2019est digne de succ\u00e9der \u00e0 Moustapha Niasse. Comme nous l\u2019\u00e9crivions ici dans ces colonnes, de son vivant Niasse ne se choisira jamais de successeur et mourra \u00e0 la barre !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-22T11:27:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-22T11:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"Niasse : \u00ab\u00a0Pourquoi je n&rsquo;ai pas toujours quitt\u00e9 l&rsquo;AFP\u00a0\u00bb\",\"datePublished\":\"2022-12-22T11:27:19+00:00\",\"dateModified\":\"2022-12-22T11:27:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\"},\"wordCount\":325,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.public.sn\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg\",\"keywords\":[\"Moustapha Niasse\"],\"articleSection\":[\"ACTUALIT\u00c9S\",\"POLITIQUE\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\",\"url\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\",\"name\":\"Niasse : \\\"Pourquoi je n'ai pas toujours quitt\u00e9 l'AFP\\\" - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.public.sn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg\",\"datePublished\":\"2022-12-22T11:27:19+00:00\",\"dateModified\":\"2022-12-22T11:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage\",\"url\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg\",\"contentUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.public.sn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Niasse : \u00ab\u00a0Pourquoi je n&rsquo;ai pas toujours quitt\u00e9 l&rsquo;AFP\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.public.sn\/#website\",\"url\":\"https:\/\/www.public.sn\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.public.sn\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.public.sn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.public.sn\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\/\/www.public.sn\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\/\/www.public.sn\"],\"url\":\"https:\/\/www.public.sn\/index.php\/author\/admin7324\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Niasse : \"Pourquoi je n'ai pas toujours quitt\u00e9 l'AFP\" - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/","og_locale":"fr_FR","og_type":"article","og_title":"Niasse : \"Pourquoi je n'ai pas toujours quitt\u00e9 l'AFP\" - LE PUBLIC","og_description":"Lors de la conf\u00e9rence de presse du secr\u00e9tariat ex\u00e9cutif permanent de la grande coalition de Benno Bokk Yakaar (Bby), Moustapha Niasse est revenu sur sa succession \u00e0 la t\u00eate de l\u2019Alliance de forces de progr\u00e8s (Afp).\u00a0 Le secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019Alliance des Forces de Progr\u00e8s (AFP) a encore \u00e9voqu\u00e9 sa succession. L\u2019ancien pr\u00e9sident de l\u2019Assembl\u00e9e nationale a une nouvelle fois \u00e9tonn\u00e9 son en soutenant que, s\u2019il reste encore au poste de secr\u00e9taire g\u00e9n\u00e9ral national de l\u2019AFP, c\u2019est parce qu\u2019il n\u2019a pas encore trouv\u00e9 de rempla\u00e7ant (Sic). C\u2019est \u00e0 croire qu\u2019il n\u2019en trouvera jamais ! Mais, selon Moustapha Niasse, le congr\u00e8s de son parti qui est en train de se pr\u00e9parer se fera d\u00e9mocratiquement. \u00ab Le 16 Juin dernier, lors de l\u2019anniversaire du parti, j\u2019ai rappel\u00e9 aux camarades du Parti que si je reste au poste de secr\u00e9taire g\u00e9n\u00e9ral national, c\u2019est parce que je n\u2019ai pas encore qui me remplacer. Le congr\u00e8s devait se tenir en Janvier, mais c\u2019est la direction du parti qui s\u2019est r\u00e9unie pendant que j\u2019\u00e9tais en France pour demander d\u2019attendre la fin de la vente des cartes. Maintenant ma succession se fera d\u00e9mocratiquement \u00e0 l\u2019issue d\u2019un congr\u00e8s qui est en train de se pr\u00e9parer. Et celui ou celle qui sera choisi va diriger le parti \u00bb, a-t-il encore indiqu\u00e9 en marge de la conf\u00e9rence de presse du secr\u00e9tariat Ex\u00e9cutif national de la coalition BBY&#8230; Comme quoi, de toute la masse de cadres dont dispose l\u2019AFP, aucun d\u2019eux n\u2019est digne de succ\u00e9der \u00e0 Moustapha Niasse. Comme nous l\u2019\u00e9crivions ici dans ces colonnes, de son vivant Niasse ne se choisira jamais de successeur et mourra \u00e0 la barre !","og_url":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/","og_site_name":"LE PUBLIC","article_published_time":"2022-12-22T11:27:19+00:00","article_modified_time":"2022-12-22T11:27:35+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"Niasse : \u00ab\u00a0Pourquoi je n&rsquo;ai pas toujours quitt\u00e9 l&rsquo;AFP\u00a0\u00bb","datePublished":"2022-12-22T11:27:19+00:00","dateModified":"2022-12-22T11:27:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/"},"wordCount":325,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg","keywords":["Moustapha Niasse"],"articleSection":["ACTUALIT\u00c9S","POLITIQUE","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/","url":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/","name":"Niasse : \"Pourquoi je n'ai pas toujours quitt\u00e9 l'AFP\" - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg","datePublished":"2022-12-22T11:27:19+00:00","dateModified":"2022-12-22T11:27:35+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/22\/niasse-pourquoi-je-nai-pas-toujours-quitte-lafp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"Niasse : \u00ab\u00a0Pourquoi je n&rsquo;ai pas toujours quitt\u00e9 l&rsquo;AFP\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/niasse.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/12248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=12248"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/12248\/revisions"}],"predecessor-version":[{"id":12250,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/12248\/revisions\/12250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/12249"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=12248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=12248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=12248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}