{"id":13008,"date":"2022-12-28T13:51:15","date_gmt":"2022-12-28T13:51:15","guid":{"rendered":"https:\/\/www.public.sn\/?p=13008"},"modified":"2022-12-28T13:52:07","modified_gmt":"2022-12-28T13:52:07","slug":"28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/","title":{"rendered":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 !"},"content":{"rendered":"<p><strong>28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022. Voil\u00e0 15 ans d\u00e9j\u00e0 que disparaissait le cinqui\u00e8me khalife de Bamba. <a href=\"https:\/\/www.public.sn\/index.php\/2022\/10\/14\/kelcom-les-recoltes-demarrent\/\">Serigne Saliou Mback\u00e9<\/a> a \u00e0 son compte un long khalifat\u00a0: 17 ans (1990-2007) \u00e0 la t\u00eate du Mouridisme, sans qu\u2019on puisse lui reprocher grand-chose.\u00a0<\/strong><\/p><div id=\"publi-3213084830\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Vendredi 28 d\u00e9cembre 2007, Serigne Saliou Mback\u00e9 quitte ce bas monde \u00e0 l\u2019\u00e2ge de 92 ans. Dernier fils de Cheikh Ahmadou Bamba Mback\u00e9 \u00e0 avoir occup\u00e9 le khalifat (17 ans), celui que l\u2019on surnommait \u00ab\u00a0Borom Jamono\u00a0\u00bb a vu le jour en 1915 \u00e0 Diourbel.<\/p>\n<p>Il a fait de l\u2019\u00e9ducation son occupation continue. En effet, ses daaras o\u00f9 les \u00e9tudiants travaillent dans les champs \u00e9parpill\u00e9s \u00e0 travers le pays datent de plus d\u2019un demi-si\u00e8cle.<\/p>\n<p>L\u2019apprentissage du travail chez les jeunes leur conf\u00e8re la conscience qui permet \u00e0 l\u2019homme de s\u2019accomplir, d\u2019\u00eatre utile \u00e0 lui-m\u00eame et \u00e0 la communaut\u00e9. Quant \u00e0 l\u2019\u00e9ducation, elle a pour but dans ces \u00ab\u00a0daaras\u00a0\u00bb de faire conna\u00eetre aux jeunes disciples le sens de la vie, les r\u00e8gles de comportement dans la soci\u00e9t\u00e9, les normes spirituelles et morales dont l\u2019observation assure \u00e0 chacun la sauvegarde de son humanit\u00e9.<\/p>\n<p>Serigne Saliou fondateur de plusieurs daraas destin\u00e9s \u00e0 la m\u00e9morisation du Saint Coran, l\u2019\u00e9ducation et l\u2019apprentissage de la vie, il mettra aussi l\u2019accent\u00a0sur les sciences religieuses car pour lui, la foi en Dieu est la principale dimension de l\u2019homme. Cette entreprise d\u2019\u00e9ducation, qui s\u2019adressait \u00e0 des milliers d\u2019\u00e9l\u00e8ves, \u00e9tait entour\u00e9e du plus grand soin de la part de Serigne Saliou qui y consacrait d\u2019\u00e9normes ressources, donnant ainsi le signe d\u2019un engagement personnel, profond.<\/p>\n<p>D\u00e9crit comme un \u00e9ducateur hors pair, un travailleur et un soufi affirm\u00e9, Serigne Saliou Mback\u00e9 avait une ma\u00eetrise des rouages de l\u2019\u00e9ducation religieuse. Serigne Saliou \u00e9tait \u00e9galement connu pour avoir \u00e9t\u00e9 un grand producteur agricole avec notamment Khelcom sur une surface de 45 000 hectares.<\/p>\n<p>Il reprit de nombreux travaux de r\u00e9novation aussi bien internes qu\u2019externes de la mosqu\u00e9e et la construction de l\u2019universit\u00e9 islamique qu\u2019avait entam\u00e9e son fr\u00e8re a\u00een\u00e9 Abdoul Ahad Mback\u00e9, l\u2019assainissement de la ville de Touba. En d\u00e9finitive, Serigne Saliou a fait du Mouridisme une voie soufie connue actuellement \u00e0 travers le monde entier.<\/p>\n<p>Il est inhum\u00e9 dans l\u2019enceinte de la grande mosqu\u00e9e de Touba.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"publi-1207663781\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022. Voil\u00e0 15 ans d\u00e9j\u00e0 que disparaissait le cinqui\u00e8me khalife de Bamba. Serigne Saliou Mback\u00e9 a \u00e0 son compte un long khalifat\u00a0: 17 ans (1990-2007) \u00e0 la t\u00eate du Mouridisme, sans qu\u2019on puisse lui reprocher grand-chose.\u00a0 Vendredi 28 d\u00e9cembre 2007, Serigne Saliou Mback\u00e9 quitte ce bas monde \u00e0 l\u2019\u00e2ge de 92 ans. Dernier fils de Cheikh Ahmadou Bamba Mback\u00e9 \u00e0 avoir occup\u00e9 le khalifat (17 ans), celui que l\u2019on surnommait \u00ab\u00a0Borom Jamono\u00a0\u00bb a vu le jour en 1915 \u00e0 Diourbel. Il a fait de l\u2019\u00e9ducation son occupation continue. En effet, ses daaras o\u00f9 les \u00e9tudiants travaillent dans les champs \u00e9parpill\u00e9s \u00e0 travers le pays datent de plus d\u2019un demi-si\u00e8cle. L\u2019apprentissage du travail chez les jeunes leur conf\u00e8re la conscience qui permet \u00e0 l\u2019homme de s\u2019accomplir, d\u2019\u00eatre utile \u00e0 lui-m\u00eame et \u00e0 la communaut\u00e9. Quant \u00e0 l\u2019\u00e9ducation, elle a pour but dans ces \u00ab\u00a0daaras\u00a0\u00bb de faire conna\u00eetre aux jeunes disciples le sens de la vie, les r\u00e8gles de comportement dans la soci\u00e9t\u00e9, les normes spirituelles et morales dont l\u2019observation assure \u00e0 chacun la sauvegarde de son humanit\u00e9. Serigne Saliou fondateur de plusieurs daraas destin\u00e9s \u00e0 la m\u00e9morisation du Saint Coran, l\u2019\u00e9ducation et l\u2019apprentissage de la vie, il mettra aussi l\u2019accent\u00a0sur les sciences religieuses car pour lui, la foi en Dieu est la principale dimension de l\u2019homme. Cette entreprise d\u2019\u00e9ducation, qui s\u2019adressait \u00e0 des milliers d\u2019\u00e9l\u00e8ves, \u00e9tait entour\u00e9e du plus grand soin de la part de Serigne Saliou qui y consacrait d\u2019\u00e9normes ressources, donnant ainsi le signe d\u2019un engagement personnel, profond. D\u00e9crit comme un \u00e9ducateur hors pair, un travailleur et un soufi affirm\u00e9, Serigne Saliou Mback\u00e9 avait une ma\u00eetrise des rouages de l\u2019\u00e9ducation religieuse. Serigne Saliou \u00e9tait \u00e9galement connu pour avoir \u00e9t\u00e9 un grand producteur agricole avec notamment Khelcom sur une surface de 45 000 hectares. Il reprit de nombreux travaux de r\u00e9novation aussi bien internes qu\u2019externes de la mosqu\u00e9e et la construction de l\u2019universit\u00e9 islamique qu\u2019avait entam\u00e9e son fr\u00e8re a\u00een\u00e9 Abdoul Ahad Mback\u00e9, l\u2019assainissement de la ville de Touba. En d\u00e9finitive, Serigne Saliou a fait du Mouridisme une voie soufie connue actuellement \u00e0 travers le monde entier. Il est inhum\u00e9 dans l\u2019enceinte de la grande mosqu\u00e9e de Touba. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":13009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,1,4,372],"tags":[],"class_list":["post-13008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-non-classe","category-societe","category-vedette","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 ! - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 ! - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022. Voil\u00e0 15 ans d\u00e9j\u00e0 que disparaissait le cinqui\u00e8me khalife de Bamba. Serigne Saliou Mback\u00e9 a \u00e0 son compte un long khalifat\u00a0: 17 ans (1990-2007) \u00e0 la t\u00eate du Mouridisme, sans qu\u2019on puisse lui reprocher grand-chose.\u00a0 Vendredi 28 d\u00e9cembre 2007, Serigne Saliou Mback\u00e9 quitte ce bas monde \u00e0 l\u2019\u00e2ge de 92 ans. Dernier fils de Cheikh Ahmadou Bamba Mback\u00e9 \u00e0 avoir occup\u00e9 le khalifat (17 ans), celui que l\u2019on surnommait \u00ab\u00a0Borom Jamono\u00a0\u00bb a vu le jour en 1915 \u00e0 Diourbel. Il a fait de l\u2019\u00e9ducation son occupation continue. En effet, ses daaras o\u00f9 les \u00e9tudiants travaillent dans les champs \u00e9parpill\u00e9s \u00e0 travers le pays datent de plus d\u2019un demi-si\u00e8cle. L\u2019apprentissage du travail chez les jeunes leur conf\u00e8re la conscience qui permet \u00e0 l\u2019homme de s\u2019accomplir, d\u2019\u00eatre utile \u00e0 lui-m\u00eame et \u00e0 la communaut\u00e9. Quant \u00e0 l\u2019\u00e9ducation, elle a pour but dans ces \u00ab\u00a0daaras\u00a0\u00bb de faire conna\u00eetre aux jeunes disciples le sens de la vie, les r\u00e8gles de comportement dans la soci\u00e9t\u00e9, les normes spirituelles et morales dont l\u2019observation assure \u00e0 chacun la sauvegarde de son humanit\u00e9. Serigne Saliou fondateur de plusieurs daraas destin\u00e9s \u00e0 la m\u00e9morisation du Saint Coran, l\u2019\u00e9ducation et l\u2019apprentissage de la vie, il mettra aussi l\u2019accent\u00a0sur les sciences religieuses car pour lui, la foi en Dieu est la principale dimension de l\u2019homme. Cette entreprise d\u2019\u00e9ducation, qui s\u2019adressait \u00e0 des milliers d\u2019\u00e9l\u00e8ves, \u00e9tait entour\u00e9e du plus grand soin de la part de Serigne Saliou qui y consacrait d\u2019\u00e9normes ressources, donnant ainsi le signe d\u2019un engagement personnel, profond. D\u00e9crit comme un \u00e9ducateur hors pair, un travailleur et un soufi affirm\u00e9, Serigne Saliou Mback\u00e9 avait une ma\u00eetrise des rouages de l\u2019\u00e9ducation religieuse. Serigne Saliou \u00e9tait \u00e9galement connu pour avoir \u00e9t\u00e9 un grand producteur agricole avec notamment Khelcom sur une surface de 45 000 hectares. Il reprit de nombreux travaux de r\u00e9novation aussi bien internes qu\u2019externes de la mosqu\u00e9e et la construction de l\u2019universit\u00e9 islamique qu\u2019avait entam\u00e9e son fr\u00e8re a\u00een\u00e9 Abdoul Ahad Mback\u00e9, l\u2019assainissement de la ville de Touba. En d\u00e9finitive, Serigne Saliou a fait du Mouridisme une voie soufie connue actuellement \u00e0 travers le monde entier. Il est inhum\u00e9 dans l\u2019enceinte de la grande mosqu\u00e9e de Touba. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T13:51:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T13:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"409\" \/>\n\t<meta property=\"og:image:height\" content=\"307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\\\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 !\",\"datePublished\":\"2022-12-28T13:51:15+00:00\",\"dateModified\":\"2022-12-28T13:52:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/\"},\"wordCount\":405,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/SERIGNE-SALIOU.jpg\",\"articleSection\":[\"ACTUALIT\u00c9S\",\"S\u00c9N\u00c9GAL\",\"SOCIETE\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/\",\"name\":\"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\\\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 ! - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/SERIGNE-SALIOU.jpg\",\"datePublished\":\"2022-12-28T13:51:15+00:00\",\"dateModified\":\"2022-12-28T13:52:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/SERIGNE-SALIOU.jpg\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/SERIGNE-SALIOU.jpg\",\"width\":409,\"height\":307},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/28\\\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\\\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\\\/\\\/www.public.sn\"],\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/admin7324\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 ! - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/","og_locale":"fr_FR","og_type":"article","og_title":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 ! - LE PUBLIC","og_description":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022. Voil\u00e0 15 ans d\u00e9j\u00e0 que disparaissait le cinqui\u00e8me khalife de Bamba. Serigne Saliou Mback\u00e9 a \u00e0 son compte un long khalifat\u00a0: 17 ans (1990-2007) \u00e0 la t\u00eate du Mouridisme, sans qu\u2019on puisse lui reprocher grand-chose.\u00a0 Vendredi 28 d\u00e9cembre 2007, Serigne Saliou Mback\u00e9 quitte ce bas monde \u00e0 l\u2019\u00e2ge de 92 ans. Dernier fils de Cheikh Ahmadou Bamba Mback\u00e9 \u00e0 avoir occup\u00e9 le khalifat (17 ans), celui que l\u2019on surnommait \u00ab\u00a0Borom Jamono\u00a0\u00bb a vu le jour en 1915 \u00e0 Diourbel. Il a fait de l\u2019\u00e9ducation son occupation continue. En effet, ses daaras o\u00f9 les \u00e9tudiants travaillent dans les champs \u00e9parpill\u00e9s \u00e0 travers le pays datent de plus d\u2019un demi-si\u00e8cle. L\u2019apprentissage du travail chez les jeunes leur conf\u00e8re la conscience qui permet \u00e0 l\u2019homme de s\u2019accomplir, d\u2019\u00eatre utile \u00e0 lui-m\u00eame et \u00e0 la communaut\u00e9. Quant \u00e0 l\u2019\u00e9ducation, elle a pour but dans ces \u00ab\u00a0daaras\u00a0\u00bb de faire conna\u00eetre aux jeunes disciples le sens de la vie, les r\u00e8gles de comportement dans la soci\u00e9t\u00e9, les normes spirituelles et morales dont l\u2019observation assure \u00e0 chacun la sauvegarde de son humanit\u00e9. Serigne Saliou fondateur de plusieurs daraas destin\u00e9s \u00e0 la m\u00e9morisation du Saint Coran, l\u2019\u00e9ducation et l\u2019apprentissage de la vie, il mettra aussi l\u2019accent\u00a0sur les sciences religieuses car pour lui, la foi en Dieu est la principale dimension de l\u2019homme. Cette entreprise d\u2019\u00e9ducation, qui s\u2019adressait \u00e0 des milliers d\u2019\u00e9l\u00e8ves, \u00e9tait entour\u00e9e du plus grand soin de la part de Serigne Saliou qui y consacrait d\u2019\u00e9normes ressources, donnant ainsi le signe d\u2019un engagement personnel, profond. D\u00e9crit comme un \u00e9ducateur hors pair, un travailleur et un soufi affirm\u00e9, Serigne Saliou Mback\u00e9 avait une ma\u00eetrise des rouages de l\u2019\u00e9ducation religieuse. Serigne Saliou \u00e9tait \u00e9galement connu pour avoir \u00e9t\u00e9 un grand producteur agricole avec notamment Khelcom sur une surface de 45 000 hectares. Il reprit de nombreux travaux de r\u00e9novation aussi bien internes qu\u2019externes de la mosqu\u00e9e et la construction de l\u2019universit\u00e9 islamique qu\u2019avait entam\u00e9e son fr\u00e8re a\u00een\u00e9 Abdoul Ahad Mback\u00e9, l\u2019assainissement de la ville de Touba. En d\u00e9finitive, Serigne Saliou a fait du Mouridisme une voie soufie connue actuellement \u00e0 travers le monde entier. Il est inhum\u00e9 dans l\u2019enceinte de la grande mosqu\u00e9e de Touba. &nbsp;","og_url":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/","og_site_name":"LE PUBLIC","article_published_time":"2022-12-28T13:51:15+00:00","article_modified_time":"2022-12-28T13:52:07+00:00","og_image":[{"width":409,"height":307,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 !","datePublished":"2022-12-28T13:51:15+00:00","dateModified":"2022-12-28T13:52:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/"},"wordCount":405,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg","articleSection":["ACTUALIT\u00c9S","S\u00c9N\u00c9GAL","SOCIETE","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/","url":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/","name":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 ! - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg","datePublished":"2022-12-28T13:51:15+00:00","dateModified":"2022-12-28T13:52:07+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg","width":409,"height":307},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/28\/28-decembre-2007-28-decembre-2022-15-ans-apres-sa-disparition-il-etait-une-foi-serigne-saliou-mbacke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"28 d\u00e9cembre 2007\u2013 28 d\u00e9cembre 2022\/15 ans apr\u00e8s sa disparition: Il \u00e9tait une foi Serigne Saliou Mback\u00e9 !"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/SERIGNE-SALIOU.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=13008"}],"version-history":[{"count":2,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13008\/revisions"}],"predecessor-version":[{"id":13011,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13008\/revisions\/13011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/13009"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=13008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=13008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=13008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}