{"id":13146,"date":"2022-12-31T20:37:18","date_gmt":"2022-12-31T20:37:18","guid":{"rendered":"https:\/\/www.public.sn\/?p=13146"},"modified":"2022-12-31T20:37:18","modified_gmt":"2022-12-31T20:37:18","slug":"nouvel-an-lintegralite-du-discours-de-macky-sall","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/","title":{"rendered":"Nouvel An : L&rsquo;int\u00e9gralit\u00e9 du discours de Macky Sall"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Mes chers compatriotes, <\/strong><\/p><div id=\"publi-2254329398\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p><strong>H\u00f4tes \u00e9trangers qui vivez parmi nous,\u00a0<\/strong><\/p>\n<p>Au seuil du nouvel an, je suis heureux de m\u2019adresser \u00e0 vous pour vous pr\u00e9senter mes v\u0153ux.<\/p>\n<p>Ce soir, alors que la communaut\u00e9 catholique est en deuil, avec le rappel \u00e0 Dieu de Sa Saintet\u00e9, le Pape \u00e9m\u00e9rite <strong>Benoit XVI<\/strong>, je voudrais d\u2019abord joindre mes pens\u00e9es aux v\u00f4tres, en souvenir des \u00eatres chers qui nous ont quitt\u00e9s. Je prie avec vous pour qu\u2019ils reposent en paix.<\/p>\n<p>A nos malades, j\u2019exprime ma compassion et mes souhaits de prompt r\u00e9tablissement.<\/p>\n<p>L\u2019ann\u00e9e 2022 s\u2019ach\u00e8ve comme elle a commenc\u00e9. L\u2019impact de la pand\u00e9mie et d\u2019une guerre majeure continue en effet de bouleverser toutes les pr\u00e9visions et de maintenir l\u2019\u00e9conomie dans sa pire r\u00e9cession depuis la seconde guerre mondiale.<\/p>\n<p>Malgr\u00e9 cette situation difficile, o\u00f9 nombre de pays sont en stagnation ou r\u00e9cession, notre \u00e9conomie reste r\u00e9siliente. Le classement de <strong><em>World Economics<\/em><\/strong>, qui fait autorit\u00e9 en mati\u00e8re de donn\u00e9es statistiques, reconnait en effet le S\u00e9n\u00e9gal comme pays \u00e0 la croissance la plus r\u00e9guli\u00e8re sur la d\u00e9cennie 2011-2021.<\/p>\n<p>Cette ann\u00e9e, notre d\u00e9ficit budg\u00e9taire s\u2019est r\u00e9tr\u00e9ci. Notre taux de croissance, \u00e9tabli \u00e0 <strong>4,8 %<\/strong>, devrait atteindre un niveau sans pr\u00e9c\u00e9dent de <strong>10%<\/strong> en 2023, avec le d\u00e9but d\u2019exploitation de nos ressources p\u00e9troli\u00e8res et gazi\u00e8res.<\/p>\n<p>Nos recettes int\u00e9rieures ont augment\u00e9 de <strong>23%<\/strong> au cours de l\u2019ann\u00e9e 2022, gr\u00e2ce \u00e0 la bonne performance de nos r\u00e9gies financi\u00e8res qui ont r\u00e9ussi un taux de recouvrement plus que satisfaisant de <strong>90%<\/strong> par rapport \u00e0 l\u2019objectif fix\u00e9.<\/p>\n<p>Ces efforts nous ont donn\u00e9 plus d\u2019autonomie budg\u00e9taire, en permettant de couvrir <strong>85%<\/strong> des d\u00e9penses publiques internes de l\u2019Etat.<\/p>\n<p>Dans le m\u00eame esprit de bonne gouvernance des affaires publiques, l\u2019exploitation du rapport de la Cour des comptes sur la gestion financi\u00e8re de la pand\u00e9mie de COVID-19 suivra son cours conform\u00e9ment aux dispositions l\u00e9gales et r\u00e9glementaires en la mati\u00e8re.<\/p>\n<p><strong>Mes chers compatriotes, <\/strong><\/p>\n<p>Dans un contexte mondial particuli\u00e8rement difficile, marqu\u00e9 par une hausse g\u00e9n\u00e9ralis\u00e9e des prix, j\u2019ai souhait\u00e9 faire de 2022 une ann\u00e9e sociale, d\u00e9di\u00e9e \u00e0 la protection du pouvoir d\u2019achat des m\u00e9nages.<\/p>\n<p>C\u2019est le sens des mesures portant sur :<\/p>\n<p>\u00d8 l\u2019augmentation substantielle des salaires pour un montant cumul\u00e9 de <strong>236 milliards<\/strong>\u00a0de FCFA ;<\/p>\n<p>\u00d8 la subvention des prix du carburant, du gaz et des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9 pour plus de <strong>750\u00a0milliards<\/strong> ;<\/p>\n<p>\u00d8 la renonciation, par l\u2019Etat, de <strong>157 milliards<\/strong> de recettes fiscales sur des produits import\u00e9s comme le riz, le bl\u00e9, le ma\u00efs, le sucre et\u00a0l\u2019huile, afin d\u2019\u00e9viter leur rench\u00e9rissement pour le consommateur\u00a0;<\/p>\n<p>\u00d8 enfin, le soutien direct \u00e0 <strong>543 000<\/strong> familles vuln\u00e9rables par transfert d\u2019argent pour plus de <strong>43 milliards<\/strong>.<\/p>\n<p>A cela s\u2019ajoutent les d\u00e9cisions issues des concertations nationales sur la lutte contre la vie ch\u00e8re, visant \u00e0 contenir la tendance inflationniste des prix, y compris le loyer.<\/p>\n<p>Je remercie l\u2019ensemble des acteurs \u00e9conomiques et autres forces vives de la nation qui ont contribu\u00e9 au succ\u00e8s de cet exercice de solidarit\u00e9 nationale.<\/p>\n<p>L\u2019effort de protection sociale sera renforc\u00e9 en 2023 avec la mobilisation de plus de <strong>450 milliards<\/strong> au titre des subventions des produits alimentaires et \u00e9nerg\u00e9tiques.<\/p>\n<p>Celles concernant le carburant et l\u2019\u00e9lectricit\u00e9 seront cependant ajust\u00e9es et mieux cibl\u00e9es en faveur des couches sociales les plus n\u00e9cessiteuses.<\/p>\n<p>En outre, les bourses de s\u00e9curit\u00e9 familiale seront port\u00e9es de <strong>25\u00a0000 fcfa <\/strong>\u00e0 <strong>35\u00a0000<\/strong> <strong>fcfa <\/strong>par trimestre et \u00e9largies \u00e0 de nouveaux b\u00e9n\u00e9ficiaires sur la base de crit\u00e8res de vuln\u00e9rabilit\u00e9.<\/p>\n<p>C\u2019est dire, mes chers compatriotes, que le Gouvernement reste dans <strong>le temps de l\u2019action<\/strong>, <strong>de la sensibilit\u00e9 sociale par la<\/strong> <strong>veille, l\u2019\u00e9coute et la proximit\u00e9\u00a0; mais \u00e9galement de l\u2019offensive \u00e9conomique.<\/strong><\/p>\n<p>En somme, le S\u00e9n\u00e9gal est aujourd\u2019hui pass\u00e9 d\u2019un <strong>\u00e9tat d\u2019indigence \u00e0 un \u00e9tat d\u2019\u00e9mergence.<\/strong><\/p>\n<p>Le combat pour la souverainet\u00e9 alimentaire reste un objectif de premier plan.<\/p>\n<p>Ainsi, en trois, ans, le budget de la campagne agricole a doubl\u00e9, passant de <strong>40 milliards<\/strong> de FCFA en 2019 \u00e0 plus de <strong>80 milliards<\/strong> en 2022, pour soutenir les producteurs en semences, engrais et mat\u00e9riels agricoles.<\/p>\n<p>Cette ann\u00e9e encore, gr\u00e2ce \u00e0 l\u2019intensification de nos efforts et une pluviom\u00e9trie abondante, les r\u00e9coltes sont satisfaisantes, avec plus de<strong> 3,6 millions <\/strong>de tonnes pour les c\u00e9r\u00e9ales et <strong>1,5<\/strong> <strong>million<\/strong> respectivement pour l\u2019arachide et les produits horticoles.<\/p>\n<p>Nous ferons encore mieux avec les nouveaux am\u00e9nagements hydro-agricoles en cours, une meilleure ma\u00eetrise de l\u2019eau et le d\u00e9veloppement progressif des <strong>Agropoles,<\/strong> des <strong>Domaines agricoles communautaires<\/strong> et des fermes<strong><em> Naatangu\u00e9 et Waar-Wi<\/em><\/strong>.<\/p>\n<p>Dans le cadre de la modernisation du secteur agricole, je me r\u00e9jouis d\u2019annoncer l\u2019acquisition prochaine de plusieurs mat\u00e9riels et \u00e9quipements, dont des tracteurs, moissonneuses-batteuses, kits d\u2019irrigation, magasins de stockage et chambres froides.<\/p>\n<p><strong>Mes chers compatriotes, <\/strong><\/p>\n<p>En d\u00e9pit de la crise, nous poursuivons r\u00e9solument nos chantiers d\u2019infrastructures, parce qu\u2019il ne peut y avoir d\u2019\u00e9mergence sans infrastructures de base.<\/p>\n<p>Cette ann\u00e9e, nous avons achev\u00e9 des projets embl\u00e9matiques, comme la <strong>premi\u00e8re phase du TER<\/strong>, le <strong>stade Abdoulaye Wade,<\/strong> le pont <strong>Nelson Mandela Foundiougne<\/strong> et celui de <strong>Marsassoum<\/strong>, l\u2019autopont de <strong>Keur Massar<\/strong>, les axes routiers <strong>Tambacounda-Goudiry-Kidira, et Louga-Dahra<\/strong>, entre autres.<\/p>\n<p>Au total, <strong>60 chantiers <\/strong>d\u2019infrastructures sont actuellement en cours d\u2019ex\u00e9cution, mettant \u00e0 contribution le secteur priv\u00e9 national et une main d\u2019\u0153uvre intensive.<\/p>\n<p>Il s\u2019agit, entre autres\u00a0:<\/p>\n<p>\u00d8 de la ligne du BRT entre Gu\u00e9diawaye et Dakar\u00a0;<\/p>\n<p>\u00d8 de la 2<sup>e<\/sup> phase du TER, entre Diamniadio et AIBD\u00a0;<\/p>\n<p>\u00d8 de la route du <strong>Daand\u00e9 maayo\u00a0<\/strong>;<\/p>\n<p>\u00d8 de l\u2019axe <strong>Kidira-Bakel\u00a0<\/strong>;<\/p>\n<p>\u00d8 de l\u2019autoroute du Nord <strong>Dakar-Tivaouane-Saint-Louis,<\/strong> dont les travaux d\u00e9marrent en 2023 en coh\u00e9rence avec le regain de trafic li\u00e9 \u00e0 l\u2019exploitation de nos hydrocarbures\u00a0;<\/p>\n<p>\u00d8 du <strong>Programme de Connectivit\u00e9 des Zones de Production Agricole, <\/strong>dans les r\u00e9gions de Kaffrine, Kaolack et Thi\u00e8s, dont le montage financier est boucl\u00e9\u00a0;<\/p>\n<p>\u00d8 et du <strong>Programme Sp\u00e9cial de D\u00e9senclavement,\u00a0<\/strong>un vaste chantier quinquennal qui a d\u00e9j\u00e0 d\u00e9marr\u00e9 pour r\u00e9aliser <strong>2850 Km <\/strong>de routes, ainsi que des ouvrages d\u2019art en milieu rural et urbain.<\/p>\n<p>A terme, ce Programme mobilisera <strong>60 <\/strong>entreprises nationales et g\u00e9n\u00e9rera <strong>50.000 <\/strong>emplois.<\/p>\n<p>S\u2019y ajoutent les projets sp\u00e9cifiques d\u2019\u00e9quit\u00e9 territoriale ex\u00e9cut\u00e9s par le <strong>PUDC<\/strong>, le <strong>PUMA<\/strong> et le <strong>PROMOVILLES<\/strong>, pour un maillage complet du pays en routes bitum\u00e9es, pistes carrossables, infrastructures hydrauliques et \u00e9lectriques.<\/p>\n<p>Ce sont tous ces efforts qui ont hiss\u00e9 notre pays \u00e0 la 8<sup>e<\/sup> place du classement <strong><em>Global Economy<\/em><\/strong> des meilleurs r\u00e9seaux routiers et autoroutiers d\u2019Afrique, sur <strong>38<\/strong> pays \u00e9valu\u00e9s.<\/p>\n<p>Nous avons la m\u00eame ambition de performance pour les secteurs strat\u00e9giques des mines et de l\u2019\u00e9nergie conform\u00e9ment \u00e0 nos engagements au titre de l\u2019Initiative pour la Transparence des Industries extractives (ITIE).<\/p>\n<p>Le Conseil d\u2019administration de l\u2019ITIE a ainsi reconnu en octobre dernier que le S\u00e9n\u00e9gal a \u00ab atteint un score tr\u00e8s \u00e9lev\u00e9 dans la mise en \u0153uvre de l\u2019ITIE suite \u00e0 sa seconde Validation \u00bb, avec la mise en ligne transparente des contrats miniers, p\u00e9troliers et gaziers, tous accessibles au grand public<\/p>\n<p>En cette soir\u00e9e du r\u00e9veillon, le chef de l&rsquo;Etat a prononc\u00e9 son dixi\u00e8me discours de la Saint-Sylvestre, le premier de son second mandat..<\/p>\n<p>Je suis heureux d\u2019annoncer que de bonnes perspectives sont devant nous pour r\u00e9aliser au plus vite l\u2019acc\u00e8s universel \u00e0 l\u2019\u00e9lectricit\u00e9.<\/p>\n<p>Les travaux de notre projet p\u00e9trolier <strong>Sangomar<\/strong>, et du projet gazier <strong>GTA<\/strong>, que nous partageons avec notre voisin mauritanien, sont ex\u00e9cut\u00e9s respectivement \u00e0 <strong>71%<\/strong> et <strong>85%,<\/strong> avec la participation d\u2019entreprises et de main d\u2019\u0153uvre s\u00e9n\u00e9galaises\u00a0; donnant plein effet \u00e0 notre politique de contenu local.<\/p>\n<p>Dans la perspective de nos premi\u00e8res productions en 2023, notre pays a adh\u00e9r\u00e9 en novembre dernier \u00e0 l\u2019Organisation des Pays africains Producteurs de P\u00e9trole afin de d\u00e9fendre ses int\u00e9r\u00eats dans le cadre de la solidarit\u00e9 africaine.<\/p>\n<p>D\u2019autre part, la SENELEC a renforc\u00e9 ses capacit\u00e9s avec la mise en service de la centrale \u00e9lectrique de <strong>Malicounda<\/strong> et notre quote-part de <strong>33%<\/strong> dans la centrale hydro\u00e9lectrique de <strong>Gouina<\/strong>.<\/p>\n<p>A cela s\u2019ajoutent le nouveau Programme d\u2019installation de <strong>115\u00a0000<\/strong> lampadaires solaires, prioritairement dans les communes non b\u00e9n\u00e9ficiaires de la premi\u00e8re phase, et l\u2019\u00e9lectrification de <strong>2000<\/strong> villages au titre de la phase 2 du PUDC.<\/p>\n<p>Tout comme l\u2019\u00e9lectricit\u00e9, l\u2019eau et l\u2019assainissement restent au c\u0153ur de mes priorit\u00e9s.<\/p>\n<p>Comme promis, nous avons satisfait cette ann\u00e9e une vieille dol\u00e9ance avec la r\u00e9alisation du Projet d\u2019alimentation en eau potable des \u00eeles de la Basse Casamance.<\/p>\n<p>De m\u00eame, les travaux de la premi\u00e8re phase de l\u2019usine de dessalement d\u2019eau de mer des Mamelles ont d\u00e9marr\u00e9.<\/p>\n<p>Ce chantier sera suivi par celui du dessalement d\u2019eau de mer sur la Grande C\u00f4te, pour <strong>300.000<\/strong> m<sup>3<\/sup> par jour, extensibles \u00e0 <strong>400.000<\/strong> m<sup>3<\/sup>, afin de couvrir les besoins de Dakar, Thi\u00e8s et Mbour.<\/p>\n<p>Nous lancerons en 2023 le projet d\u2019exploitation des eaux de surface du bassin de Nanija Bolong, dans le D\u00e9partement de Koungheul\u00a0; soit 46 millions de m<sup>3<\/sup> par an, pour mettre en valeur 12.000 hectares et arr\u00eater l\u2019avanc\u00e9e des eaux sal\u00e9es.<\/p>\n<p>Un financement de <strong>156 milliards<\/strong> FCFA sera \u00e9galement mobilis\u00e9 pour la premi\u00e8re phase de l\u2019ambitieux Projet de Renforcement de la R\u00e9silience des \u00c9cosyst\u00e8mes du Ferlo (le PREFERLO), qui consiste \u00e0 transf\u00e9rer <strong>680 millions<\/strong> m<sup><strong>3<\/strong><\/sup> par an du lac de Guiers vers la zone du Ferlo, sur un lin\u00e9aire de <strong>214 km<\/strong>, entre Keur Momar Sarr et Ran\u00e9rou.<\/p>\n<p>Le PREFERLO contribuera de fa\u00e7on substantielle \u00e0 la souverainet\u00e9 alimentaire de notre pays en mettant en valeur tout le potentiel d\u2019agriculture et d\u2019\u00e9levage du terroir.<\/p>\n<p>J\u2019ai aussi demand\u00e9 au gouvernement de renforcer la politique des branchements sociaux pour soutenir les couches vuln\u00e9rables en milieu urbain et rural.<\/p>\n<p>Pour un <strong><em>S\u00e9n\u00e9gal de tous, un S\u00e9n\u00e9gal pour tous<\/em>, <\/strong>et parce que l\u2019eau est un minimum vital, je tiens particuli\u00e8rement \u00e0 ce que chaque famille, quelle que soit la modestie de ses moyens, puisse acc\u00e9der \u00e0 l\u2019eau potable.<\/p>\n<p>En mati\u00e8re d\u2019assainissement, d\u2019importants chantiers sont en cours avec\u00a0:<\/p>\n<p>\u00d8 la finalisation des travaux de renforcement des capacit\u00e9s de la station de <strong>Camb\u00e9r\u00e8ne<\/strong><em>\u00a0; <\/em><\/p>\n<p>\u00d8 le lancement du projet de renouvellement du collecteur <strong>Hann-Fann,<\/strong> pour r\u00e9gler une vieille pr\u00e9occupation des communes de Hann, Fann-Point E-Amiti\u00e9, Grand Dakar, Biscuterie, Mermoz-Sacr\u00e9-C\u0153ur, Sicap Libert\u00e9, Dieupeul-Derkl\u00e9, Grand Yoff et des HLM\u00a0;<\/p>\n<p>\u00d8 enfin, la poursuite du Programme d\u2019assainissement des villes de Dakar, Kaolack, Louga, Matam, Pikine, Rufisque, Tambacounda, Saint Louis, Tivaouane et Touba.<\/p>\n<p>Dans la qu\u00eate d\u2019\u00e9mergence, notre syst\u00e8me \u00e9ducatif reste le c\u0153ur battant qui irrigue le corps social, et donne vie et espoir \u00e0 la nation.<\/p>\n<p>Eduquer et former nos enfants, c\u2019est entretenir la lumi\u00e8re du savoir qui \u00e9claire les esprits et illumine notre marche vers le S\u00e9n\u00e9gal de nos r\u00eaves.<\/p>\n<p>C\u2019est pourquoi l\u2019Etat continue d\u2019investir plus de 25% du budget national dans l\u2019\u00e9ducation et la formation.<\/p>\n<p>Nos acquis r\u00e9cents le prouvent \u00e0 suffisance avec\u00a0:<\/p>\n<p>\u00d8 l\u2019inauguration de l\u2019Universit\u00e9 Amadou Mahtar Mbow\u00a0;<\/p>\n<p>\u00d8 le d\u00e9marrage des classes pr\u00e9paratoires aux grandes \u00e9coles\u00a0;<\/p>\n<p>\u00d8 la finalisation des travaux de construction de l\u2019Universit\u00e9 El hadji Ibrahima Niasse ;<\/p>\n<p>\u00d8 le renforcement des capacit\u00e9s de l\u2019Universit\u00e9 Virtuelle du S\u00e9n\u00e9gal, avec la construction en cours de <strong>46<\/strong> Espaces Num\u00e9riques Ouverts\u00a0;<\/p>\n<p>\u00d8 le d\u00e9marrage des enseignements du campus franco-s\u00e9n\u00e9galais\u00a0;<\/p>\n<p>\u00d8 la cr\u00e9ation des Universit\u00e9s Souleymane Niang de Matam, et S\u00e9n\u00e9gal oriental de Tambacounda, dont les Coordonnateurs de projets sont d\u00e9j\u00e0 nomm\u00e9s\u00a0;<\/p>\n<p>\u00d8 la mobilisation de<strong> 52 <\/strong>milliards pour la modernisation des \u00e9quipements scientifiques de nos universit\u00e9s\u00a0;<\/p>\n<p>\u00d8\u00a0l\u2019am\u00e9lioration de la pension de retraite du Personnel enseignant et de recherche\u00a0;<\/p>\n<p>\u00d8 et l\u2019augmentation des avantages accord\u00e9s aux personnels administratifs, technique et de service.<\/p>\n<p>Malgr\u00e9 nos contraintes et nos limites, nous devons \u00eatre fiers de notre syst\u00e8me universitaire, au regard des performances de l\u2019Universit\u00e9 Cheikh Anta DIOP de Dakar, r\u00e9cemment class\u00e9e 1<sup>ere<\/sup> universit\u00e9 francophone d\u2019Afrique, et des excellents r\u00e9sultats de nos candidats au dernier Concours d\u2019Agr\u00e9gation du CAMES en Sciences de la Sant\u00e9.<\/p>\n<p>Et \u00e0 travers le monde, des compatriotes et ressortissants d\u2019autres nationalit\u00e9s, form\u00e9s \u00e0 l\u2019universit\u00e9 s\u00e9n\u00e9galaise excellent dans tous les domaines de l\u2019activit\u00e9 humaine, y compris les plus pointus.<\/p>\n<p>Tout cela montre que nous devons continuer \u00e0 investir\u00a0dans l\u2019\u00e9cole, parce que c\u2019est opportun et productif.<\/p>\n<p>C\u2019est pourquoi je tiens \u00e0 l\u2019ex\u00e9cution diligente\u00a0:<\/p>\n<p>\u00d8 du projet de construction, \u00e0 compter de 2023, de <strong>22 <\/strong>lyc\u00e9es et coll\u00e8ges dans les r\u00e9gions de Dakar, Thi\u00e8s, Kaolack, Kaffrine et S\u00e9dhiou\u00a0;<\/p>\n<p>\u00d8 et du Programme d\u2019urgence de r\u00e9habilitation de plusieurs lyc\u00e9es historiques, notamment Blaise Diagne, Seydina Limamou Laye, Seydou Nourou Tall et John Fitzgerald Kennedy de Dakar\u00a0; El Hadji Malick Sy de Thi\u00e8s\u00a0; El Hadj Oumar Foutyou Tall et Charles de Gaulle de Saint Louis\u00a0; Valdiodio Ndiaye de Kaolack et Djignabo de Ziguinchor.<\/p>\n<p>J\u2019accorde le m\u00eame ordre de priorit\u00e9 \u00e0 la mise en \u0153uvre des conclusions de la <strong><em>Rencontre nationale avec la communaut\u00e9 des daara<\/em> <\/strong>du 28 novembre dernier.<\/p>\n<p>Depuis des si\u00e8cles, les daara font partie int\u00e9grante de notre patrimoine spirituel, \u00e9ducatif et socio culturel. Ils m\u00e9ritent, \u00e0 ce titre, une reconnaissance et un appui institutionnel plus cons\u00e9quents.<\/p>\n<p>A cet effet, en attendant la mobilisation prochaine d\u2019autres moyens, j\u2019ai d\u00e9cid\u00e9 d\u2019allouer au syst\u00e8me \u00e9ducatif des <em>daara<\/em><strong> 20%<\/strong> des fonds de dotation, afin de p\u00e9renniser leur prise en charge concert\u00e9e, alliant tradition et modernit\u00e9.<\/p>\n<p>Dans la m\u00eame dynamique d\u2019inclusion sociale et d\u2019\u00e9quit\u00e9 territoriale, la DER\/FJ, qui compte \u00e0 ce jour <strong>205\u00a0000<\/strong> b\u00e9n\u00e9ficiaires, continue son d\u00e9ploiement sur l\u2019\u00e9tendue du pays, pour financer, conseiller et accompagner des femmes et jeunes porteurs de projets.<\/p>\n<p>Je tiens particuli\u00e8rement \u00e0 ce que la DER\/FJ veille \u00e0 assouplir davantage ses proc\u00e9dures et m\u00e9thodes d\u2019intervention pour mieux s\u2019adapter aux besoins et r\u00e9alit\u00e9s de ses cibles.<\/p>\n<p>De m\u00eame, l\u2019Etat soutiendra davantage les cultures urbaines avec les moyens accrus du nouveau Fonds de d\u00e9veloppement des cultures urbaines et des industries cr\u00e9atives.<\/p>\n<p>Le Gouvernement reste \u00e9galement engag\u00e9 sur le front de la sant\u00e9 pour tous.<\/p>\n<p>Ainsi, apr\u00e8s les inaugurations des h\u00f4pitaux de <strong>S\u00e9dhiou, Kaffrine K\u00e9dougou, Touba et Agnam<\/strong>, d\u2019autres chantiers d\u2019\u00e9tablissements publics de sant\u00e9 sont en cours \u00e0 <strong>Tivaouane, Ourossogui et Saint-Louis.<\/strong><\/p>\n<p>Les travaux de la polyclinique de l\u2019h\u00f4pital Principal se poursuivent, de m\u00eame que la construction de l\u2019h\u00f4pital Aristide Le Dantec et celle du Centre national d\u2019oncologie de Diamniadio pour le traitement du cancer.<\/p>\n<p>En m\u00eame temps que nous investissons dans les structures de sant\u00e9 et leurs ressources humaines, il nous faut imp\u00e9rativement r\u00e9former et am\u00e9liorer la gouvernance du secteur, afin de la rendre plus efficace et plus transparente.<\/p>\n<p>C\u2019est pourquoi j\u2019ai demand\u00e9 une digitalisation int\u00e9grale du syst\u00e8me, la mise en place de contrats de performance pour les h\u00f4pitaux, et la r\u00e9vision de la Convention hospitalo-universitaire.<\/p>\n<p><strong>Mes chers compatriotes, <\/strong><\/p>\n<p>Au titre de son mandat \u00e0 la t\u00eate de l\u2019Union Africaine, et dans un contexte international agit\u00e9 et incertain, notre pays, fid\u00e8le \u00e0 ses id\u00e9aux panafricanistes, a port\u00e9 avec constance le plaidoyer pour la paix et l\u2019int\u00e9gration africaine, et la d\u00e9fense des int\u00e9r\u00eats de notre continent dans la gouvernance politique, \u00e9conomique et financi\u00e8re mondiale.<\/p>\n<p>Notre diplomatie a pu mobiliser un consensus g\u00e9n\u00e9ral qui balise d\u00e9sormais la voie pour l\u2019adh\u00e9sion historique de l\u2019Union Africaine comme membre de plein droit du G20.<\/p>\n<p>Je redis notre gratitude et nos sinc\u00e8res remerciements \u00e0 tous nos partenaires qui ont soutenu la candidature de l\u2019Afrique, dans un esprit d\u2019\u00e9quit\u00e9 et de solidarit\u00e9.<\/p>\n<p>Ce succ\u00e8s parmi d\u2019autres, ajout\u00e9 au premier sacre de nos Lions \u00e0 la Coupe d\u2019Afrique des Nations et \u00e0 leur 3<sup>e<\/sup> participation \u00e0 la Coupe du monde de football, confirme le standing que notre pays doit <strong>tenir<\/strong> et <strong>entretenir <\/strong>dans le concert des nations.<\/p>\n<p>Ce rang, qui nous vaut le respect et la confiance de l\u2019Afrique et du monde, nous le devons surtout \u00e0 notre h\u00e9ritage commun de nation libre, unie dans sa diversit\u00e9, paisible et stable dans un monde constamment percut\u00e9 par la violence et l\u2019antagonisme, jusqu\u2019\u00e0 nos fronti\u00e8res.<\/p>\n<p>Chacun de nous est le l\u00e9gataire de cet h\u00e9ritage.<\/p>\n<p>En cons\u00e9quence, nous avons la responsabilit\u00e9 individuelle et collective de surmonter nos diff\u00e9rences afin de cultiver notre <em>vivre ensemble<\/em> et le pr\u00e9server des p\u00e9rils qui font le malheur des peuples.<\/p>\n<p><strong>Nul ne doit s\u2019imaginer plus grand ou plus fort que cette nation qui nous abrite tous.<\/strong> <strong>Nous sommes parce que le S\u00e9n\u00e9gal est.\u00a0<\/strong><\/p>\n<p>Si nous sommes l\u00e0 aujourd\u2019hui, rassembl\u00e9s en tant que nation, c\u2019est bien parce que nos anciens nous ont couv\u00e9s et port\u00e9s sur leurs \u00e9paules.<\/p>\n<p>Notre honneur, c\u2019est d\u2019en faire autant pour nos enfants, en consolidant chaque jour le pacte de biens\u00e9ance, de solidarit\u00e9 et de fraternit\u00e9 humaine qui lie cette nation, g\u00e9n\u00e9ration apr\u00e8s g\u00e9n\u00e9ration.<\/p>\n<p>Cette t\u00e2che qui nous incombe tous, moi au premier chef, je continuerai d\u2019y veiller de toutes mes forces, pour un S\u00e9n\u00e9gal toujours uni, paisible, stable et prosp\u00e8re.<\/p>\n<p>A toutes et \u00e0 tous, mes chers compatriotes, j\u2019exprime mes sentiments affectueux, avec mes v\u0153ux les meilleurs\u00a0;\u00a0v\u0153ux de paix, de bonne sant\u00e9, de bien-\u00eatre et de r\u00e9ussite.<\/p>\n<p><strong>Bonsoir et d\u00e9w\u00e9net<\/strong><\/p>\n<div id=\"publi-3699899460\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Mes chers compatriotes, H\u00f4tes \u00e9trangers qui vivez parmi nous,\u00a0 Au seuil du nouvel an, je suis heureux de m\u2019adresser \u00e0 vous pour vous pr\u00e9senter mes v\u0153ux. Ce soir, alors que la communaut\u00e9 catholique est en deuil, avec le rappel \u00e0 Dieu de Sa Saintet\u00e9, le Pape \u00e9m\u00e9rite Benoit XVI, je voudrais d\u2019abord joindre mes pens\u00e9es aux v\u00f4tres, en souvenir des \u00eatres chers qui nous ont quitt\u00e9s. Je prie avec vous pour qu\u2019ils reposent en paix. A nos malades, j\u2019exprime ma compassion et mes souhaits de prompt r\u00e9tablissement. L\u2019ann\u00e9e 2022 s\u2019ach\u00e8ve comme elle a commenc\u00e9. L\u2019impact de la pand\u00e9mie et d\u2019une guerre majeure continue en effet de bouleverser toutes les pr\u00e9visions et de maintenir l\u2019\u00e9conomie dans sa pire r\u00e9cession depuis la seconde guerre mondiale. Malgr\u00e9 cette situation difficile, o\u00f9 nombre de pays sont en stagnation ou r\u00e9cession, notre \u00e9conomie reste r\u00e9siliente. Le classement de World Economics, qui fait autorit\u00e9 en mati\u00e8re de donn\u00e9es statistiques, reconnait en effet le S\u00e9n\u00e9gal comme pays \u00e0 la croissance la plus r\u00e9guli\u00e8re sur la d\u00e9cennie 2011-2021. Cette ann\u00e9e, notre d\u00e9ficit budg\u00e9taire s\u2019est r\u00e9tr\u00e9ci. Notre taux de croissance, \u00e9tabli \u00e0 4,8 %, devrait atteindre un niveau sans pr\u00e9c\u00e9dent de 10% en 2023, avec le d\u00e9but d\u2019exploitation de nos ressources p\u00e9troli\u00e8res et gazi\u00e8res. Nos recettes int\u00e9rieures ont augment\u00e9 de 23% au cours de l\u2019ann\u00e9e 2022, gr\u00e2ce \u00e0 la bonne performance de nos r\u00e9gies financi\u00e8res qui ont r\u00e9ussi un taux de recouvrement plus que satisfaisant de 90% par rapport \u00e0 l\u2019objectif fix\u00e9. Ces efforts nous ont donn\u00e9 plus d\u2019autonomie budg\u00e9taire, en permettant de couvrir 85% des d\u00e9penses publiques internes de l\u2019Etat. Dans le m\u00eame esprit de bonne gouvernance des affaires publiques, l\u2019exploitation du rapport de la Cour des comptes sur la gestion financi\u00e8re de la pand\u00e9mie de COVID-19 suivra son cours conform\u00e9ment aux dispositions l\u00e9gales et r\u00e9glementaires en la mati\u00e8re. Mes chers compatriotes, Dans un contexte mondial particuli\u00e8rement difficile, marqu\u00e9 par une hausse g\u00e9n\u00e9ralis\u00e9e des prix, j\u2019ai souhait\u00e9 faire de 2022 une ann\u00e9e sociale, d\u00e9di\u00e9e \u00e0 la protection du pouvoir d\u2019achat des m\u00e9nages. C\u2019est le sens des mesures portant sur : \u00d8 l\u2019augmentation substantielle des salaires pour un montant cumul\u00e9 de 236 milliards\u00a0de FCFA ; \u00d8 la subvention des prix du carburant, du gaz et des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9 pour plus de 750\u00a0milliards ; \u00d8 la renonciation, par l\u2019Etat, de 157 milliards de recettes fiscales sur des produits import\u00e9s comme le riz, le bl\u00e9, le ma\u00efs, le sucre et\u00a0l\u2019huile, afin d\u2019\u00e9viter leur rench\u00e9rissement pour le consommateur\u00a0; \u00d8 enfin, le soutien direct \u00e0 543 000 familles vuln\u00e9rables par transfert d\u2019argent pour plus de 43 milliards. A cela s\u2019ajoutent les d\u00e9cisions issues des concertations nationales sur la lutte contre la vie ch\u00e8re, visant \u00e0 contenir la tendance inflationniste des prix, y compris le loyer. Je remercie l\u2019ensemble des acteurs \u00e9conomiques et autres forces vives de la nation qui ont contribu\u00e9 au succ\u00e8s de cet exercice de solidarit\u00e9 nationale. L\u2019effort de protection sociale sera renforc\u00e9 en 2023 avec la mobilisation de plus de 450 milliards au titre des subventions des produits alimentaires et \u00e9nerg\u00e9tiques. Celles concernant le carburant et l\u2019\u00e9lectricit\u00e9 seront cependant ajust\u00e9es et mieux cibl\u00e9es en faveur des couches sociales les plus n\u00e9cessiteuses. En outre, les bourses de s\u00e9curit\u00e9 familiale seront port\u00e9es de 25\u00a0000 fcfa \u00e0 35\u00a0000 fcfa par trimestre et \u00e9largies \u00e0 de nouveaux b\u00e9n\u00e9ficiaires sur la base de crit\u00e8res de vuln\u00e9rabilit\u00e9. C\u2019est dire, mes chers compatriotes, que le Gouvernement reste dans le temps de l\u2019action, de la sensibilit\u00e9 sociale par la veille, l\u2019\u00e9coute et la proximit\u00e9\u00a0; mais \u00e9galement de l\u2019offensive \u00e9conomique. En somme, le S\u00e9n\u00e9gal est aujourd\u2019hui pass\u00e9 d\u2019un \u00e9tat d\u2019indigence \u00e0 un \u00e9tat d\u2019\u00e9mergence. Le combat pour la souverainet\u00e9 alimentaire reste un objectif de premier plan. Ainsi, en trois, ans, le budget de la campagne agricole a doubl\u00e9, passant de 40 milliards de FCFA en 2019 \u00e0 plus de 80 milliards en 2022, pour soutenir les producteurs en semences, engrais et mat\u00e9riels agricoles. Cette ann\u00e9e encore, gr\u00e2ce \u00e0 l\u2019intensification de nos efforts et une pluviom\u00e9trie abondante, les r\u00e9coltes sont satisfaisantes, avec plus de 3,6 millions de tonnes pour les c\u00e9r\u00e9ales et 1,5 million respectivement pour l\u2019arachide et les produits horticoles. Nous ferons encore mieux avec les nouveaux am\u00e9nagements hydro-agricoles en cours, une meilleure ma\u00eetrise de l\u2019eau et le d\u00e9veloppement progressif des Agropoles, des Domaines agricoles communautaires et des fermes Naatangu\u00e9 et Waar-Wi. Dans le cadre de la modernisation du secteur agricole, je me r\u00e9jouis d\u2019annoncer l\u2019acquisition prochaine de plusieurs mat\u00e9riels et \u00e9quipements, dont des tracteurs, moissonneuses-batteuses, kits d\u2019irrigation, magasins de stockage et chambres froides. Mes chers compatriotes, En d\u00e9pit de la crise, nous poursuivons r\u00e9solument nos chantiers d\u2019infrastructures, parce qu\u2019il ne peut y avoir d\u2019\u00e9mergence sans infrastructures de base. Cette ann\u00e9e, nous avons achev\u00e9 des projets embl\u00e9matiques, comme la premi\u00e8re phase du TER, le stade Abdoulaye Wade, le pont Nelson Mandela Foundiougne et celui de Marsassoum, l\u2019autopont de Keur Massar, les axes routiers Tambacounda-Goudiry-Kidira, et Louga-Dahra, entre autres. Au total, 60 chantiers d\u2019infrastructures sont actuellement en cours d\u2019ex\u00e9cution, mettant \u00e0 contribution le secteur priv\u00e9 national et une main d\u2019\u0153uvre intensive. Il s\u2019agit, entre autres\u00a0: \u00d8 de la ligne du BRT entre Gu\u00e9diawaye et Dakar\u00a0; \u00d8 de la 2e phase du TER, entre Diamniadio et AIBD\u00a0; \u00d8 de la route du Daand\u00e9 maayo\u00a0; \u00d8 de l\u2019axe Kidira-Bakel\u00a0; \u00d8 de l\u2019autoroute du Nord Dakar-Tivaouane-Saint-Louis, dont les travaux d\u00e9marrent en 2023 en coh\u00e9rence avec le regain de trafic li\u00e9 \u00e0 l\u2019exploitation de nos hydrocarbures\u00a0; \u00d8 du Programme de Connectivit\u00e9 des Zones de Production Agricole, dans les r\u00e9gions de Kaffrine, Kaolack et Thi\u00e8s, dont le montage financier est boucl\u00e9\u00a0; \u00d8 et du Programme Sp\u00e9cial de D\u00e9senclavement,\u00a0un vaste chantier quinquennal qui a d\u00e9j\u00e0 d\u00e9marr\u00e9 pour r\u00e9aliser 2850 Km de routes, ainsi que des ouvrages d\u2019art en milieu rural et urbain. A terme, ce Programme mobilisera 60 entreprises nationales et g\u00e9n\u00e9rera 50.000 emplois. S\u2019y ajoutent les projets sp\u00e9cifiques d\u2019\u00e9quit\u00e9 territoriale ex\u00e9cut\u00e9s par le PUDC, le PUMA et le PROMOVILLES, pour un maillage complet du pays en routes bitum\u00e9es, pistes carrossables, infrastructures hydrauliques et \u00e9lectriques. Ce sont tous ces efforts qui ont<\/p>\n","protected":false},"author":1,"featured_media":13147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,3,1,372],"tags":[],"class_list":["post-13146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-politique","category-non-classe","category-vedette","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvel An : L&#039;int\u00e9gralit\u00e9 du discours de Macky Sall - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvel An : L&#039;int\u00e9gralit\u00e9 du discours de Macky Sall - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Mes chers compatriotes, H\u00f4tes \u00e9trangers qui vivez parmi nous,\u00a0 Au seuil du nouvel an, je suis heureux de m\u2019adresser \u00e0 vous pour vous pr\u00e9senter mes v\u0153ux. Ce soir, alors que la communaut\u00e9 catholique est en deuil, avec le rappel \u00e0 Dieu de Sa Saintet\u00e9, le Pape \u00e9m\u00e9rite Benoit XVI, je voudrais d\u2019abord joindre mes pens\u00e9es aux v\u00f4tres, en souvenir des \u00eatres chers qui nous ont quitt\u00e9s. Je prie avec vous pour qu\u2019ils reposent en paix. A nos malades, j\u2019exprime ma compassion et mes souhaits de prompt r\u00e9tablissement. L\u2019ann\u00e9e 2022 s\u2019ach\u00e8ve comme elle a commenc\u00e9. L\u2019impact de la pand\u00e9mie et d\u2019une guerre majeure continue en effet de bouleverser toutes les pr\u00e9visions et de maintenir l\u2019\u00e9conomie dans sa pire r\u00e9cession depuis la seconde guerre mondiale. Malgr\u00e9 cette situation difficile, o\u00f9 nombre de pays sont en stagnation ou r\u00e9cession, notre \u00e9conomie reste r\u00e9siliente. Le classement de World Economics, qui fait autorit\u00e9 en mati\u00e8re de donn\u00e9es statistiques, reconnait en effet le S\u00e9n\u00e9gal comme pays \u00e0 la croissance la plus r\u00e9guli\u00e8re sur la d\u00e9cennie 2011-2021. Cette ann\u00e9e, notre d\u00e9ficit budg\u00e9taire s\u2019est r\u00e9tr\u00e9ci. Notre taux de croissance, \u00e9tabli \u00e0 4,8 %, devrait atteindre un niveau sans pr\u00e9c\u00e9dent de 10% en 2023, avec le d\u00e9but d\u2019exploitation de nos ressources p\u00e9troli\u00e8res et gazi\u00e8res. Nos recettes int\u00e9rieures ont augment\u00e9 de 23% au cours de l\u2019ann\u00e9e 2022, gr\u00e2ce \u00e0 la bonne performance de nos r\u00e9gies financi\u00e8res qui ont r\u00e9ussi un taux de recouvrement plus que satisfaisant de 90% par rapport \u00e0 l\u2019objectif fix\u00e9. Ces efforts nous ont donn\u00e9 plus d\u2019autonomie budg\u00e9taire, en permettant de couvrir 85% des d\u00e9penses publiques internes de l\u2019Etat. Dans le m\u00eame esprit de bonne gouvernance des affaires publiques, l\u2019exploitation du rapport de la Cour des comptes sur la gestion financi\u00e8re de la pand\u00e9mie de COVID-19 suivra son cours conform\u00e9ment aux dispositions l\u00e9gales et r\u00e9glementaires en la mati\u00e8re. Mes chers compatriotes, Dans un contexte mondial particuli\u00e8rement difficile, marqu\u00e9 par une hausse g\u00e9n\u00e9ralis\u00e9e des prix, j\u2019ai souhait\u00e9 faire de 2022 une ann\u00e9e sociale, d\u00e9di\u00e9e \u00e0 la protection du pouvoir d\u2019achat des m\u00e9nages. C\u2019est le sens des mesures portant sur : \u00d8 l\u2019augmentation substantielle des salaires pour un montant cumul\u00e9 de 236 milliards\u00a0de FCFA ; \u00d8 la subvention des prix du carburant, du gaz et des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9 pour plus de 750\u00a0milliards ; \u00d8 la renonciation, par l\u2019Etat, de 157 milliards de recettes fiscales sur des produits import\u00e9s comme le riz, le bl\u00e9, le ma\u00efs, le sucre et\u00a0l\u2019huile, afin d\u2019\u00e9viter leur rench\u00e9rissement pour le consommateur\u00a0; \u00d8 enfin, le soutien direct \u00e0 543 000 familles vuln\u00e9rables par transfert d\u2019argent pour plus de 43 milliards. A cela s\u2019ajoutent les d\u00e9cisions issues des concertations nationales sur la lutte contre la vie ch\u00e8re, visant \u00e0 contenir la tendance inflationniste des prix, y compris le loyer. Je remercie l\u2019ensemble des acteurs \u00e9conomiques et autres forces vives de la nation qui ont contribu\u00e9 au succ\u00e8s de cet exercice de solidarit\u00e9 nationale. L\u2019effort de protection sociale sera renforc\u00e9 en 2023 avec la mobilisation de plus de 450 milliards au titre des subventions des produits alimentaires et \u00e9nerg\u00e9tiques. Celles concernant le carburant et l\u2019\u00e9lectricit\u00e9 seront cependant ajust\u00e9es et mieux cibl\u00e9es en faveur des couches sociales les plus n\u00e9cessiteuses. En outre, les bourses de s\u00e9curit\u00e9 familiale seront port\u00e9es de 25\u00a0000 fcfa \u00e0 35\u00a0000 fcfa par trimestre et \u00e9largies \u00e0 de nouveaux b\u00e9n\u00e9ficiaires sur la base de crit\u00e8res de vuln\u00e9rabilit\u00e9. C\u2019est dire, mes chers compatriotes, que le Gouvernement reste dans le temps de l\u2019action, de la sensibilit\u00e9 sociale par la veille, l\u2019\u00e9coute et la proximit\u00e9\u00a0; mais \u00e9galement de l\u2019offensive \u00e9conomique. En somme, le S\u00e9n\u00e9gal est aujourd\u2019hui pass\u00e9 d\u2019un \u00e9tat d\u2019indigence \u00e0 un \u00e9tat d\u2019\u00e9mergence. Le combat pour la souverainet\u00e9 alimentaire reste un objectif de premier plan. Ainsi, en trois, ans, le budget de la campagne agricole a doubl\u00e9, passant de 40 milliards de FCFA en 2019 \u00e0 plus de 80 milliards en 2022, pour soutenir les producteurs en semences, engrais et mat\u00e9riels agricoles. Cette ann\u00e9e encore, gr\u00e2ce \u00e0 l\u2019intensification de nos efforts et une pluviom\u00e9trie abondante, les r\u00e9coltes sont satisfaisantes, avec plus de 3,6 millions de tonnes pour les c\u00e9r\u00e9ales et 1,5 million respectivement pour l\u2019arachide et les produits horticoles. Nous ferons encore mieux avec les nouveaux am\u00e9nagements hydro-agricoles en cours, une meilleure ma\u00eetrise de l\u2019eau et le d\u00e9veloppement progressif des Agropoles, des Domaines agricoles communautaires et des fermes Naatangu\u00e9 et Waar-Wi. Dans le cadre de la modernisation du secteur agricole, je me r\u00e9jouis d\u2019annoncer l\u2019acquisition prochaine de plusieurs mat\u00e9riels et \u00e9quipements, dont des tracteurs, moissonneuses-batteuses, kits d\u2019irrigation, magasins de stockage et chambres froides. Mes chers compatriotes, En d\u00e9pit de la crise, nous poursuivons r\u00e9solument nos chantiers d\u2019infrastructures, parce qu\u2019il ne peut y avoir d\u2019\u00e9mergence sans infrastructures de base. Cette ann\u00e9e, nous avons achev\u00e9 des projets embl\u00e9matiques, comme la premi\u00e8re phase du TER, le stade Abdoulaye Wade, le pont Nelson Mandela Foundiougne et celui de Marsassoum, l\u2019autopont de Keur Massar, les axes routiers Tambacounda-Goudiry-Kidira, et Louga-Dahra, entre autres. Au total, 60 chantiers d\u2019infrastructures sont actuellement en cours d\u2019ex\u00e9cution, mettant \u00e0 contribution le secteur priv\u00e9 national et une main d\u2019\u0153uvre intensive. Il s\u2019agit, entre autres\u00a0: \u00d8 de la ligne du BRT entre Gu\u00e9diawaye et Dakar\u00a0; \u00d8 de la 2e phase du TER, entre Diamniadio et AIBD\u00a0; \u00d8 de la route du Daand\u00e9 maayo\u00a0; \u00d8 de l\u2019axe Kidira-Bakel\u00a0; \u00d8 de l\u2019autoroute du Nord Dakar-Tivaouane-Saint-Louis, dont les travaux d\u00e9marrent en 2023 en coh\u00e9rence avec le regain de trafic li\u00e9 \u00e0 l\u2019exploitation de nos hydrocarbures\u00a0; \u00d8 du Programme de Connectivit\u00e9 des Zones de Production Agricole, dans les r\u00e9gions de Kaffrine, Kaolack et Thi\u00e8s, dont le montage financier est boucl\u00e9\u00a0; \u00d8 et du Programme Sp\u00e9cial de D\u00e9senclavement,\u00a0un vaste chantier quinquennal qui a d\u00e9j\u00e0 d\u00e9marr\u00e9 pour r\u00e9aliser 2850 Km de routes, ainsi que des ouvrages d\u2019art en milieu rural et urbain. A terme, ce Programme mobilisera 60 entreprises nationales et g\u00e9n\u00e9rera 50.000 emplois. S\u2019y ajoutent les projets sp\u00e9cifiques d\u2019\u00e9quit\u00e9 territoriale ex\u00e9cut\u00e9s par le PUDC, le PUMA et le PROMOVILLES, pour un maillage complet du pays en routes bitum\u00e9es, pistes carrossables, infrastructures hydrauliques et \u00e9lectriques. Ce sont tous ces efforts qui ont\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-31T20:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png\" \/>\n\t<meta property=\"og:image:width\" content=\"674\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"Nouvel An : L&rsquo;int\u00e9gralit\u00e9 du discours de Macky Sall\",\"datePublished\":\"2022-12-31T20:37:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/\"},\"wordCount\":3025,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/macky.png\",\"articleSection\":[\"ACTUALIT\u00c9S\",\"POLITIQUE\",\"S\u00c9N\u00c9GAL\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/\",\"name\":\"Nouvel An : L'int\u00e9gralit\u00e9 du discours de Macky Sall - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/macky.png\",\"datePublished\":\"2022-12-31T20:37:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/macky.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/macky.png\",\"width\":674,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/12\\\/31\\\/nouvel-an-lintegralite-du-discours-de-macky-sall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvel An : L&rsquo;int\u00e9gralit\u00e9 du discours de Macky Sall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\\\/\\\/www.public.sn\"],\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/admin7324\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvel An : L'int\u00e9gralit\u00e9 du discours de Macky Sall - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvel An : L'int\u00e9gralit\u00e9 du discours de Macky Sall - LE PUBLIC","og_description":"&nbsp; Mes chers compatriotes, H\u00f4tes \u00e9trangers qui vivez parmi nous,\u00a0 Au seuil du nouvel an, je suis heureux de m\u2019adresser \u00e0 vous pour vous pr\u00e9senter mes v\u0153ux. Ce soir, alors que la communaut\u00e9 catholique est en deuil, avec le rappel \u00e0 Dieu de Sa Saintet\u00e9, le Pape \u00e9m\u00e9rite Benoit XVI, je voudrais d\u2019abord joindre mes pens\u00e9es aux v\u00f4tres, en souvenir des \u00eatres chers qui nous ont quitt\u00e9s. Je prie avec vous pour qu\u2019ils reposent en paix. A nos malades, j\u2019exprime ma compassion et mes souhaits de prompt r\u00e9tablissement. L\u2019ann\u00e9e 2022 s\u2019ach\u00e8ve comme elle a commenc\u00e9. L\u2019impact de la pand\u00e9mie et d\u2019une guerre majeure continue en effet de bouleverser toutes les pr\u00e9visions et de maintenir l\u2019\u00e9conomie dans sa pire r\u00e9cession depuis la seconde guerre mondiale. Malgr\u00e9 cette situation difficile, o\u00f9 nombre de pays sont en stagnation ou r\u00e9cession, notre \u00e9conomie reste r\u00e9siliente. Le classement de World Economics, qui fait autorit\u00e9 en mati\u00e8re de donn\u00e9es statistiques, reconnait en effet le S\u00e9n\u00e9gal comme pays \u00e0 la croissance la plus r\u00e9guli\u00e8re sur la d\u00e9cennie 2011-2021. Cette ann\u00e9e, notre d\u00e9ficit budg\u00e9taire s\u2019est r\u00e9tr\u00e9ci. Notre taux de croissance, \u00e9tabli \u00e0 4,8 %, devrait atteindre un niveau sans pr\u00e9c\u00e9dent de 10% en 2023, avec le d\u00e9but d\u2019exploitation de nos ressources p\u00e9troli\u00e8res et gazi\u00e8res. Nos recettes int\u00e9rieures ont augment\u00e9 de 23% au cours de l\u2019ann\u00e9e 2022, gr\u00e2ce \u00e0 la bonne performance de nos r\u00e9gies financi\u00e8res qui ont r\u00e9ussi un taux de recouvrement plus que satisfaisant de 90% par rapport \u00e0 l\u2019objectif fix\u00e9. Ces efforts nous ont donn\u00e9 plus d\u2019autonomie budg\u00e9taire, en permettant de couvrir 85% des d\u00e9penses publiques internes de l\u2019Etat. Dans le m\u00eame esprit de bonne gouvernance des affaires publiques, l\u2019exploitation du rapport de la Cour des comptes sur la gestion financi\u00e8re de la pand\u00e9mie de COVID-19 suivra son cours conform\u00e9ment aux dispositions l\u00e9gales et r\u00e9glementaires en la mati\u00e8re. Mes chers compatriotes, Dans un contexte mondial particuli\u00e8rement difficile, marqu\u00e9 par une hausse g\u00e9n\u00e9ralis\u00e9e des prix, j\u2019ai souhait\u00e9 faire de 2022 une ann\u00e9e sociale, d\u00e9di\u00e9e \u00e0 la protection du pouvoir d\u2019achat des m\u00e9nages. C\u2019est le sens des mesures portant sur : \u00d8 l\u2019augmentation substantielle des salaires pour un montant cumul\u00e9 de 236 milliards\u00a0de FCFA ; \u00d8 la subvention des prix du carburant, du gaz et des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9 pour plus de 750\u00a0milliards ; \u00d8 la renonciation, par l\u2019Etat, de 157 milliards de recettes fiscales sur des produits import\u00e9s comme le riz, le bl\u00e9, le ma\u00efs, le sucre et\u00a0l\u2019huile, afin d\u2019\u00e9viter leur rench\u00e9rissement pour le consommateur\u00a0; \u00d8 enfin, le soutien direct \u00e0 543 000 familles vuln\u00e9rables par transfert d\u2019argent pour plus de 43 milliards. A cela s\u2019ajoutent les d\u00e9cisions issues des concertations nationales sur la lutte contre la vie ch\u00e8re, visant \u00e0 contenir la tendance inflationniste des prix, y compris le loyer. Je remercie l\u2019ensemble des acteurs \u00e9conomiques et autres forces vives de la nation qui ont contribu\u00e9 au succ\u00e8s de cet exercice de solidarit\u00e9 nationale. L\u2019effort de protection sociale sera renforc\u00e9 en 2023 avec la mobilisation de plus de 450 milliards au titre des subventions des produits alimentaires et \u00e9nerg\u00e9tiques. Celles concernant le carburant et l\u2019\u00e9lectricit\u00e9 seront cependant ajust\u00e9es et mieux cibl\u00e9es en faveur des couches sociales les plus n\u00e9cessiteuses. En outre, les bourses de s\u00e9curit\u00e9 familiale seront port\u00e9es de 25\u00a0000 fcfa \u00e0 35\u00a0000 fcfa par trimestre et \u00e9largies \u00e0 de nouveaux b\u00e9n\u00e9ficiaires sur la base de crit\u00e8res de vuln\u00e9rabilit\u00e9. C\u2019est dire, mes chers compatriotes, que le Gouvernement reste dans le temps de l\u2019action, de la sensibilit\u00e9 sociale par la veille, l\u2019\u00e9coute et la proximit\u00e9\u00a0; mais \u00e9galement de l\u2019offensive \u00e9conomique. En somme, le S\u00e9n\u00e9gal est aujourd\u2019hui pass\u00e9 d\u2019un \u00e9tat d\u2019indigence \u00e0 un \u00e9tat d\u2019\u00e9mergence. Le combat pour la souverainet\u00e9 alimentaire reste un objectif de premier plan. Ainsi, en trois, ans, le budget de la campagne agricole a doubl\u00e9, passant de 40 milliards de FCFA en 2019 \u00e0 plus de 80 milliards en 2022, pour soutenir les producteurs en semences, engrais et mat\u00e9riels agricoles. Cette ann\u00e9e encore, gr\u00e2ce \u00e0 l\u2019intensification de nos efforts et une pluviom\u00e9trie abondante, les r\u00e9coltes sont satisfaisantes, avec plus de 3,6 millions de tonnes pour les c\u00e9r\u00e9ales et 1,5 million respectivement pour l\u2019arachide et les produits horticoles. Nous ferons encore mieux avec les nouveaux am\u00e9nagements hydro-agricoles en cours, une meilleure ma\u00eetrise de l\u2019eau et le d\u00e9veloppement progressif des Agropoles, des Domaines agricoles communautaires et des fermes Naatangu\u00e9 et Waar-Wi. Dans le cadre de la modernisation du secteur agricole, je me r\u00e9jouis d\u2019annoncer l\u2019acquisition prochaine de plusieurs mat\u00e9riels et \u00e9quipements, dont des tracteurs, moissonneuses-batteuses, kits d\u2019irrigation, magasins de stockage et chambres froides. Mes chers compatriotes, En d\u00e9pit de la crise, nous poursuivons r\u00e9solument nos chantiers d\u2019infrastructures, parce qu\u2019il ne peut y avoir d\u2019\u00e9mergence sans infrastructures de base. Cette ann\u00e9e, nous avons achev\u00e9 des projets embl\u00e9matiques, comme la premi\u00e8re phase du TER, le stade Abdoulaye Wade, le pont Nelson Mandela Foundiougne et celui de Marsassoum, l\u2019autopont de Keur Massar, les axes routiers Tambacounda-Goudiry-Kidira, et Louga-Dahra, entre autres. Au total, 60 chantiers d\u2019infrastructures sont actuellement en cours d\u2019ex\u00e9cution, mettant \u00e0 contribution le secteur priv\u00e9 national et une main d\u2019\u0153uvre intensive. Il s\u2019agit, entre autres\u00a0: \u00d8 de la ligne du BRT entre Gu\u00e9diawaye et Dakar\u00a0; \u00d8 de la 2e phase du TER, entre Diamniadio et AIBD\u00a0; \u00d8 de la route du Daand\u00e9 maayo\u00a0; \u00d8 de l\u2019axe Kidira-Bakel\u00a0; \u00d8 de l\u2019autoroute du Nord Dakar-Tivaouane-Saint-Louis, dont les travaux d\u00e9marrent en 2023 en coh\u00e9rence avec le regain de trafic li\u00e9 \u00e0 l\u2019exploitation de nos hydrocarbures\u00a0; \u00d8 du Programme de Connectivit\u00e9 des Zones de Production Agricole, dans les r\u00e9gions de Kaffrine, Kaolack et Thi\u00e8s, dont le montage financier est boucl\u00e9\u00a0; \u00d8 et du Programme Sp\u00e9cial de D\u00e9senclavement,\u00a0un vaste chantier quinquennal qui a d\u00e9j\u00e0 d\u00e9marr\u00e9 pour r\u00e9aliser 2850 Km de routes, ainsi que des ouvrages d\u2019art en milieu rural et urbain. A terme, ce Programme mobilisera 60 entreprises nationales et g\u00e9n\u00e9rera 50.000 emplois. S\u2019y ajoutent les projets sp\u00e9cifiques d\u2019\u00e9quit\u00e9 territoriale ex\u00e9cut\u00e9s par le PUDC, le PUMA et le PROMOVILLES, pour un maillage complet du pays en routes bitum\u00e9es, pistes carrossables, infrastructures hydrauliques et \u00e9lectriques. Ce sont tous ces efforts qui ont","og_url":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/","og_site_name":"LE PUBLIC","article_published_time":"2022-12-31T20:37:18+00:00","og_image":[{"width":674,"height":381,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png","type":"image\/png"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"Nouvel An : L&rsquo;int\u00e9gralit\u00e9 du discours de Macky Sall","datePublished":"2022-12-31T20:37:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/"},"wordCount":3025,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png","articleSection":["ACTUALIT\u00c9S","POLITIQUE","S\u00c9N\u00c9GAL","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/","url":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/","name":"Nouvel An : L'int\u00e9gralit\u00e9 du discours de Macky Sall - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png","datePublished":"2022-12-31T20:37:18+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png","width":674,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2022\/12\/31\/nouvel-an-lintegralite-du-discours-de-macky-sall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"Nouvel An : L&rsquo;int\u00e9gralit\u00e9 du discours de Macky Sall"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/12\/macky.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=13146"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13146\/revisions"}],"predecessor-version":[{"id":13148,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13146\/revisions\/13148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/13147"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=13146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=13146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=13146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}