{"id":13627,"date":"2023-01-14T10:24:06","date_gmt":"2023-01-14T10:24:06","guid":{"rendered":"https:\/\/www.public.sn\/?p=13627"},"modified":"2023-01-14T10:24:06","modified_gmt":"2023-01-14T10:24:06","slug":"presidentielle-2024-la-question-du-3e-mandat-divise-lafp","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/","title":{"rendered":"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP"},"content":{"rendered":"<p><strong>La Pr\u00e9sidentielle de 2024 va certainement caus\u00e9e beaucoup de fissures au sein de la coalition BBY. A quelques mois de ce rendez-vous tr\u00e8s int\u00e9ressant dans la vie d&rsquo;une nation, les ambitions des uns et des autres se dessinent. Au sein de l\u2019Alliance des forces de progr\u00e8s (AFP, des militants ont exprim\u00e9 le souhait de rompre avec la Coalition pr\u00e9sidentielle Benno Bokk Yakaar (BBY).<\/strong><\/p><div class=\"publi-paragraphe1\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"publi-2476852804\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Cheikh Ndiaye, un des responsables progressistes \u00e0 la Sicap-Libert\u00e9 et t\u00eate de file de ce groupe de r\u00e9flexion s\u2019est ainsi d\u00e9marqu\u00e9 sur les ondes de la Rfm : \u00ab Nous sommes embarqu\u00e9 sur une voie qui est sans issue aujourd\u2019hui pour l\u2019AFP. Depuis 2014, l\u2019AFP s\u2019\u00e9tait engag\u00e9e \u00e0 accompagner pour un second mandat, le pr\u00e9sident Macky Sall. \u00bb<\/p>\n<p>Il rappelle, toutefois, qu\u2019il y avait \u00ab un consensus autour d\u2019une candidature de l\u2019AFP en 2024 et une d\u00e9claration de notre secr\u00e9taire g\u00e9n\u00e9ral et son directeur de cabinet. \u00bb Mais, \u00ab nous sommes quasiment en 2024 et l\u2019AFP ne s\u2019est pas prononc\u00e9e \u00bb, ajoute-t-il.<\/p>\n<p>La r\u00e9ponse du porte-parole de l\u2019AFP, Dr Malick Diop n\u2019a pas tard\u00e9, soulignant que le parti reste arrim\u00e9 \u00e0 BBY. Puisqu\u2019a-t-il object\u00e9 : Aucune volont\u00e9 allant dans le sens de claquer la porte de la coalition au pouvoir en vue de faire cavalier seul pour la pr\u00e9sidentielle 2024 n\u2019a pas encore \u00e9t\u00e9 manifest\u00e9e au sein de leur instance politique.<\/p>\n<p>\u00ab Nous sommes un parti d\u00e9mocratique. Chacun peut dire ce qu\u2019il veut, \u00e7a n\u2019engage que lui \u00bb, a tranch\u00e9 le 3\u00e8me vice-pr\u00e9sident de l&rsquo;Assembl\u00e9e nationale.<\/p>\n<div class=\"publi-apres-le-contenu\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"publi-2903497449\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La Pr\u00e9sidentielle de 2024 va certainement caus\u00e9e beaucoup de fissures au sein de la coalition BBY. A quelques mois de ce rendez-vous tr\u00e8s int\u00e9ressant dans la vie d&rsquo;une nation, les ambitions des uns et des autres se dessinent. Au sein de l\u2019Alliance des forces de progr\u00e8s (AFP, des militants ont exprim\u00e9 le souhait de rompre avec la Coalition pr\u00e9sidentielle Benno Bokk Yakaar (BBY). Cheikh Ndiaye, un des responsables progressistes \u00e0 la Sicap-Libert\u00e9 et t\u00eate de file de ce groupe de r\u00e9flexion s\u2019est ainsi d\u00e9marqu\u00e9 sur les ondes de la Rfm : \u00ab Nous sommes embarqu\u00e9 sur une voie qui est sans issue aujourd\u2019hui pour l\u2019AFP. Depuis 2014, l\u2019AFP s\u2019\u00e9tait engag\u00e9e \u00e0 accompagner pour un second mandat, le pr\u00e9sident Macky Sall. \u00bb Il rappelle, toutefois, qu\u2019il y avait \u00ab un consensus autour d\u2019une candidature de l\u2019AFP en 2024 et une d\u00e9claration de notre secr\u00e9taire g\u00e9n\u00e9ral et son directeur de cabinet. \u00bb Mais, \u00ab nous sommes quasiment en 2024 et l\u2019AFP ne s\u2019est pas prononc\u00e9e \u00bb, ajoute-t-il. La r\u00e9ponse du porte-parole de l\u2019AFP, Dr Malick Diop n\u2019a pas tard\u00e9, soulignant que le parti reste arrim\u00e9 \u00e0 BBY. Puisqu\u2019a-t-il object\u00e9 : Aucune volont\u00e9 allant dans le sens de claquer la porte de la coalition au pouvoir en vue de faire cavalier seul pour la pr\u00e9sidentielle 2024 n\u2019a pas encore \u00e9t\u00e9 manifest\u00e9e au sein de leur instance politique. \u00ab Nous sommes un parti d\u00e9mocratique. Chacun peut dire ce qu\u2019il veut, \u00e7a n\u2019engage que lui \u00bb, a tranch\u00e9 le 3\u00e8me vice-pr\u00e9sident de l&rsquo;Assembl\u00e9e nationale.<\/p>\n","protected":false},"author":1,"featured_media":13628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,3,1,372],"tags":[4091,806],"class_list":["post-13627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-politique","category-non-classe","category-vedette","tag-afp","tag-moustapha-niasse","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"La Pr\u00e9sidentielle de 2024 va certainement caus\u00e9e beaucoup de fissures au sein de la coalition BBY. A quelques mois de ce rendez-vous tr\u00e8s int\u00e9ressant dans la vie d&rsquo;une nation, les ambitions des uns et des autres se dessinent. Au sein de l\u2019Alliance des forces de progr\u00e8s (AFP, des militants ont exprim\u00e9 le souhait de rompre avec la Coalition pr\u00e9sidentielle Benno Bokk Yakaar (BBY). Cheikh Ndiaye, un des responsables progressistes \u00e0 la Sicap-Libert\u00e9 et t\u00eate de file de ce groupe de r\u00e9flexion s\u2019est ainsi d\u00e9marqu\u00e9 sur les ondes de la Rfm : \u00ab Nous sommes embarqu\u00e9 sur une voie qui est sans issue aujourd\u2019hui pour l\u2019AFP. Depuis 2014, l\u2019AFP s\u2019\u00e9tait engag\u00e9e \u00e0 accompagner pour un second mandat, le pr\u00e9sident Macky Sall. \u00bb Il rappelle, toutefois, qu\u2019il y avait \u00ab un consensus autour d\u2019une candidature de l\u2019AFP en 2024 et une d\u00e9claration de notre secr\u00e9taire g\u00e9n\u00e9ral et son directeur de cabinet. \u00bb Mais, \u00ab nous sommes quasiment en 2024 et l\u2019AFP ne s\u2019est pas prononc\u00e9e \u00bb, ajoute-t-il. La r\u00e9ponse du porte-parole de l\u2019AFP, Dr Malick Diop n\u2019a pas tard\u00e9, soulignant que le parti reste arrim\u00e9 \u00e0 BBY. Puisqu\u2019a-t-il object\u00e9 : Aucune volont\u00e9 allant dans le sens de claquer la porte de la coalition au pouvoir en vue de faire cavalier seul pour la pr\u00e9sidentielle 2024 n\u2019a pas encore \u00e9t\u00e9 manifest\u00e9e au sein de leur instance politique. \u00ab Nous sommes un parti d\u00e9mocratique. Chacun peut dire ce qu\u2019il veut, \u00e7a n\u2019engage que lui \u00bb, a tranch\u00e9 le 3\u00e8me vice-pr\u00e9sident de l&rsquo;Assembl\u00e9e nationale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-14T10:24:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"447\" \/>\n\t<meta property=\"og:image:height\" content=\"362\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP\",\"datePublished\":\"2023-01-14T10:24:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\"},\"wordCount\":280,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.public.sn\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg\",\"keywords\":[\"AFP\",\"Moustapha Niasse\"],\"articleSection\":[\"ACTUALIT\u00c9S\",\"POLITIQUE\",\"S\u00c9N\u00c9GAL\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\",\"url\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\",\"name\":\"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.public.sn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg\",\"datePublished\":\"2023-01-14T10:24:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage\",\"url\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg\",\"contentUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg\",\"width\":447,\"height\":362},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.public.sn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.public.sn\/#website\",\"url\":\"https:\/\/www.public.sn\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.public.sn\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.public.sn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.public.sn\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\/\/www.public.sn\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\/\/www.public.sn\"],\"url\":\"https:\/\/www.public.sn\/index.php\/author\/admin7324\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP - LE PUBLIC","og_description":"La Pr\u00e9sidentielle de 2024 va certainement caus\u00e9e beaucoup de fissures au sein de la coalition BBY. A quelques mois de ce rendez-vous tr\u00e8s int\u00e9ressant dans la vie d&rsquo;une nation, les ambitions des uns et des autres se dessinent. Au sein de l\u2019Alliance des forces de progr\u00e8s (AFP, des militants ont exprim\u00e9 le souhait de rompre avec la Coalition pr\u00e9sidentielle Benno Bokk Yakaar (BBY). Cheikh Ndiaye, un des responsables progressistes \u00e0 la Sicap-Libert\u00e9 et t\u00eate de file de ce groupe de r\u00e9flexion s\u2019est ainsi d\u00e9marqu\u00e9 sur les ondes de la Rfm : \u00ab Nous sommes embarqu\u00e9 sur une voie qui est sans issue aujourd\u2019hui pour l\u2019AFP. Depuis 2014, l\u2019AFP s\u2019\u00e9tait engag\u00e9e \u00e0 accompagner pour un second mandat, le pr\u00e9sident Macky Sall. \u00bb Il rappelle, toutefois, qu\u2019il y avait \u00ab un consensus autour d\u2019une candidature de l\u2019AFP en 2024 et une d\u00e9claration de notre secr\u00e9taire g\u00e9n\u00e9ral et son directeur de cabinet. \u00bb Mais, \u00ab nous sommes quasiment en 2024 et l\u2019AFP ne s\u2019est pas prononc\u00e9e \u00bb, ajoute-t-il. La r\u00e9ponse du porte-parole de l\u2019AFP, Dr Malick Diop n\u2019a pas tard\u00e9, soulignant que le parti reste arrim\u00e9 \u00e0 BBY. Puisqu\u2019a-t-il object\u00e9 : Aucune volont\u00e9 allant dans le sens de claquer la porte de la coalition au pouvoir en vue de faire cavalier seul pour la pr\u00e9sidentielle 2024 n\u2019a pas encore \u00e9t\u00e9 manifest\u00e9e au sein de leur instance politique. \u00ab Nous sommes un parti d\u00e9mocratique. Chacun peut dire ce qu\u2019il veut, \u00e7a n\u2019engage que lui \u00bb, a tranch\u00e9 le 3\u00e8me vice-pr\u00e9sident de l&rsquo;Assembl\u00e9e nationale.","og_url":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/","og_site_name":"LE PUBLIC","article_published_time":"2023-01-14T10:24:06+00:00","og_image":[{"width":447,"height":362,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP","datePublished":"2023-01-14T10:24:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/"},"wordCount":280,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg","keywords":["AFP","Moustapha Niasse"],"articleSection":["ACTUALIT\u00c9S","POLITIQUE","S\u00c9N\u00c9GAL","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/","url":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/","name":"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg","datePublished":"2023-01-14T10:24:06+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg","width":447,"height":362},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2023\/01\/14\/presidentielle-2024-la-question-du-3e-mandat-divise-lafp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9sidentielle 2024 : La question du 3e mandat divise l\u2019AFP"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/01\/moustapha-nias.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=13627"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13627\/revisions"}],"predecessor-version":[{"id":13629,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/13627\/revisions\/13629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/13628"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=13627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=13627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=13627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}