{"id":16489,"date":"2023-02-24T14:38:23","date_gmt":"2023-02-24T14:38:23","guid":{"rendered":"https:\/\/www.public.sn\/?p=16489"},"modified":"2023-02-24T14:38:23","modified_gmt":"2023-02-24T14:38:23","slug":"la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/","title":{"rendered":"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards"},"content":{"rendered":"<p>En d\u00e9pit d\u2019une rude concurrence et d\u2019un contexte socio\u00e9conomique difficile, le Groupe Sonatel, pr\u00e9sent dans 5 pays (S\u00e9n\u00e9gal, Mali, Guin\u00e9e, Guin\u00e9e Bissau et Sierra L\u00e9one), a atteint ses objectifs pour l\u2019exercice 2022 gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle. D\u2019apr\u00e8s un communiqu\u00e9 parvenu \u00abL\u2019As\u00bb, le chiffre d\u2019affaires consolid\u00e9 dans les 5 pays s\u2019\u00e9l\u00e8ve \u00e0 1455 milliards FCFA, soit une croissance de 9% par rapport \u00e0 d\u00e9cembre 2021. Une progression obtenue sans une hausse des tarifs, malgr\u00e9 le rench\u00e9rissement des co\u00fbts de production du fait de la pouss\u00e9e inflationniste, selon L\u2019As.<\/p><div id=\"publi-1193161026\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Cette croissance a \u00e9t\u00e9 soutenue par l\u2019intensification des investissements pour \u00e9tendre et densifier les r\u00e9seaux. Au titre de l\u2019ann\u00e9e 2022, indique le communiqu\u00e9, 262 milliards FCFA ont \u00e9t\u00e9 allou\u00e9s aux investissements dans les 5 pays en r\u00e9ponse aux engagements r\u00e9glementaires, pour l\u2019am\u00e9lioration de la qualit\u00e9 de service, la contribution \u00e0 l\u2019am\u00e9nagement num\u00e9rique des territoires et surtout pour l\u2019accompagnement des Etats dans leur politique de d\u00e9veloppement num\u00e9rique.<\/p>\n<p>Ce qui a permis d\u2019\u00e9tendre le r\u00e9seau Fibre pour faciliter l\u2019acc\u00e8s des m\u00e9nages \u00e0 l\u2019internet haut d\u00e9bit, l\u2019am\u00e9lioration de l\u2019exp\u00e9rience client avec une qualit\u00e9 des r\u00e9seaux incomparable et l\u2019innovation avec le lancement en phase pilote de la 5G au S\u00e9n\u00e9gal. Gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle et une politique de ma\u00eetrise des charges en constante am\u00e9lioration, selon la Sonatel, le r\u00e9sultat net consolid\u00e9 du Groupe s\u2019\u00e9tablit \u00e0 279 milliards FCFA en croissance de 10,5%, repr\u00e9sentant 19% du chiffre d\u2019affaires consolid\u00e9.<\/p>\n<div id=\"publi-1882256371\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En d\u00e9pit d\u2019une rude concurrence et d\u2019un contexte socio\u00e9conomique difficile, le Groupe Sonatel, pr\u00e9sent dans 5 pays (S\u00e9n\u00e9gal, Mali, Guin\u00e9e, Guin\u00e9e Bissau et Sierra L\u00e9one), a atteint ses objectifs pour l\u2019exercice 2022 gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle. D\u2019apr\u00e8s un communiqu\u00e9 parvenu \u00abL\u2019As\u00bb, le chiffre d\u2019affaires consolid\u00e9 dans les 5 pays s\u2019\u00e9l\u00e8ve \u00e0 1455 milliards FCFA, soit une croissance de 9% par rapport \u00e0 d\u00e9cembre 2021. Une progression obtenue sans une hausse des tarifs, malgr\u00e9 le rench\u00e9rissement des co\u00fbts de production du fait de la pouss\u00e9e inflationniste, selon L\u2019As. Cette croissance a \u00e9t\u00e9 soutenue par l\u2019intensification des investissements pour \u00e9tendre et densifier les r\u00e9seaux. Au titre de l\u2019ann\u00e9e 2022, indique le communiqu\u00e9, 262 milliards FCFA ont \u00e9t\u00e9 allou\u00e9s aux investissements dans les 5 pays en r\u00e9ponse aux engagements r\u00e9glementaires, pour l\u2019am\u00e9lioration de la qualit\u00e9 de service, la contribution \u00e0 l\u2019am\u00e9nagement num\u00e9rique des territoires et surtout pour l\u2019accompagnement des Etats dans leur politique de d\u00e9veloppement num\u00e9rique. Ce qui a permis d\u2019\u00e9tendre le r\u00e9seau Fibre pour faciliter l\u2019acc\u00e8s des m\u00e9nages \u00e0 l\u2019internet haut d\u00e9bit, l\u2019am\u00e9lioration de l\u2019exp\u00e9rience client avec une qualit\u00e9 des r\u00e9seaux incomparable et l\u2019innovation avec le lancement en phase pilote de la 5G au S\u00e9n\u00e9gal. Gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle et une politique de ma\u00eetrise des charges en constante am\u00e9lioration, selon la Sonatel, le r\u00e9sultat net consolid\u00e9 du Groupe s\u2019\u00e9tablit \u00e0 279 milliards FCFA en croissance de 10,5%, repr\u00e9sentant 19% du chiffre d\u2019affaires consolid\u00e9.<\/p>\n","protected":false},"author":7,"featured_media":16491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,550,549,4222,5,1,4,4478,372],"tags":[4533,381],"class_list":["post-16489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-afrique-monde","category-economie","category-infrastructures","category-people","category-non-classe","category-societe","category-telecommunication","category-vedette","tag-chiffre-daffaire","tag-orange","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"En d\u00e9pit d\u2019une rude concurrence et d\u2019un contexte socio\u00e9conomique difficile, le Groupe Sonatel, pr\u00e9sent dans 5 pays (S\u00e9n\u00e9gal, Mali, Guin\u00e9e, Guin\u00e9e Bissau et Sierra L\u00e9one), a atteint ses objectifs pour l\u2019exercice 2022 gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle. D\u2019apr\u00e8s un communiqu\u00e9 parvenu \u00abL\u2019As\u00bb, le chiffre d\u2019affaires consolid\u00e9 dans les 5 pays s\u2019\u00e9l\u00e8ve \u00e0 1455 milliards FCFA, soit une croissance de 9% par rapport \u00e0 d\u00e9cembre 2021. Une progression obtenue sans une hausse des tarifs, malgr\u00e9 le rench\u00e9rissement des co\u00fbts de production du fait de la pouss\u00e9e inflationniste, selon L\u2019As. Cette croissance a \u00e9t\u00e9 soutenue par l\u2019intensification des investissements pour \u00e9tendre et densifier les r\u00e9seaux. Au titre de l\u2019ann\u00e9e 2022, indique le communiqu\u00e9, 262 milliards FCFA ont \u00e9t\u00e9 allou\u00e9s aux investissements dans les 5 pays en r\u00e9ponse aux engagements r\u00e9glementaires, pour l\u2019am\u00e9lioration de la qualit\u00e9 de service, la contribution \u00e0 l\u2019am\u00e9nagement num\u00e9rique des territoires et surtout pour l\u2019accompagnement des Etats dans leur politique de d\u00e9veloppement num\u00e9rique. Ce qui a permis d\u2019\u00e9tendre le r\u00e9seau Fibre pour faciliter l\u2019acc\u00e8s des m\u00e9nages \u00e0 l\u2019internet haut d\u00e9bit, l\u2019am\u00e9lioration de l\u2019exp\u00e9rience client avec une qualit\u00e9 des r\u00e9seaux incomparable et l\u2019innovation avec le lancement en phase pilote de la 5G au S\u00e9n\u00e9gal. Gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle et une politique de ma\u00eetrise des charges en constante am\u00e9lioration, selon la Sonatel, le r\u00e9sultat net consolid\u00e9 du Groupe s\u2019\u00e9tablit \u00e0 279 milliards FCFA en croissance de 10,5%, repr\u00e9sentant 19% du chiffre d\u2019affaires consolid\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-24T14:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/cb76c8e1b8becc6be61fb5e92d6d0224\"},\"headline\":\"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards\",\"datePublished\":\"2023-02-24T14:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SIEGE-SONATEL.jpg\",\"keywords\":[\"Chiffre d'affaire\",\"orange\"],\"articleSection\":[\"ACTUALIT\u00c9S\",\"AFRIQUE &amp; MONDE\",\"\u00c9CONOMIE\",\"INFRASTRUCTURES\",\"PEOPLE\",\"S\u00c9N\u00c9GAL\",\"SOCIETE\",\"T\u00c9L\u00c9COMMUNICATION\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/\",\"name\":\"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SIEGE-SONATEL.jpg\",\"datePublished\":\"2023-02-24T14:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SIEGE-SONATEL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/SIEGE-SONATEL.jpg\",\"width\":1110,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/02\\\/24\\\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/cb76c8e1b8becc6be61fb5e92d6d0224\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/editeurpsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/","og_locale":"fr_FR","og_type":"article","og_title":"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards - LE PUBLIC","og_description":"En d\u00e9pit d\u2019une rude concurrence et d\u2019un contexte socio\u00e9conomique difficile, le Groupe Sonatel, pr\u00e9sent dans 5 pays (S\u00e9n\u00e9gal, Mali, Guin\u00e9e, Guin\u00e9e Bissau et Sierra L\u00e9one), a atteint ses objectifs pour l\u2019exercice 2022 gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle. D\u2019apr\u00e8s un communiqu\u00e9 parvenu \u00abL\u2019As\u00bb, le chiffre d\u2019affaires consolid\u00e9 dans les 5 pays s\u2019\u00e9l\u00e8ve \u00e0 1455 milliards FCFA, soit une croissance de 9% par rapport \u00e0 d\u00e9cembre 2021. Une progression obtenue sans une hausse des tarifs, malgr\u00e9 le rench\u00e9rissement des co\u00fbts de production du fait de la pouss\u00e9e inflationniste, selon L\u2019As. Cette croissance a \u00e9t\u00e9 soutenue par l\u2019intensification des investissements pour \u00e9tendre et densifier les r\u00e9seaux. Au titre de l\u2019ann\u00e9e 2022, indique le communiqu\u00e9, 262 milliards FCFA ont \u00e9t\u00e9 allou\u00e9s aux investissements dans les 5 pays en r\u00e9ponse aux engagements r\u00e9glementaires, pour l\u2019am\u00e9lioration de la qualit\u00e9 de service, la contribution \u00e0 l\u2019am\u00e9nagement num\u00e9rique des territoires et surtout pour l\u2019accompagnement des Etats dans leur politique de d\u00e9veloppement num\u00e9rique. Ce qui a permis d\u2019\u00e9tendre le r\u00e9seau Fibre pour faciliter l\u2019acc\u00e8s des m\u00e9nages \u00e0 l\u2019internet haut d\u00e9bit, l\u2019am\u00e9lioration de l\u2019exp\u00e9rience client avec une qualit\u00e9 des r\u00e9seaux incomparable et l\u2019innovation avec le lancement en phase pilote de la 5G au S\u00e9n\u00e9gal. Gr\u00e2ce \u00e0 une efficacit\u00e9 op\u00e9rationnelle et une politique de ma\u00eetrise des charges en constante am\u00e9lioration, selon la Sonatel, le r\u00e9sultat net consolid\u00e9 du Groupe s\u2019\u00e9tablit \u00e0 279 milliards FCFA en croissance de 10,5%, repr\u00e9sentant 19% du chiffre d\u2019affaires consolid\u00e9.","og_url":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/","og_site_name":"LE PUBLIC","article_published_time":"2023-02-24T14:38:23+00:00","og_image":[{"width":1110,"height":550,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/cb76c8e1b8becc6be61fb5e92d6d0224"},"headline":"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards","datePublished":"2023-02-24T14:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg","keywords":["Chiffre d'affaire","orange"],"articleSection":["ACTUALIT\u00c9S","AFRIQUE &amp; MONDE","\u00c9CONOMIE","INFRASTRUCTURES","PEOPLE","S\u00c9N\u00c9GAL","SOCIETE","T\u00c9L\u00c9COMMUNICATION","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/","url":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/","name":"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg","datePublished":"2023-02-24T14:38:23+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg","width":1110,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2023\/02\/24\/la-sonatel-realise-un-chiffre-daffaires-de-1455-milliards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"La Sonatel r\u00e9alise un chiffre d\u2019affaires de 1455 milliards"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/cb76c8e1b8becc6be61fb5e92d6d0224","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","caption":"LA REDACTION"},"url":"https:\/\/www.public.sn\/index.php\/author\/editeurpsn\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/02\/SIEGE-SONATEL.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/16489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=16489"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/16489\/revisions"}],"predecessor-version":[{"id":16492,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/16489\/revisions\/16492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/16491"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=16489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=16489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=16489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}