{"id":19939,"date":"2023-04-17T15:20:20","date_gmt":"2023-04-17T15:20:20","guid":{"rendered":"https:\/\/www.public.sn\/?p=19939"},"modified":"2023-04-17T15:20:20","modified_gmt":"2023-04-17T15:20:20","slug":"violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/","title":{"rendered":"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s"},"content":{"rendered":"<p style=\"text-align: left;\">Le proc\u00e8s en appel \u00a0des d\u00e9put\u00e9s Massata Samb et Mamadou Niang a \u00e9t\u00e9 renvoy\u00e9 par la cour d&rsquo;appel du tribunal de grande instance de Dakar au 15 mai prochain. Les deux parlementaires ont \u00e9t\u00e9 condamn\u00e9s \u00e0 6 mois de prison ferme\u00a0 en premi\u00e8re instance pour des actes de violence qui se sont produits \u00e0 l&rsquo;h\u00e9micycle sur leur coll\u00e8gue Amy Ndiaye GNIBY en la giflant et en lui donnant un coup de pied dans le ventre. Pour Me Abdy Nar Ndiaye, conform\u00e9ment \u00e0 l\u2019article 129 du code de proc\u00e9dure p\u00e9nale, les avocats des parlementaires \u00a0ont tent\u00e9 de plaider la \u00a0libert\u00e9 provisoire, mais le juge a dit qu\u2019il ne peut pas y prononcer pare qu\u2019il ne peut pas conna\u00eetre l\u2019affaire conform\u00e9ment \u00e0 la loi. \u00c0 la sortie de l\u2019audience, les conseils des accus\u00e9s comptent r\u00e9diger une lettre \u00e0 la premi\u00e8re chambre de la cour d\u2019appel pour demander la mise en libert\u00e9 provisoire. Cela veut dire \u00e9videmment que la cour d\u2019appel peut lib\u00e9rer \u00a0les d\u00e9put\u00e9s avant la date du 15 mai prochain.<\/p><div id=\"publi-501283098\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<div id=\"publi-1883289858\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le proc\u00e8s en appel \u00a0des d\u00e9put\u00e9s Massata Samb et Mamadou Niang a \u00e9t\u00e9 renvoy\u00e9 par la cour d&rsquo;appel du tribunal de grande instance de Dakar au 15 mai prochain. Les deux parlementaires ont \u00e9t\u00e9 condamn\u00e9s \u00e0 6 mois de prison ferme\u00a0 en premi\u00e8re instance pour des actes de violence qui se sont produits \u00e0 l&rsquo;h\u00e9micycle sur leur coll\u00e8gue Amy Ndiaye GNIBY en la giflant et en lui donnant un coup de pied dans le ventre. Pour Me Abdy Nar Ndiaye, conform\u00e9ment \u00e0 l\u2019article 129 du code de proc\u00e9dure p\u00e9nale, les avocats des parlementaires \u00a0ont tent\u00e9 de plaider la \u00a0libert\u00e9 provisoire, mais le juge a dit qu\u2019il ne peut pas y prononcer pare qu\u2019il ne peut pas conna\u00eetre l\u2019affaire conform\u00e9ment \u00e0 la loi. \u00c0 la sortie de l\u2019audience, les conseils des accus\u00e9s comptent r\u00e9diger une lettre \u00e0 la premi\u00e8re chambre de la cour d\u2019appel pour demander la mise en libert\u00e9 provisoire. Cela veut dire \u00e9videmment que la cour d\u2019appel peut lib\u00e9rer \u00a0les d\u00e9put\u00e9s avant la date du 15 mai prochain.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19939","post","type-post","status-publish","format-standard","hentry","category-non-classe","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"Le proc\u00e8s en appel \u00a0des d\u00e9put\u00e9s Massata Samb et Mamadou Niang a \u00e9t\u00e9 renvoy\u00e9 par la cour d&rsquo;appel du tribunal de grande instance de Dakar au 15 mai prochain. Les deux parlementaires ont \u00e9t\u00e9 condamn\u00e9s \u00e0 6 mois de prison ferme\u00a0 en premi\u00e8re instance pour des actes de violence qui se sont produits \u00e0 l&rsquo;h\u00e9micycle sur leur coll\u00e8gue Amy Ndiaye GNIBY en la giflant et en lui donnant un coup de pied dans le ventre. Pour Me Abdy Nar Ndiaye, conform\u00e9ment \u00e0 l\u2019article 129 du code de proc\u00e9dure p\u00e9nale, les avocats des parlementaires \u00a0ont tent\u00e9 de plaider la \u00a0libert\u00e9 provisoire, mais le juge a dit qu\u2019il ne peut pas y prononcer pare qu\u2019il ne peut pas conna\u00eetre l\u2019affaire conform\u00e9ment \u00e0 la loi. \u00c0 la sortie de l\u2019audience, les conseils des accus\u00e9s comptent r\u00e9diger une lettre \u00e0 la premi\u00e8re chambre de la cour d\u2019appel pour demander la mise en libert\u00e9 provisoire. Cela veut dire \u00e9videmment que la cour d\u2019appel peut lib\u00e9rer \u00a0les d\u00e9put\u00e9s avant la date du 15 mai prochain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T15:20:20+00:00\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s\",\"datePublished\":\"2023-04-17T15:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/\"},\"wordCount\":202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"articleSection\":[\"S\u00c9N\u00c9GAL\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/\",\"name\":\"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"datePublished\":\"2023-04-17T15:20:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/17\\\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\\\/\\\/www.public.sn\"],\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/admin7324\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/","og_locale":"fr_FR","og_type":"article","og_title":"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s - LE PUBLIC","og_description":"Le proc\u00e8s en appel \u00a0des d\u00e9put\u00e9s Massata Samb et Mamadou Niang a \u00e9t\u00e9 renvoy\u00e9 par la cour d&rsquo;appel du tribunal de grande instance de Dakar au 15 mai prochain. Les deux parlementaires ont \u00e9t\u00e9 condamn\u00e9s \u00e0 6 mois de prison ferme\u00a0 en premi\u00e8re instance pour des actes de violence qui se sont produits \u00e0 l&rsquo;h\u00e9micycle sur leur coll\u00e8gue Amy Ndiaye GNIBY en la giflant et en lui donnant un coup de pied dans le ventre. Pour Me Abdy Nar Ndiaye, conform\u00e9ment \u00e0 l\u2019article 129 du code de proc\u00e9dure p\u00e9nale, les avocats des parlementaires \u00a0ont tent\u00e9 de plaider la \u00a0libert\u00e9 provisoire, mais le juge a dit qu\u2019il ne peut pas y prononcer pare qu\u2019il ne peut pas conna\u00eetre l\u2019affaire conform\u00e9ment \u00e0 la loi. \u00c0 la sortie de l\u2019audience, les conseils des accus\u00e9s comptent r\u00e9diger une lettre \u00e0 la premi\u00e8re chambre de la cour d\u2019appel pour demander la mise en libert\u00e9 provisoire. Cela veut dire \u00e9videmment que la cour d\u2019appel peut lib\u00e9rer \u00a0les d\u00e9put\u00e9s avant la date du 15 mai prochain.","og_url":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/","og_site_name":"LE PUBLIC","article_published_time":"2023-04-17T15:20:20+00:00","author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s","datePublished":"2023-04-17T15:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/"},"wordCount":202,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"articleSection":["S\u00c9N\u00c9GAL"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/","url":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/","name":"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"datePublished":"2023-04-17T15:20:20+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/17\/violence-a-lhemicycle-massata-samb-et-mamadou-niang-risquent-de-perdre-leur-mandat-de-deputes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"VIOLENCE A L\u2019HEMICYCLE : Massata Samb et Mamadou Niang risquent de perdre leur mandat de d\u00e9put\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/19939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=19939"}],"version-history":[{"count":2,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/19939\/revisions"}],"predecessor-version":[{"id":19941,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/19939\/revisions\/19941"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=19939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=19939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=19939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}