{"id":20315,"date":"2023-04-24T12:53:56","date_gmt":"2023-04-24T12:53:56","guid":{"rendered":"https:\/\/www.public.sn\/?p=20315"},"modified":"2023-04-24T12:53:56","modified_gmt":"2023-04-24T12:53:56","slug":"violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/","title":{"rendered":"Violences \u00e0 Khartoum et au Darfour : Des pays  quittent le Soudan"},"content":{"rendered":"<p>Plusieurs pays m\u00e8nent des op\u00e9rations de rapatriement de leurs ressortissants du Soudan o\u00f9 la guerre entre arm\u00e9e et paramilitaires fait rage depuis plus d&rsquo;une semaine.<br \/>\nLes violences, principalement \u00e0 Khartoum et au Darfour (ouest) ont fait selon l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS) plus de 420 morts et 3.700 bless\u00e9s.<\/p><div id=\"publi-1755414597\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>&#8211; Pays de l&rsquo;UE &#8211;<\/p>\n<p>Plus de mille ressortissants de l&rsquo;Union europ\u00e9enne (UE) ont \u00e9t\u00e9 \u00e9vacu\u00e9s du Soudan lors d&rsquo;une \u00ab\u00a0op\u00e9ration complexe mais (&#8230;) couronn\u00e9e de succ\u00e8s\u00a0\u00bb, a annonc\u00e9 lundi le chef de sa diplomatie Josep Borrell.<br \/>\nEn plus de l&rsquo;UE, qui a une d\u00e9l\u00e9gation \u00e0 Khartoum, sept pays membres (France, Allemagne, Italie, Espagne, Pays-Bas, Gr\u00e8ce et R\u00e9publique Tch\u00e8que) sont repr\u00e9sent\u00e9s dans la capitale. Quelque 1.500 ressortissants europ\u00e9ens vivent dans le pays, selon un responsable europ\u00e9en contact\u00e9 par l&rsquo;AFP vendredi.<br \/>\nLa France a \u00e9vacu\u00e9 pr\u00e8s de 400 ressortissants fran\u00e7ais et de multiples nationalit\u00e9s, en assurant depuis dimanche plusieurs rotations a\u00e9riennes entre Khartoum et Djibouti, a indiqu\u00e9 lundi la diplomatie fran\u00e7aise.<br \/>\nUne \u00ab\u00a0poign\u00e9e\u00a0\u00bb de ressortissants des Pays-Bas ont \u00e9t\u00e9 \u00e9vacu\u00e9s \u00e0 bord d&rsquo;un avion fran\u00e7ais, tandis qu&rsquo;un autre groupe de N\u00e9erlandais a quitt\u00e9 Khartoum par la route dans un convoi de l&rsquo;ONU, a d\u00e9clar\u00e9 la diplomatie n\u00e9erlandaise.<br \/>\n\u00ab\u00a0Avec l&rsquo;assistance de la France\u00a0\u00bb, la Gr\u00e8ce a annonc\u00e9 avoir \u00e9vacu\u00e9 dimanche un premier groupe de ses ressortissants, dont deux bless\u00e9s, vers Djibouti.<br \/>\nDimanche, les autorit\u00e9s italiennes ont dit avoir \u00e9vacu\u00e9 tous les Italiens qui \u00ab\u00a0avaient demand\u00e9 \u00e0 partir\u00a0\u00bb et des \u00ab\u00a0citoyens \u00e9trangers\u00a0\u00bb, soit \u00ab\u00a0environ 200 personnes\u00a0\u00bb.<br \/>\nL&rsquo;Allemagne a rapatri\u00e9 depuis dimanche plus de 300 personnes &#8211;dont des ressortissants d&rsquo;autres pays&#8211; par trois avions, le dernier ayant atterri dans la nuit de dimanche \u00e0 lundi en Jordanie, a indiqu\u00e9 \u00e0 l&rsquo;AFP un porte-parole du Commandement des op\u00e9rations de l&rsquo;arm\u00e9e allemande.<br \/>\nUn avion militaire espagnol avec \u00ab\u00a0une centaine de passagers\u00a0\u00bb &#8211;dont une trentaine d&rsquo;Espagnols&#8211; est parti dimanche pour Djibouti, selon Madrid.<br \/>\nLa Su\u00e8de a envoy\u00e9 environ 150 soldats pour \u00e9vacuer ses diplomates et ressortissants, selon son minist\u00e8re de la D\u00e9fense, et la Norv\u00e8ge a \u00e9galement annonc\u00e9 l&rsquo;\u00e9vacuation de ses diplomates.<\/p>\n<p>&#8211; Royaume-Uni, Irlande, Suisse &#8211;<br \/>\nLe Premier ministre britannique Rishi Sunak a annonc\u00e9 l&rsquo;\u00e9vacuation du personnel diplomatique du Royaume-Uni et de leurs familles.<br \/>\n\u00ab\u00a0Les forces arm\u00e9es britanniques ont proc\u00e9d\u00e9 \u00e0 une \u00e9vacuation complexe et rapide dans un contexte d&rsquo;escalade de la violence et de menaces \u00e0 l&rsquo;encontre du personnel de l&rsquo;ambassade\u00a0\u00bb, a tweet\u00e9 M. Sunak.<br \/>\nL&rsquo;Irlande a indiqu\u00e9 de son c\u00f4t\u00e9 avoir entam\u00e9 le \u00ab\u00a0processus d&rsquo;\u00e9vacuation\u00a0\u00bb de ses ressortissants et les personnes \u00e0 leur charge.<br \/>\nLa Suisse a, elle, annonc\u00e9 lundi avoir ferm\u00e9 son ambassade et \u00e9vacu\u00e9 son personnel.<\/p>\n<p>&#8211; Etats-Unis &#8211;<br \/>\nLe pr\u00e9sident am\u00e9ricain Joe Biden a annonc\u00e9 samedi soir tard que l&rsquo;arm\u00e9e avait \u00ab\u00a0men\u00e9 une op\u00e9ration pour extraire le personnel du gouvernement am\u00e9ricain de Khartoum\u00a0\u00bb.<br \/>\nQuelque 100 soldats des op\u00e9rations sp\u00e9ciales am\u00e9ricaines ont particip\u00e9 \u00e0 l&rsquo;\u00e9vacuation d&rsquo;un \u00ab\u00a0peu moins d&rsquo;une centaine\u00a0\u00bb de personnes, dont plusieurs diplomates \u00e9trangers, au moyen d&rsquo;une op\u00e9ration h\u00e9liport\u00e9e, selon le d\u00e9partement d&rsquo;Etat. Une \u00e9vacuation de plusieurs centaines d&rsquo;autres ressortissants am\u00e9ricains n&rsquo;est pas pr\u00e9vue \u00ab\u00a0pour le moment\u00a0\u00bb.<\/p>\n<p>&#8211; Pays arabes &#8211;<br \/>\nL&rsquo;Arabie saoudite a \u00e9vacu\u00e9 samedi 91 Saoudiens ainsi qu&rsquo;une soixantaine de ressortissants de 12 autres pays.<br \/>\nLa Jordanie a d\u00e9clar\u00e9 samedi avoir commenc\u00e9 l&rsquo;\u00e9vacuation d&rsquo;environ 300 Jordaniens.<br \/>\nL&rsquo;Irak a pour sa part annonc\u00e9 dimanche l&rsquo;\u00e9vacuation de 14 Irakiens de Khartoum \u00ab\u00a0vers un site s\u00e9curis\u00e9 de Port Soudan\u00a0\u00bb, assurant que les efforts se poursuivent pour \u00e9vacuer ceux qui restent.<br \/>\nLa veille, Bagdad avait annonc\u00e9 que \u00ab\u00a0l&rsquo;\u00e9quipe diplomatique irakienne avait \u00e9t\u00e9 \u00e9vacu\u00e9e\u00a0\u00bb de l&rsquo;ambassade.<br \/>\nLe Liban a d\u00e9clar\u00e9 que 60 de ses ressortissants avaient quitt\u00e9 Khartoum par la route et qu&rsquo;ils \u00e9taient \u00ab\u00a0en s\u00e9curit\u00e9\u00a0\u00bb.<br \/>\nL&rsquo;ambassade de Tunisie \u00e0 Khartoum a indiqu\u00e9 dimanche que l&rsquo;op\u00e9ration d&rsquo;\u00e9vacuation des membres de la communaut\u00e9 tunisienne au Soudan commencera lundi. Pays voisin du Soudan, la Libye a annonc\u00e9 l&rsquo;\u00e9vacuation de 83 Libyens de Khartoum vers Port-Soudan.<\/p>\n<p>&#8211; Turquie &#8211;<br \/>\nAnkara a annonc\u00e9 qu&rsquo;elle \u00e9vacuerait ses \u00ab\u00a0ressortissants se trouvant dans les zones de conflit par la voie terrestre et en passant par un pays tiers\u00a0\u00bb. L&rsquo;\u00e9vacuation des quelque 600 ressortissants a commenc\u00e9 dimanche de Khartoum et de Wad Madani, \u00e0 200 kilom\u00e8tres au sud.<br \/>\nMais l&rsquo;\u00e9vacuation du quartier de Kafouri, dans le nord de Khartoum, a \u00e9t\u00e9 report\u00e9e \u00ab\u00a0jusqu&rsquo;\u00e0 nouvel ordre\u00a0\u00bb \u00e0 cause d&rsquo;une explosion dimanche pr\u00e8s d&rsquo;un lieu de rassemblement, selon l&rsquo;ambassade de Turquie \u00e0 Khartoum.<\/p>\n<p>&#8211; Cor\u00e9e du Sud, Japon, Chine, Indon\u00e9sie, Inde &#8211;<br \/>\nD&rsquo;autres pays se pr\u00e9parent \u00e0 \u00e9vacuer leurs ressortissants, notamment la Cor\u00e9e du Sud et le Japon, en d\u00e9ployant des forces dans des pays voisins.<br \/>\nEn Indon\u00e9sie, le gouvernement \u00ab\u00a0prend toutes les mesures n\u00e9cessaires pour \u00e9vacuer les citoyens indon\u00e9siens du Soudan\u00a0\u00bb, a d\u00e9clar\u00e9 dimanche \u00e0 l&rsquo;AFP le minist\u00e8re des Affaires \u00e9trang\u00e8res.<br \/>\nL&rsquo;Inde a indiqu\u00e9 travailler \u00ab\u00a0en \u00e9troite collaboration avec divers partenaires pour assurer le d\u00e9placement en toute s\u00e9curit\u00e9 des Indiens bloqu\u00e9s au Soudan et qui souhaiteraient \u00eatre \u00e9vacu\u00e9s\u00a0\u00bb.<br \/>\nL&rsquo;arm\u00e9e soudanaise a par ailleurs d\u00e9clar\u00e9 qu&rsquo;elle coordonnait les efforts visant \u00e0 \u00e9vacuer des diplomates chinois.<\/p>\n<div id=\"publi-609485061\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Plusieurs pays m\u00e8nent des op\u00e9rations de rapatriement de leurs ressortissants du Soudan o\u00f9 la guerre entre arm\u00e9e et paramilitaires fait rage depuis plus d&rsquo;une semaine. Les violences, principalement \u00e0 Khartoum et au Darfour (ouest) ont fait selon l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS) plus de 420 morts et 3.700 bless\u00e9s. &#8211; Pays de l&rsquo;UE &#8211; Plus de mille ressortissants de l&rsquo;Union europ\u00e9enne (UE) ont \u00e9t\u00e9 \u00e9vacu\u00e9s du Soudan lors d&rsquo;une \u00ab\u00a0op\u00e9ration complexe mais (&#8230;) couronn\u00e9e de succ\u00e8s\u00a0\u00bb, a annonc\u00e9 lundi le chef de sa diplomatie Josep Borrell. En plus de l&rsquo;UE, qui a une d\u00e9l\u00e9gation \u00e0 Khartoum, sept pays membres (France, Allemagne, Italie, Espagne, Pays-Bas, Gr\u00e8ce et R\u00e9publique Tch\u00e8que) sont repr\u00e9sent\u00e9s dans la capitale. Quelque 1.500 ressortissants europ\u00e9ens vivent dans le pays, selon un responsable europ\u00e9en contact\u00e9 par l&rsquo;AFP vendredi. La France a \u00e9vacu\u00e9 pr\u00e8s de 400 ressortissants fran\u00e7ais et de multiples nationalit\u00e9s, en assurant depuis dimanche plusieurs rotations a\u00e9riennes entre Khartoum et Djibouti, a indiqu\u00e9 lundi la diplomatie fran\u00e7aise. Une \u00ab\u00a0poign\u00e9e\u00a0\u00bb de ressortissants des Pays-Bas ont \u00e9t\u00e9 \u00e9vacu\u00e9s \u00e0 bord d&rsquo;un avion fran\u00e7ais, tandis qu&rsquo;un autre groupe de N\u00e9erlandais a quitt\u00e9 Khartoum par la route dans un convoi de l&rsquo;ONU, a d\u00e9clar\u00e9 la diplomatie n\u00e9erlandaise. \u00ab\u00a0Avec l&rsquo;assistance de la France\u00a0\u00bb, la Gr\u00e8ce a annonc\u00e9 avoir \u00e9vacu\u00e9 dimanche un premier groupe de ses ressortissants, dont deux bless\u00e9s, vers Djibouti. Dimanche, les autorit\u00e9s italiennes ont dit avoir \u00e9vacu\u00e9 tous les Italiens qui \u00ab\u00a0avaient demand\u00e9 \u00e0 partir\u00a0\u00bb et des \u00ab\u00a0citoyens \u00e9trangers\u00a0\u00bb, soit \u00ab\u00a0environ 200 personnes\u00a0\u00bb. L&rsquo;Allemagne a rapatri\u00e9 depuis dimanche plus de 300 personnes &#8211;dont des ressortissants d&rsquo;autres pays&#8211; par trois avions, le dernier ayant atterri dans la nuit de dimanche \u00e0 lundi en Jordanie, a indiqu\u00e9 \u00e0 l&rsquo;AFP un porte-parole du Commandement des op\u00e9rations de l&rsquo;arm\u00e9e allemande. Un avion militaire espagnol avec \u00ab\u00a0une centaine de passagers\u00a0\u00bb &#8211;dont une trentaine d&rsquo;Espagnols&#8211; est parti dimanche pour Djibouti, selon Madrid. La Su\u00e8de a envoy\u00e9 environ 150 soldats pour \u00e9vacuer ses diplomates et ressortissants, selon son minist\u00e8re de la D\u00e9fense, et la Norv\u00e8ge a \u00e9galement annonc\u00e9 l&rsquo;\u00e9vacuation de ses diplomates. &#8211; Royaume-Uni, Irlande, Suisse &#8211; Le Premier ministre britannique Rishi Sunak a annonc\u00e9 l&rsquo;\u00e9vacuation du personnel diplomatique du Royaume-Uni et de leurs familles. \u00ab\u00a0Les forces arm\u00e9es britanniques ont proc\u00e9d\u00e9 \u00e0 une \u00e9vacuation complexe et rapide dans un contexte d&rsquo;escalade de la violence et de menaces \u00e0 l&rsquo;encontre du personnel de l&rsquo;ambassade\u00a0\u00bb, a tweet\u00e9 M. Sunak. L&rsquo;Irlande a indiqu\u00e9 de son c\u00f4t\u00e9 avoir entam\u00e9 le \u00ab\u00a0processus d&rsquo;\u00e9vacuation\u00a0\u00bb de ses ressortissants et les personnes \u00e0 leur charge. La Suisse a, elle, annonc\u00e9 lundi avoir ferm\u00e9 son ambassade et \u00e9vacu\u00e9 son personnel. &#8211; Etats-Unis &#8211; Le pr\u00e9sident am\u00e9ricain Joe Biden a annonc\u00e9 samedi soir tard que l&rsquo;arm\u00e9e avait \u00ab\u00a0men\u00e9 une op\u00e9ration pour extraire le personnel du gouvernement am\u00e9ricain de Khartoum\u00a0\u00bb. Quelque 100 soldats des op\u00e9rations sp\u00e9ciales am\u00e9ricaines ont particip\u00e9 \u00e0 l&rsquo;\u00e9vacuation d&rsquo;un \u00ab\u00a0peu moins d&rsquo;une centaine\u00a0\u00bb de personnes, dont plusieurs diplomates \u00e9trangers, au moyen d&rsquo;une op\u00e9ration h\u00e9liport\u00e9e, selon le d\u00e9partement d&rsquo;Etat. Une \u00e9vacuation de plusieurs centaines d&rsquo;autres ressortissants am\u00e9ricains n&rsquo;est pas pr\u00e9vue \u00ab\u00a0pour le moment\u00a0\u00bb. &#8211; Pays arabes &#8211; L&rsquo;Arabie saoudite a \u00e9vacu\u00e9 samedi 91 Saoudiens ainsi qu&rsquo;une soixantaine de ressortissants de 12 autres pays. La Jordanie a d\u00e9clar\u00e9 samedi avoir commenc\u00e9 l&rsquo;\u00e9vacuation d&rsquo;environ 300 Jordaniens. L&rsquo;Irak a pour sa part annonc\u00e9 dimanche l&rsquo;\u00e9vacuation de 14 Irakiens de Khartoum \u00ab\u00a0vers un site s\u00e9curis\u00e9 de Port Soudan\u00a0\u00bb, assurant que les efforts se poursuivent pour \u00e9vacuer ceux qui restent. La veille, Bagdad avait annonc\u00e9 que \u00ab\u00a0l&rsquo;\u00e9quipe diplomatique irakienne avait \u00e9t\u00e9 \u00e9vacu\u00e9e\u00a0\u00bb de l&rsquo;ambassade. Le Liban a d\u00e9clar\u00e9 que 60 de ses ressortissants avaient quitt\u00e9 Khartoum par la route et qu&rsquo;ils \u00e9taient \u00ab\u00a0en s\u00e9curit\u00e9\u00a0\u00bb. L&rsquo;ambassade de Tunisie \u00e0 Khartoum a indiqu\u00e9 dimanche que l&rsquo;op\u00e9ration d&rsquo;\u00e9vacuation des membres de la communaut\u00e9 tunisienne au Soudan commencera lundi. Pays voisin du Soudan, la Libye a annonc\u00e9 l&rsquo;\u00e9vacuation de 83 Libyens de Khartoum vers Port-Soudan. &#8211; Turquie &#8211; Ankara a annonc\u00e9 qu&rsquo;elle \u00e9vacuerait ses \u00ab\u00a0ressortissants se trouvant dans les zones de conflit par la voie terrestre et en passant par un pays tiers\u00a0\u00bb. L&rsquo;\u00e9vacuation des quelque 600 ressortissants a commenc\u00e9 dimanche de Khartoum et de Wad Madani, \u00e0 200 kilom\u00e8tres au sud. Mais l&rsquo;\u00e9vacuation du quartier de Kafouri, dans le nord de Khartoum, a \u00e9t\u00e9 report\u00e9e \u00ab\u00a0jusqu&rsquo;\u00e0 nouvel ordre\u00a0\u00bb \u00e0 cause d&rsquo;une explosion dimanche pr\u00e8s d&rsquo;un lieu de rassemblement, selon l&rsquo;ambassade de Turquie \u00e0 Khartoum. &#8211; Cor\u00e9e du Sud, Japon, Chine, Indon\u00e9sie, Inde &#8211; D&rsquo;autres pays se pr\u00e9parent \u00e0 \u00e9vacuer leurs ressortissants, notamment la Cor\u00e9e du Sud et le Japon, en d\u00e9ployant des forces dans des pays voisins. En Indon\u00e9sie, le gouvernement \u00ab\u00a0prend toutes les mesures n\u00e9cessaires pour \u00e9vacuer les citoyens indon\u00e9siens du Soudan\u00a0\u00bb, a d\u00e9clar\u00e9 dimanche \u00e0 l&rsquo;AFP le minist\u00e8re des Affaires \u00e9trang\u00e8res. L&rsquo;Inde a indiqu\u00e9 travailler \u00ab\u00a0en \u00e9troite collaboration avec divers partenaires pour assurer le d\u00e9placement en toute s\u00e9curit\u00e9 des Indiens bloqu\u00e9s au Soudan et qui souhaiteraient \u00eatre \u00e9vacu\u00e9s\u00a0\u00bb. L&rsquo;arm\u00e9e soudanaise a par ailleurs d\u00e9clar\u00e9 qu&rsquo;elle coordonnait les efforts visant \u00e0 \u00e9vacuer des diplomates chinois.<\/p>\n","protected":false},"author":1,"featured_media":20316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,550,372],"tags":[],"class_list":["post-20315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-afrique-monde","category-vedette","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"Plusieurs pays m\u00e8nent des op\u00e9rations de rapatriement de leurs ressortissants du Soudan o\u00f9 la guerre entre arm\u00e9e et paramilitaires fait rage depuis plus d&rsquo;une semaine. Les violences, principalement \u00e0 Khartoum et au Darfour (ouest) ont fait selon l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS) plus de 420 morts et 3.700 bless\u00e9s. &#8211; Pays de l&rsquo;UE &#8211; Plus de mille ressortissants de l&rsquo;Union europ\u00e9enne (UE) ont \u00e9t\u00e9 \u00e9vacu\u00e9s du Soudan lors d&rsquo;une \u00ab\u00a0op\u00e9ration complexe mais (&#8230;) couronn\u00e9e de succ\u00e8s\u00a0\u00bb, a annonc\u00e9 lundi le chef de sa diplomatie Josep Borrell. En plus de l&rsquo;UE, qui a une d\u00e9l\u00e9gation \u00e0 Khartoum, sept pays membres (France, Allemagne, Italie, Espagne, Pays-Bas, Gr\u00e8ce et R\u00e9publique Tch\u00e8que) sont repr\u00e9sent\u00e9s dans la capitale. Quelque 1.500 ressortissants europ\u00e9ens vivent dans le pays, selon un responsable europ\u00e9en contact\u00e9 par l&rsquo;AFP vendredi. La France a \u00e9vacu\u00e9 pr\u00e8s de 400 ressortissants fran\u00e7ais et de multiples nationalit\u00e9s, en assurant depuis dimanche plusieurs rotations a\u00e9riennes entre Khartoum et Djibouti, a indiqu\u00e9 lundi la diplomatie fran\u00e7aise. Une \u00ab\u00a0poign\u00e9e\u00a0\u00bb de ressortissants des Pays-Bas ont \u00e9t\u00e9 \u00e9vacu\u00e9s \u00e0 bord d&rsquo;un avion fran\u00e7ais, tandis qu&rsquo;un autre groupe de N\u00e9erlandais a quitt\u00e9 Khartoum par la route dans un convoi de l&rsquo;ONU, a d\u00e9clar\u00e9 la diplomatie n\u00e9erlandaise. \u00ab\u00a0Avec l&rsquo;assistance de la France\u00a0\u00bb, la Gr\u00e8ce a annonc\u00e9 avoir \u00e9vacu\u00e9 dimanche un premier groupe de ses ressortissants, dont deux bless\u00e9s, vers Djibouti. Dimanche, les autorit\u00e9s italiennes ont dit avoir \u00e9vacu\u00e9 tous les Italiens qui \u00ab\u00a0avaient demand\u00e9 \u00e0 partir\u00a0\u00bb et des \u00ab\u00a0citoyens \u00e9trangers\u00a0\u00bb, soit \u00ab\u00a0environ 200 personnes\u00a0\u00bb. L&rsquo;Allemagne a rapatri\u00e9 depuis dimanche plus de 300 personnes &#8211;dont des ressortissants d&rsquo;autres pays&#8211; par trois avions, le dernier ayant atterri dans la nuit de dimanche \u00e0 lundi en Jordanie, a indiqu\u00e9 \u00e0 l&rsquo;AFP un porte-parole du Commandement des op\u00e9rations de l&rsquo;arm\u00e9e allemande. Un avion militaire espagnol avec \u00ab\u00a0une centaine de passagers\u00a0\u00bb &#8211;dont une trentaine d&rsquo;Espagnols&#8211; est parti dimanche pour Djibouti, selon Madrid. La Su\u00e8de a envoy\u00e9 environ 150 soldats pour \u00e9vacuer ses diplomates et ressortissants, selon son minist\u00e8re de la D\u00e9fense, et la Norv\u00e8ge a \u00e9galement annonc\u00e9 l&rsquo;\u00e9vacuation de ses diplomates. &#8211; Royaume-Uni, Irlande, Suisse &#8211; Le Premier ministre britannique Rishi Sunak a annonc\u00e9 l&rsquo;\u00e9vacuation du personnel diplomatique du Royaume-Uni et de leurs familles. \u00ab\u00a0Les forces arm\u00e9es britanniques ont proc\u00e9d\u00e9 \u00e0 une \u00e9vacuation complexe et rapide dans un contexte d&rsquo;escalade de la violence et de menaces \u00e0 l&rsquo;encontre du personnel de l&rsquo;ambassade\u00a0\u00bb, a tweet\u00e9 M. Sunak. L&rsquo;Irlande a indiqu\u00e9 de son c\u00f4t\u00e9 avoir entam\u00e9 le \u00ab\u00a0processus d&rsquo;\u00e9vacuation\u00a0\u00bb de ses ressortissants et les personnes \u00e0 leur charge. La Suisse a, elle, annonc\u00e9 lundi avoir ferm\u00e9 son ambassade et \u00e9vacu\u00e9 son personnel. &#8211; Etats-Unis &#8211; Le pr\u00e9sident am\u00e9ricain Joe Biden a annonc\u00e9 samedi soir tard que l&rsquo;arm\u00e9e avait \u00ab\u00a0men\u00e9 une op\u00e9ration pour extraire le personnel du gouvernement am\u00e9ricain de Khartoum\u00a0\u00bb. Quelque 100 soldats des op\u00e9rations sp\u00e9ciales am\u00e9ricaines ont particip\u00e9 \u00e0 l&rsquo;\u00e9vacuation d&rsquo;un \u00ab\u00a0peu moins d&rsquo;une centaine\u00a0\u00bb de personnes, dont plusieurs diplomates \u00e9trangers, au moyen d&rsquo;une op\u00e9ration h\u00e9liport\u00e9e, selon le d\u00e9partement d&rsquo;Etat. Une \u00e9vacuation de plusieurs centaines d&rsquo;autres ressortissants am\u00e9ricains n&rsquo;est pas pr\u00e9vue \u00ab\u00a0pour le moment\u00a0\u00bb. &#8211; Pays arabes &#8211; L&rsquo;Arabie saoudite a \u00e9vacu\u00e9 samedi 91 Saoudiens ainsi qu&rsquo;une soixantaine de ressortissants de 12 autres pays. La Jordanie a d\u00e9clar\u00e9 samedi avoir commenc\u00e9 l&rsquo;\u00e9vacuation d&rsquo;environ 300 Jordaniens. L&rsquo;Irak a pour sa part annonc\u00e9 dimanche l&rsquo;\u00e9vacuation de 14 Irakiens de Khartoum \u00ab\u00a0vers un site s\u00e9curis\u00e9 de Port Soudan\u00a0\u00bb, assurant que les efforts se poursuivent pour \u00e9vacuer ceux qui restent. La veille, Bagdad avait annonc\u00e9 que \u00ab\u00a0l&rsquo;\u00e9quipe diplomatique irakienne avait \u00e9t\u00e9 \u00e9vacu\u00e9e\u00a0\u00bb de l&rsquo;ambassade. Le Liban a d\u00e9clar\u00e9 que 60 de ses ressortissants avaient quitt\u00e9 Khartoum par la route et qu&rsquo;ils \u00e9taient \u00ab\u00a0en s\u00e9curit\u00e9\u00a0\u00bb. L&rsquo;ambassade de Tunisie \u00e0 Khartoum a indiqu\u00e9 dimanche que l&rsquo;op\u00e9ration d&rsquo;\u00e9vacuation des membres de la communaut\u00e9 tunisienne au Soudan commencera lundi. Pays voisin du Soudan, la Libye a annonc\u00e9 l&rsquo;\u00e9vacuation de 83 Libyens de Khartoum vers Port-Soudan. &#8211; Turquie &#8211; Ankara a annonc\u00e9 qu&rsquo;elle \u00e9vacuerait ses \u00ab\u00a0ressortissants se trouvant dans les zones de conflit par la voie terrestre et en passant par un pays tiers\u00a0\u00bb. L&rsquo;\u00e9vacuation des quelque 600 ressortissants a commenc\u00e9 dimanche de Khartoum et de Wad Madani, \u00e0 200 kilom\u00e8tres au sud. Mais l&rsquo;\u00e9vacuation du quartier de Kafouri, dans le nord de Khartoum, a \u00e9t\u00e9 report\u00e9e \u00ab\u00a0jusqu&rsquo;\u00e0 nouvel ordre\u00a0\u00bb \u00e0 cause d&rsquo;une explosion dimanche pr\u00e8s d&rsquo;un lieu de rassemblement, selon l&rsquo;ambassade de Turquie \u00e0 Khartoum. &#8211; Cor\u00e9e du Sud, Japon, Chine, Indon\u00e9sie, Inde &#8211; D&rsquo;autres pays se pr\u00e9parent \u00e0 \u00e9vacuer leurs ressortissants, notamment la Cor\u00e9e du Sud et le Japon, en d\u00e9ployant des forces dans des pays voisins. En Indon\u00e9sie, le gouvernement \u00ab\u00a0prend toutes les mesures n\u00e9cessaires pour \u00e9vacuer les citoyens indon\u00e9siens du Soudan\u00a0\u00bb, a d\u00e9clar\u00e9 dimanche \u00e0 l&rsquo;AFP le minist\u00e8re des Affaires \u00e9trang\u00e8res. L&rsquo;Inde a indiqu\u00e9 travailler \u00ab\u00a0en \u00e9troite collaboration avec divers partenaires pour assurer le d\u00e9placement en toute s\u00e9curit\u00e9 des Indiens bloqu\u00e9s au Soudan et qui souhaiteraient \u00eatre \u00e9vacu\u00e9s\u00a0\u00bb. L&rsquo;arm\u00e9e soudanaise a par ailleurs d\u00e9clar\u00e9 qu&rsquo;elle coordonnait les efforts visant \u00e0 \u00e9vacuer des diplomates chinois.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-24T12:53:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan\",\"datePublished\":\"2023-04-24T12:53:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/\"},\"wordCount\":880,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/EVACUE-SOUDAN.jpeg\",\"articleSection\":[\"ACTUALIT\u00c9S\",\"AFRIQUE &amp; MONDE\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/\",\"name\":\"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/EVACUE-SOUDAN.jpeg\",\"datePublished\":\"2023-04-24T12:53:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/EVACUE-SOUDAN.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/EVACUE-SOUDAN.jpeg\",\"width\":612,\"height\":298},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/04\\\/24\\\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\\\/\\\/www.public.sn\"],\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/admin7324\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/","og_locale":"fr_FR","og_type":"article","og_title":"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan - LE PUBLIC","og_description":"Plusieurs pays m\u00e8nent des op\u00e9rations de rapatriement de leurs ressortissants du Soudan o\u00f9 la guerre entre arm\u00e9e et paramilitaires fait rage depuis plus d&rsquo;une semaine. Les violences, principalement \u00e0 Khartoum et au Darfour (ouest) ont fait selon l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS) plus de 420 morts et 3.700 bless\u00e9s. &#8211; Pays de l&rsquo;UE &#8211; Plus de mille ressortissants de l&rsquo;Union europ\u00e9enne (UE) ont \u00e9t\u00e9 \u00e9vacu\u00e9s du Soudan lors d&rsquo;une \u00ab\u00a0op\u00e9ration complexe mais (&#8230;) couronn\u00e9e de succ\u00e8s\u00a0\u00bb, a annonc\u00e9 lundi le chef de sa diplomatie Josep Borrell. En plus de l&rsquo;UE, qui a une d\u00e9l\u00e9gation \u00e0 Khartoum, sept pays membres (France, Allemagne, Italie, Espagne, Pays-Bas, Gr\u00e8ce et R\u00e9publique Tch\u00e8que) sont repr\u00e9sent\u00e9s dans la capitale. Quelque 1.500 ressortissants europ\u00e9ens vivent dans le pays, selon un responsable europ\u00e9en contact\u00e9 par l&rsquo;AFP vendredi. La France a \u00e9vacu\u00e9 pr\u00e8s de 400 ressortissants fran\u00e7ais et de multiples nationalit\u00e9s, en assurant depuis dimanche plusieurs rotations a\u00e9riennes entre Khartoum et Djibouti, a indiqu\u00e9 lundi la diplomatie fran\u00e7aise. Une \u00ab\u00a0poign\u00e9e\u00a0\u00bb de ressortissants des Pays-Bas ont \u00e9t\u00e9 \u00e9vacu\u00e9s \u00e0 bord d&rsquo;un avion fran\u00e7ais, tandis qu&rsquo;un autre groupe de N\u00e9erlandais a quitt\u00e9 Khartoum par la route dans un convoi de l&rsquo;ONU, a d\u00e9clar\u00e9 la diplomatie n\u00e9erlandaise. \u00ab\u00a0Avec l&rsquo;assistance de la France\u00a0\u00bb, la Gr\u00e8ce a annonc\u00e9 avoir \u00e9vacu\u00e9 dimanche un premier groupe de ses ressortissants, dont deux bless\u00e9s, vers Djibouti. Dimanche, les autorit\u00e9s italiennes ont dit avoir \u00e9vacu\u00e9 tous les Italiens qui \u00ab\u00a0avaient demand\u00e9 \u00e0 partir\u00a0\u00bb et des \u00ab\u00a0citoyens \u00e9trangers\u00a0\u00bb, soit \u00ab\u00a0environ 200 personnes\u00a0\u00bb. L&rsquo;Allemagne a rapatri\u00e9 depuis dimanche plus de 300 personnes &#8211;dont des ressortissants d&rsquo;autres pays&#8211; par trois avions, le dernier ayant atterri dans la nuit de dimanche \u00e0 lundi en Jordanie, a indiqu\u00e9 \u00e0 l&rsquo;AFP un porte-parole du Commandement des op\u00e9rations de l&rsquo;arm\u00e9e allemande. Un avion militaire espagnol avec \u00ab\u00a0une centaine de passagers\u00a0\u00bb &#8211;dont une trentaine d&rsquo;Espagnols&#8211; est parti dimanche pour Djibouti, selon Madrid. La Su\u00e8de a envoy\u00e9 environ 150 soldats pour \u00e9vacuer ses diplomates et ressortissants, selon son minist\u00e8re de la D\u00e9fense, et la Norv\u00e8ge a \u00e9galement annonc\u00e9 l&rsquo;\u00e9vacuation de ses diplomates. &#8211; Royaume-Uni, Irlande, Suisse &#8211; Le Premier ministre britannique Rishi Sunak a annonc\u00e9 l&rsquo;\u00e9vacuation du personnel diplomatique du Royaume-Uni et de leurs familles. \u00ab\u00a0Les forces arm\u00e9es britanniques ont proc\u00e9d\u00e9 \u00e0 une \u00e9vacuation complexe et rapide dans un contexte d&rsquo;escalade de la violence et de menaces \u00e0 l&rsquo;encontre du personnel de l&rsquo;ambassade\u00a0\u00bb, a tweet\u00e9 M. Sunak. L&rsquo;Irlande a indiqu\u00e9 de son c\u00f4t\u00e9 avoir entam\u00e9 le \u00ab\u00a0processus d&rsquo;\u00e9vacuation\u00a0\u00bb de ses ressortissants et les personnes \u00e0 leur charge. La Suisse a, elle, annonc\u00e9 lundi avoir ferm\u00e9 son ambassade et \u00e9vacu\u00e9 son personnel. &#8211; Etats-Unis &#8211; Le pr\u00e9sident am\u00e9ricain Joe Biden a annonc\u00e9 samedi soir tard que l&rsquo;arm\u00e9e avait \u00ab\u00a0men\u00e9 une op\u00e9ration pour extraire le personnel du gouvernement am\u00e9ricain de Khartoum\u00a0\u00bb. Quelque 100 soldats des op\u00e9rations sp\u00e9ciales am\u00e9ricaines ont particip\u00e9 \u00e0 l&rsquo;\u00e9vacuation d&rsquo;un \u00ab\u00a0peu moins d&rsquo;une centaine\u00a0\u00bb de personnes, dont plusieurs diplomates \u00e9trangers, au moyen d&rsquo;une op\u00e9ration h\u00e9liport\u00e9e, selon le d\u00e9partement d&rsquo;Etat. Une \u00e9vacuation de plusieurs centaines d&rsquo;autres ressortissants am\u00e9ricains n&rsquo;est pas pr\u00e9vue \u00ab\u00a0pour le moment\u00a0\u00bb. &#8211; Pays arabes &#8211; L&rsquo;Arabie saoudite a \u00e9vacu\u00e9 samedi 91 Saoudiens ainsi qu&rsquo;une soixantaine de ressortissants de 12 autres pays. La Jordanie a d\u00e9clar\u00e9 samedi avoir commenc\u00e9 l&rsquo;\u00e9vacuation d&rsquo;environ 300 Jordaniens. L&rsquo;Irak a pour sa part annonc\u00e9 dimanche l&rsquo;\u00e9vacuation de 14 Irakiens de Khartoum \u00ab\u00a0vers un site s\u00e9curis\u00e9 de Port Soudan\u00a0\u00bb, assurant que les efforts se poursuivent pour \u00e9vacuer ceux qui restent. La veille, Bagdad avait annonc\u00e9 que \u00ab\u00a0l&rsquo;\u00e9quipe diplomatique irakienne avait \u00e9t\u00e9 \u00e9vacu\u00e9e\u00a0\u00bb de l&rsquo;ambassade. Le Liban a d\u00e9clar\u00e9 que 60 de ses ressortissants avaient quitt\u00e9 Khartoum par la route et qu&rsquo;ils \u00e9taient \u00ab\u00a0en s\u00e9curit\u00e9\u00a0\u00bb. L&rsquo;ambassade de Tunisie \u00e0 Khartoum a indiqu\u00e9 dimanche que l&rsquo;op\u00e9ration d&rsquo;\u00e9vacuation des membres de la communaut\u00e9 tunisienne au Soudan commencera lundi. Pays voisin du Soudan, la Libye a annonc\u00e9 l&rsquo;\u00e9vacuation de 83 Libyens de Khartoum vers Port-Soudan. &#8211; Turquie &#8211; Ankara a annonc\u00e9 qu&rsquo;elle \u00e9vacuerait ses \u00ab\u00a0ressortissants se trouvant dans les zones de conflit par la voie terrestre et en passant par un pays tiers\u00a0\u00bb. L&rsquo;\u00e9vacuation des quelque 600 ressortissants a commenc\u00e9 dimanche de Khartoum et de Wad Madani, \u00e0 200 kilom\u00e8tres au sud. Mais l&rsquo;\u00e9vacuation du quartier de Kafouri, dans le nord de Khartoum, a \u00e9t\u00e9 report\u00e9e \u00ab\u00a0jusqu&rsquo;\u00e0 nouvel ordre\u00a0\u00bb \u00e0 cause d&rsquo;une explosion dimanche pr\u00e8s d&rsquo;un lieu de rassemblement, selon l&rsquo;ambassade de Turquie \u00e0 Khartoum. &#8211; Cor\u00e9e du Sud, Japon, Chine, Indon\u00e9sie, Inde &#8211; D&rsquo;autres pays se pr\u00e9parent \u00e0 \u00e9vacuer leurs ressortissants, notamment la Cor\u00e9e du Sud et le Japon, en d\u00e9ployant des forces dans des pays voisins. En Indon\u00e9sie, le gouvernement \u00ab\u00a0prend toutes les mesures n\u00e9cessaires pour \u00e9vacuer les citoyens indon\u00e9siens du Soudan\u00a0\u00bb, a d\u00e9clar\u00e9 dimanche \u00e0 l&rsquo;AFP le minist\u00e8re des Affaires \u00e9trang\u00e8res. L&rsquo;Inde a indiqu\u00e9 travailler \u00ab\u00a0en \u00e9troite collaboration avec divers partenaires pour assurer le d\u00e9placement en toute s\u00e9curit\u00e9 des Indiens bloqu\u00e9s au Soudan et qui souhaiteraient \u00eatre \u00e9vacu\u00e9s\u00a0\u00bb. L&rsquo;arm\u00e9e soudanaise a par ailleurs d\u00e9clar\u00e9 qu&rsquo;elle coordonnait les efforts visant \u00e0 \u00e9vacuer des diplomates chinois.","og_url":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/","og_site_name":"LE PUBLIC","article_published_time":"2023-04-24T12:53:56+00:00","og_image":[{"width":612,"height":298,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan","datePublished":"2023-04-24T12:53:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/"},"wordCount":880,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg","articleSection":["ACTUALIT\u00c9S","AFRIQUE &amp; MONDE","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/","url":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/","name":"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg","datePublished":"2023-04-24T12:53:56+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg","width":612,"height":298},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2023\/04\/24\/violences-a-khartoum-et-au-darfour-des-pays-quittent-le-soudan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"Violences \u00e0 Khartoum et au Darfour : Des pays quittent le Soudan"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/EVACUE-SOUDAN.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/20315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=20315"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/20315\/revisions"}],"predecessor-version":[{"id":20317,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/20315\/revisions\/20317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/20316"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=20315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=20315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=20315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}