{"id":24092,"date":"2023-06-22T08:59:27","date_gmt":"2023-06-22T08:59:27","guid":{"rendered":"https:\/\/www.public.sn\/?p=24092"},"modified":"2023-06-22T08:59:27","modified_gmt":"2023-06-22T08:59:27","slug":"la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/","title":{"rendered":"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une"},"content":{"rendered":"<p><strong>La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.<\/strong><\/p><div id=\"publi-4252932593\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>\u2018\u2019Le pr\u00e9sident d\u00e9voile sa candidature devant ses militants \u00e0 Paris\u2019\u2019 et pr\u00e9dit \u2018\u2019la victoire en 2024\u2019\u2019, selon Lib\u00e9ration qui ajoute : \u2018\u2019le chef de l\u2019Etat annonce une d\u00e9claration pour +bient\u00f4t+ et lance : +Nous allons faire face \u00e0 ceux qui veulent d\u00e9truire le S\u00e9n\u00e9gal+\u2019\u2019.<\/p>\n<p>\u2018\u2019Macky Sall, candidat ou non \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle !?, \u00c7a se pr\u00e9cise pour 2024\u2026\u2019\u2019, affiche \u00e0 la Une Le Soleil, soulignant que le pr\u00e9sident de la R\u00e9publique, en d\u00e9placement \u00e0 Paris, au sommet pour un nouveau pacte financier mondial, a \u2018\u2019\u00e9t\u00e9 accueilli par une ferveur militante exceptionnelle\u2019\u2019.<\/p>\n<p>Le journal souligne que \u2018\u2019devant la forte mobilisation de ses partisans d\u00e9cid\u00e9s \u00e0 redorer le blason de la coalition pr\u00e9sidentielle, Bennoo Bokk Yaakaar, dans l\u2019Hexagone, le Pr\u00e9sident Macky Sall a prononc\u00e9 des propos qui pourraient faire penser \u00e0 sa possible candidature en 2024\u2019\u2019.<\/p>\n<p>Devant ses militants, il a d\u00e9clar\u00e9 : \u2018\u2019Ce que je peux vous promettre, c\u2019est que gr\u00e2ce \u00e0 notre travail, nous nous maintiendrons au pouvoir avec la volont\u00e9 du peuple s\u00e9n\u00e9galais\u2019\u2019.<\/p>\n<p>\u2018\u2019Soyez \u00e0 l\u2019\u00e9coute de mon message. Restez unis et mobilis\u00e9s. De toute fa\u00e7on, je m\u2019adresserai au pays dans pas longtemps. Nous aurons beaucoup \u00e0 faire apr\u00e8s cette d\u00e9claration pour aller vers la marche du progr\u00e8s et vers la victoire de 2024. Soyez rassur\u00e9s, tout comme la coalition Benno bokk yaakaar\u2019\u2019, a lanc\u00e9 Macky Sall.<\/p>\n<p>\u2018\u2019Depuis 11 ans, nous avons travaill\u00e9 ensemble, pour imprimer des changements majeurs et marcher vers le progr\u00e8s et l\u2019\u00e9panouissement de nos compatriotes. \u00c7a, c\u2019est ce qui me motive, contrairement \u00e0 ceux qui veulent d\u00e9truire le S\u00e9n\u00e9gal. Nous ferons face et nous prot\u00e8gerons le S\u00e9n\u00e9gal et restaurerons la paix\u2019\u2019, a-t-il promis<\/p>\n<p>\u2018\u2019Macky l\u00e2che un morceau \u00e0 Paris\u2019\u2019, dit B\u00ebs Bi. \u2018\u2019Dans quelques jours, sauf nouvel agenda, le pr\u00e9sident de la R\u00e9publique va s\u2019adresser \u00e0 la Nation sur sa candidature ou non en 2024. Mais d\u00e9j\u00e0, \u00e0 Paris hier, face \u00e0 ses militants, il a annonc\u00e9 la couleur. C\u2019est presque une d\u00e9claration de candidature qui attend d\u2019\u00eatre formalis\u00e9e\u2019\u2019, \u00e9crit le journal.<\/p>\n<p>Pour L\u2019Info, \u2018\u2019 Mack Sall est \u00e0 un pas d\u2019une 3e candidature\u2019\u2019. Apr\u00e8s avoir soulign\u00e9 le 20 mars dernier \u00e0 l\u2019hebdomadaire fran\u00e7ais \u2018\u2019L\u2019Express\u2019\u2019 que \u2018\u2019la question juridique du 3e mandat \u00e9tait d\u00e9j\u00e0 r\u00e9gl\u00e9e, Macky Sall s\u2019est ouvert un boulevard avec le dialogue national qui laisse au Conseil Constitutionnel le soin de valider ou non sa candidature en 2024\u2019\u2019, \u00e9crit la publication.<\/p>\n<p>Macky Sall \u2018\u2019toujours dans le discours clair-obscur\u2019\u2019 appelle ses militants \u00e0 \u2018\u2019se mobiliser et \u00e0 travailler pour la victoire de 2024\u2019\u2019, dit Les Echos.<\/p>\n<p>Vox Populi, estime que \u2018\u2019de Paris, Macky Sall ajoute \u00e0 la confusion\u2019\u2019. \u2018\u2019Le pr\u00e9sident \u00e9vite le +je+ de clarification surfant plus sur le +nous+ de diversion\u2019\u2019, selon le quotiien.<\/p>\n<p>Pour WalfQuotidien, \u2018\u2019Macky Sall sera candidat \u00e0 sa propre succession en 2024. Il a fait l\u2019annonce, hier, \u00e0 la r\u00e9sidence de l\u2019ambassadeur du S\u00e9n\u00e9gal, \u00e0 Paris, au cours d\u2019une audience accord\u00e9e \u00e0 ses militants\u2019\u2019.<\/p>\n<p>Selon L\u2019As, \u2018\u2019Macky Sall jette le masque\u2019\u2019. \u2018\u2019En d\u00e9placement \u00e0 Paris, Macky Sall a annonc\u00e9 sa candidature \u00e0 la prochaine \u00e9lection pr\u00e9sidentielle devant ses militants venus en masse pour communier avec lui. Cette d\u00e9claration du pr\u00e9sident de la R\u00e9publique intervient dans un contexte o\u00f9 l\u2019on annonce que les participants au dialogue national ont valid\u00e9 la candidature de Karim Wade et Khalifa Sall \u00e0 la prochaine \u00e9lection pr\u00e9sidentielle\u2019\u2019, indique le journal.<\/p>\n<p><strong>APS<\/strong><\/p>\n<div id=\"publi-3739900373\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS. \u2018\u2019Le pr\u00e9sident d\u00e9voile sa candidature devant ses militants \u00e0 Paris\u2019\u2019 et pr\u00e9dit \u2018\u2019la victoire en 2024\u2019\u2019, selon Lib\u00e9ration qui ajoute : \u2018\u2019le chef de l\u2019Etat annonce une d\u00e9claration pour +bient\u00f4t+ et lance : +Nous allons faire face \u00e0 ceux qui veulent d\u00e9truire le S\u00e9n\u00e9gal+\u2019\u2019. \u2018\u2019Macky Sall, candidat ou non \u00e0 l\u2019\u00e9lection pr\u00e9sidentielle !?, \u00c7a se pr\u00e9cise pour 2024\u2026\u2019\u2019, affiche \u00e0 la Une Le Soleil, soulignant que le pr\u00e9sident de la R\u00e9publique, en d\u00e9placement \u00e0 Paris, au sommet pour un nouveau pacte financier mondial, a \u2018\u2019\u00e9t\u00e9 accueilli par une ferveur militante exceptionnelle\u2019\u2019. Le journal souligne que \u2018\u2019devant la forte mobilisation de ses partisans d\u00e9cid\u00e9s \u00e0 redorer le blason de la coalition pr\u00e9sidentielle, Bennoo Bokk Yaakaar, dans l\u2019Hexagone, le Pr\u00e9sident Macky Sall a prononc\u00e9 des propos qui pourraient faire penser \u00e0 sa possible candidature en 2024\u2019\u2019. Devant ses militants, il a d\u00e9clar\u00e9 : \u2018\u2019Ce que je peux vous promettre, c\u2019est que gr\u00e2ce \u00e0 notre travail, nous nous maintiendrons au pouvoir avec la volont\u00e9 du peuple s\u00e9n\u00e9galais\u2019\u2019. \u2018\u2019Soyez \u00e0 l\u2019\u00e9coute de mon message. Restez unis et mobilis\u00e9s. De toute fa\u00e7on, je m\u2019adresserai au pays dans pas longtemps. Nous aurons beaucoup \u00e0 faire apr\u00e8s cette d\u00e9claration pour aller vers la marche du progr\u00e8s et vers la victoire de 2024. Soyez rassur\u00e9s, tout comme la coalition Benno bokk yaakaar\u2019\u2019, a lanc\u00e9 Macky Sall. \u2018\u2019Depuis 11 ans, nous avons travaill\u00e9 ensemble, pour imprimer des changements majeurs et marcher vers le progr\u00e8s et l\u2019\u00e9panouissement de nos compatriotes. \u00c7a, c\u2019est ce qui me motive, contrairement \u00e0 ceux qui veulent d\u00e9truire le S\u00e9n\u00e9gal. Nous ferons face et nous prot\u00e8gerons le S\u00e9n\u00e9gal et restaurerons la paix\u2019\u2019, a-t-il promis \u2018\u2019Macky l\u00e2che un morceau \u00e0 Paris\u2019\u2019, dit B\u00ebs Bi. \u2018\u2019Dans quelques jours, sauf nouvel agenda, le pr\u00e9sident de la R\u00e9publique va s\u2019adresser \u00e0 la Nation sur sa candidature ou non en 2024. Mais d\u00e9j\u00e0, \u00e0 Paris hier, face \u00e0 ses militants, il a annonc\u00e9 la couleur. C\u2019est presque une d\u00e9claration de candidature qui attend d\u2019\u00eatre formalis\u00e9e\u2019\u2019, \u00e9crit le journal. Pour L\u2019Info, \u2018\u2019 Mack Sall est \u00e0 un pas d\u2019une 3e candidature\u2019\u2019. Apr\u00e8s avoir soulign\u00e9 le 20 mars dernier \u00e0 l\u2019hebdomadaire fran\u00e7ais \u2018\u2019L\u2019Express\u2019\u2019 que \u2018\u2019la question juridique du 3e mandat \u00e9tait d\u00e9j\u00e0 r\u00e9gl\u00e9e, Macky Sall s\u2019est ouvert un boulevard avec le dialogue national qui laisse au Conseil Constitutionnel le soin de valider ou non sa candidature en 2024\u2019\u2019, \u00e9crit la publication. Macky Sall \u2018\u2019toujours dans le discours clair-obscur\u2019\u2019 appelle ses militants \u00e0 \u2018\u2019se mobiliser et \u00e0 travailler pour la victoire de 2024\u2019\u2019, dit Les Echos. Vox Populi, estime que \u2018\u2019de Paris, Macky Sall ajoute \u00e0 la confusion\u2019\u2019. \u2018\u2019Le pr\u00e9sident \u00e9vite le +je+ de clarification surfant plus sur le +nous+ de diversion\u2019\u2019, selon le quotiien. Pour WalfQuotidien, \u2018\u2019Macky Sall sera candidat \u00e0 sa propre succession en 2024. Il a fait l\u2019annonce, hier, \u00e0 la r\u00e9sidence de l\u2019ambassadeur du S\u00e9n\u00e9gal, \u00e0 Paris, au cours d\u2019une audience accord\u00e9e \u00e0 ses militants\u2019\u2019. Selon L\u2019As, \u2018\u2019Macky Sall jette le masque\u2019\u2019. \u2018\u2019En d\u00e9placement \u00e0 Paris, Macky Sall a annonc\u00e9 sa candidature \u00e0 la prochaine \u00e9lection pr\u00e9sidentielle devant ses militants venus en masse pour communier avec lui. Cette d\u00e9claration du pr\u00e9sident de la R\u00e9publique intervient dans un contexte o\u00f9 l\u2019on annonce que les participants au dialogue national ont valid\u00e9 la candidature de Karim Wade et Khalifa Sall \u00e0 la prochaine \u00e9lection pr\u00e9sidentielle\u2019\u2019, indique le journal. APS<\/p>\n","protected":false},"author":1,"featured_media":19287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,844,1,372],"tags":[4215],"class_list":["post-24092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-revue-de-presse","category-non-classe","category-vedette","tag-presidentielle-de-2024","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une - LE PUBLIC<\/title>\n<meta name=\"description\" content=\"La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-22T08:59:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une\",\"datePublished\":\"2023-06-22T08:59:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/\"},\"wordCount\":630,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/discours-03-AVRIL-MACKY-SALL.webp\",\"keywords\":[\"Pr\u00e9sidentielle de 2024\"],\"articleSection\":[\"ACTUALIT\u00c9S\",\"REVUE DE PRESSE\",\"S\u00c9N\u00c9GAL\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/\",\"name\":\"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/discours-03-AVRIL-MACKY-SALL.webp\",\"datePublished\":\"2023-06-22T08:59:27+00:00\",\"description\":\"La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/discours-03-AVRIL-MACKY-SALL.webp\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/discours-03-AVRIL-MACKY-SALL.webp\",\"width\":1080,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/06\\\/22\\\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\\\/\\\/www.public.sn\"],\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/admin7324\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une - LE PUBLIC","description":"La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/","og_locale":"fr_FR","og_type":"article","og_title":"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une - LE PUBLIC","og_description":"La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.","og_url":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/","og_site_name":"LE PUBLIC","article_published_time":"2023-06-22T08:59:27+00:00","og_image":[{"width":1080,"height":725,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp","type":"image\/webp"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une","datePublished":"2023-06-22T08:59:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/"},"wordCount":630,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp","keywords":["Pr\u00e9sidentielle de 2024"],"articleSection":["ACTUALIT\u00c9S","REVUE DE PRESSE","S\u00c9N\u00c9GAL","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/","url":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/","name":"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp","datePublished":"2023-06-22T08:59:27+00:00","description":"La derni\u00e8re d\u00e9claration de Macky Sall aux allures d\u2019une annonce de candidature \u00e0 la pr\u00e9sidentielle de 2024 est largement comment\u00e9e par les quotidiens re\u00e7us jeudi \u00e0 l\u2019APS.","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp","width":1080,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2023\/06\/22\/la-nouvelle-declaration-de-macky-sall-au-sujet-de-la-presidentielle-de-2024-a-la-une\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"La nouvelle d\u00e9claration de Macky Sall au sujet de la pr\u00e9sidentielle de 2024 \u00e0 la Une"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/04\/discours-03-AVRIL-MACKY-SALL.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/24092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=24092"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/24092\/revisions"}],"predecessor-version":[{"id":24093,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/24092\/revisions\/24093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/19287"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=24092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=24092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=24092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}