{"id":27465,"date":"2023-09-27T13:48:00","date_gmt":"2023-09-27T13:48:00","guid":{"rendered":"https:\/\/www.public.sn\/?p=27465"},"modified":"2023-09-27T13:48:00","modified_gmt":"2023-09-27T13:48:00","slug":"meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/","title":{"rendered":"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau"},"content":{"rendered":"<p>Les populations de Faoune, d\u00e9partement de Bounkiling, vivent depuis hier\u00a0dans la tristesse et la consternation. Pour cause, un alcoolique a tu\u00e9 son fr\u00e8re\u00a0\u00e0 coups de couteau.\u00a0Ivrogne et r\u00e9put\u00e9 galopin dans son village, Faoune Torodo, M. S. Diallo a tu\u00e9\u00a0hier son petit fr\u00e8re K. Diallo \u00e0 coup de couteau. Selon des t\u00e9moins, la victime a trouv\u00e9 son fr\u00e8re disputer avec sa maman\u00a0qu\u2019il mena\u00e7ait de tuer, K. Diallo a intervenu et sugg\u00e8re solennellement son\u00a0grand de laisser tranquillement sa m\u00e8re. M. S. Diallo change de cible et\u00a0maintenant il prof\u00e8re contre son fr\u00e8re. Une menace qu\u2019il ex\u00e9cutera quelques\u00a0minutes apr\u00e8s. D\u2019apr\u00e8s notre interlocuteur, il a surpris son fr\u00e8re assis dans un\u00a0coin de la maison famille et qui manipulait son t\u00e9l\u00e9phone.<\/p><div id=\"publi-2746373960\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Ainsi, il lui a ass\u00e9n\u00e9\u00a0trois coups de couteau. La victime a perdu la vie avant m\u00eame avant son arriv\u00e9e\u00a0au dispensaire de Faoune. Alert\u00e9, les limiers de la brigade de la gendarmerie de\u00a0Bounkiling ont mis la main sur le meurtrier et le corps sans vie a \u00e9t\u00e9 achemin\u00e9 \u00e0\u00a0l\u2019h\u00f4pital r\u00e9gional de S\u00e9dhiou pour des raisons d\u2019autopsie. Selon nos sources,\u00a0l\u2019homme qui vivait en Gambie o\u00f9 il \u00e9tait depuis longtemps d\u00e9tenu \u00e0 la prison\u00a0de Miles Two de Banjul et depuis son retour au village natal, il \u00e9tait dans de\u00a0sale besogne et menacer souvent de tuer ses parents. Une enqu\u00eate a \u00e9t\u00e9\u00a0ouverte par la l\u00e9gion de la gendarmerie de Bounkiling.<\/p>\n<div id=\"publi-1088526891\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les populations de Faoune, d\u00e9partement de Bounkiling, vivent depuis hier\u00a0dans la tristesse et la consternation. Pour cause, un alcoolique a tu\u00e9 son fr\u00e8re\u00a0\u00e0 coups de couteau.\u00a0Ivrogne et r\u00e9put\u00e9 galopin dans son village, Faoune Torodo, M. S. Diallo a tu\u00e9\u00a0hier son petit fr\u00e8re K. Diallo \u00e0 coup de couteau. Selon des t\u00e9moins, la victime a trouv\u00e9 son fr\u00e8re disputer avec sa maman\u00a0qu\u2019il mena\u00e7ait de tuer, K. Diallo a intervenu et sugg\u00e8re solennellement son\u00a0grand de laisser tranquillement sa m\u00e8re. M. S. Diallo change de cible et\u00a0maintenant il prof\u00e8re contre son fr\u00e8re. Une menace qu\u2019il ex\u00e9cutera quelques\u00a0minutes apr\u00e8s. D\u2019apr\u00e8s notre interlocuteur, il a surpris son fr\u00e8re assis dans un\u00a0coin de la maison famille et qui manipulait son t\u00e9l\u00e9phone. Ainsi, il lui a ass\u00e9n\u00e9\u00a0trois coups de couteau. La victime a perdu la vie avant m\u00eame avant son arriv\u00e9e\u00a0au dispensaire de Faoune. Alert\u00e9, les limiers de la brigade de la gendarmerie de\u00a0Bounkiling ont mis la main sur le meurtrier et le corps sans vie a \u00e9t\u00e9 achemin\u00e9 \u00e0\u00a0l\u2019h\u00f4pital r\u00e9gional de S\u00e9dhiou pour des raisons d\u2019autopsie. Selon nos sources,\u00a0l\u2019homme qui vivait en Gambie o\u00f9 il \u00e9tait depuis longtemps d\u00e9tenu \u00e0 la prison\u00a0de Miles Two de Banjul et depuis son retour au village natal, il \u00e9tait dans de\u00a0sale besogne et menacer souvent de tuer ses parents. Une enqu\u00eate a \u00e9t\u00e9\u00a0ouverte par la l\u00e9gion de la gendarmerie de Bounkiling.<\/p>\n","protected":false},"author":7,"featured_media":27466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,3,1,4,372],"tags":[],"class_list":["post-27465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-politique","category-non-classe","category-societe","category-vedette","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"Les populations de Faoune, d\u00e9partement de Bounkiling, vivent depuis hier\u00a0dans la tristesse et la consternation. Pour cause, un alcoolique a tu\u00e9 son fr\u00e8re\u00a0\u00e0 coups de couteau.\u00a0Ivrogne et r\u00e9put\u00e9 galopin dans son village, Faoune Torodo, M. S. Diallo a tu\u00e9\u00a0hier son petit fr\u00e8re K. Diallo \u00e0 coup de couteau. Selon des t\u00e9moins, la victime a trouv\u00e9 son fr\u00e8re disputer avec sa maman\u00a0qu\u2019il mena\u00e7ait de tuer, K. Diallo a intervenu et sugg\u00e8re solennellement son\u00a0grand de laisser tranquillement sa m\u00e8re. M. S. Diallo change de cible et\u00a0maintenant il prof\u00e8re contre son fr\u00e8re. Une menace qu\u2019il ex\u00e9cutera quelques\u00a0minutes apr\u00e8s. D\u2019apr\u00e8s notre interlocuteur, il a surpris son fr\u00e8re assis dans un\u00a0coin de la maison famille et qui manipulait son t\u00e9l\u00e9phone. Ainsi, il lui a ass\u00e9n\u00e9\u00a0trois coups de couteau. La victime a perdu la vie avant m\u00eame avant son arriv\u00e9e\u00a0au dispensaire de Faoune. Alert\u00e9, les limiers de la brigade de la gendarmerie de\u00a0Bounkiling ont mis la main sur le meurtrier et le corps sans vie a \u00e9t\u00e9 achemin\u00e9 \u00e0\u00a0l\u2019h\u00f4pital r\u00e9gional de S\u00e9dhiou pour des raisons d\u2019autopsie. Selon nos sources,\u00a0l\u2019homme qui vivait en Gambie o\u00f9 il \u00e9tait depuis longtemps d\u00e9tenu \u00e0 la prison\u00a0de Miles Two de Banjul et depuis son retour au village natal, il \u00e9tait dans de\u00a0sale besogne et menacer souvent de tuer ses parents. Une enqu\u00eate a \u00e9t\u00e9\u00a0ouverte par la l\u00e9gion de la gendarmerie de Bounkiling.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T13:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/cb76c8e1b8becc6be61fb5e92d6d0224\"},\"headline\":\"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau\",\"datePublished\":\"2023-09-27T13:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/\"},\"wordCount\":280,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Sapeurs.jpeg\",\"articleSection\":[\"ACTUALIT\u00c9S\",\"POLITIQUE\",\"S\u00c9N\u00c9GAL\",\"SOCIETE\",\"VEDETTE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/\",\"name\":\"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Sapeurs.jpeg\",\"datePublished\":\"2023-09-27T13:48:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Sapeurs.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Sapeurs.jpeg\",\"width\":600,\"height\":397},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2023\\\/09\\\/27\\\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/cb76c8e1b8becc6be61fb5e92d6d0224\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/editeurpsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/","og_locale":"fr_FR","og_type":"article","og_title":"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau - LE PUBLIC","og_description":"Les populations de Faoune, d\u00e9partement de Bounkiling, vivent depuis hier\u00a0dans la tristesse et la consternation. Pour cause, un alcoolique a tu\u00e9 son fr\u00e8re\u00a0\u00e0 coups de couteau.\u00a0Ivrogne et r\u00e9put\u00e9 galopin dans son village, Faoune Torodo, M. S. Diallo a tu\u00e9\u00a0hier son petit fr\u00e8re K. Diallo \u00e0 coup de couteau. Selon des t\u00e9moins, la victime a trouv\u00e9 son fr\u00e8re disputer avec sa maman\u00a0qu\u2019il mena\u00e7ait de tuer, K. Diallo a intervenu et sugg\u00e8re solennellement son\u00a0grand de laisser tranquillement sa m\u00e8re. M. S. Diallo change de cible et\u00a0maintenant il prof\u00e8re contre son fr\u00e8re. Une menace qu\u2019il ex\u00e9cutera quelques\u00a0minutes apr\u00e8s. D\u2019apr\u00e8s notre interlocuteur, il a surpris son fr\u00e8re assis dans un\u00a0coin de la maison famille et qui manipulait son t\u00e9l\u00e9phone. Ainsi, il lui a ass\u00e9n\u00e9\u00a0trois coups de couteau. La victime a perdu la vie avant m\u00eame avant son arriv\u00e9e\u00a0au dispensaire de Faoune. Alert\u00e9, les limiers de la brigade de la gendarmerie de\u00a0Bounkiling ont mis la main sur le meurtrier et le corps sans vie a \u00e9t\u00e9 achemin\u00e9 \u00e0\u00a0l\u2019h\u00f4pital r\u00e9gional de S\u00e9dhiou pour des raisons d\u2019autopsie. Selon nos sources,\u00a0l\u2019homme qui vivait en Gambie o\u00f9 il \u00e9tait depuis longtemps d\u00e9tenu \u00e0 la prison\u00a0de Miles Two de Banjul et depuis son retour au village natal, il \u00e9tait dans de\u00a0sale besogne et menacer souvent de tuer ses parents. Une enqu\u00eate a \u00e9t\u00e9\u00a0ouverte par la l\u00e9gion de la gendarmerie de Bounkiling.","og_url":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/","og_site_name":"LE PUBLIC","article_published_time":"2023-09-27T13:48:00+00:00","og_image":[{"width":600,"height":397,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/cb76c8e1b8becc6be61fb5e92d6d0224"},"headline":"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau","datePublished":"2023-09-27T13:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/"},"wordCount":280,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg","articleSection":["ACTUALIT\u00c9S","POLITIQUE","S\u00c9N\u00c9GAL","SOCIETE","VEDETTE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/","url":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/","name":"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg","datePublished":"2023-09-27T13:48:00+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg","width":600,"height":397},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2023\/09\/27\/meurtre-a-sedhio-mamadou-s-diallo-tue-son-frere-a-coups-de-couteau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"MEURTRE A S\u00c9DHIO : Mamadou S. Diallo tue son fr\u00e8re \u00e0 coups de couteau"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/cb76c8e1b8becc6be61fb5e92d6d0224","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","caption":"LA REDACTION"},"url":"https:\/\/www.public.sn\/index.php\/author\/editeurpsn\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2023\/09\/Sapeurs.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/27465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=27465"}],"version-history":[{"count":1,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/27465\/revisions"}],"predecessor-version":[{"id":27467,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/27465\/revisions\/27467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/27466"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=27465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=27465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=27465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}