{"id":3892,"date":"2022-10-07T16:05:13","date_gmt":"2022-10-07T16:05:13","guid":{"rendered":"https:\/\/www.public.sn\/?p=3892"},"modified":"2022-10-07T16:05:14","modified_gmt":"2022-10-07T16:05:14","slug":"ucad-les-campus-rouvrent-le-9-octobre","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/","title":{"rendered":"UCAD : Les campus rouvrent le  9 Octobre."},"content":{"rendered":"\n<p><br><br><strong>Dimanche 09 Octobre 2022 \u00e0 09 heures. C\u2019est la date fix\u00e9e par la direction du COUD pour la r\u00e9ouverture des campus sociaux de Dakar. <\/strong><\/p><div class=\"publi-paragraphe1\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"publi-3042249739\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n\n\n\n<p>Le communiqu\u00e9 pr\u00e9cise que les \u00e9tudiants codifi\u00e9s au titre de l\u2019ann\u00e9e universitaire 2021\/2022 peuvent se rapprocher des services en charge de l\u2019h\u00e9bergement pour remplir les formalit\u00e9s administratives avant de regagner leur chambre jusqu\u2019\u00e0 la fin des examens pr\u00e9vus dans les diff\u00e9rents \u00e9tablissements. Apr\u00e8s la fin des examens, de nouvelles codifications vont se faire. Toutefois il est rappel\u00e9 \u00e0 tous que les mesures de s\u00e9curit\u00e9 au sein des campus sont toujours de rigueur.<br><\/p>\n\n\n\n<p>Pour acc\u00e9der aux campus sociaux, les \u00e9tudiants doivent, obligatoirement, se munir de leur carte d\u2019\u00e9tudiant en cours de validit\u00e9, les membres du personnel de leur carte professionnelle et les usagers de leur pi\u00e8ce d\u2019identification nationale.<br>La Direction du COUD souhaite ainsi aux \u00e9tudiants un tr\u00e8s bon retour et les appelle \u00e0 un bon usage de leurs r\u00e9sidences.<br><br>Samba SY,<br><\/p>\n<div class=\"publi-apres-le-contenu\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"publi-455708134\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dimanche 09 Octobre 2022 \u00e0 09 heures. C\u2019est la date fix\u00e9e par la direction du COUD pour la r\u00e9ouverture des campus sociaux de Dakar. Le communiqu\u00e9 pr\u00e9cise que les \u00e9tudiants codifi\u00e9s au titre de l\u2019ann\u00e9e universitaire 2021\/2022 peuvent se rapprocher des services en charge de l\u2019h\u00e9bergement pour remplir les formalit\u00e9s administratives avant de regagner leur chambre jusqu\u2019\u00e0 la fin des examens pr\u00e9vus dans les diff\u00e9rents \u00e9tablissements. Apr\u00e8s la fin des examens, de nouvelles codifications vont se faire. Toutefois il est rappel\u00e9 \u00e0 tous que les mesures de s\u00e9curit\u00e9 au sein des campus sont toujours de rigueur. Pour acc\u00e9der aux campus sociaux, les \u00e9tudiants doivent, obligatoirement, se munir de leur carte d\u2019\u00e9tudiant en cours de validit\u00e9, les membres du personnel de leur carte professionnelle et les usagers de leur pi\u00e8ce d\u2019identification nationale.La Direction du COUD souhaite ainsi aux \u00e9tudiants un tr\u00e8s bon retour et les appelle \u00e0 un bon usage de leurs r\u00e9sidences. Samba SY,<\/p>\n","protected":false},"author":1,"featured_media":3901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,854,1],"tags":[1278,1279,584],"class_list":["post-3892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-education","category-non-classe","tag-campus","tag-reouverture","tag-ucad","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UCAD : Les campus rouvrent le 9 Octobre. - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UCAD : Les campus rouvrent le 9 Octobre. - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"Dimanche 09 Octobre 2022 \u00e0 09 heures. C\u2019est la date fix\u00e9e par la direction du COUD pour la r\u00e9ouverture des campus sociaux de Dakar. Le communiqu\u00e9 pr\u00e9cise que les \u00e9tudiants codifi\u00e9s au titre de l\u2019ann\u00e9e universitaire 2021\/2022 peuvent se rapprocher des services en charge de l\u2019h\u00e9bergement pour remplir les formalit\u00e9s administratives avant de regagner leur chambre jusqu\u2019\u00e0 la fin des examens pr\u00e9vus dans les diff\u00e9rents \u00e9tablissements. Apr\u00e8s la fin des examens, de nouvelles codifications vont se faire. Toutefois il est rappel\u00e9 \u00e0 tous que les mesures de s\u00e9curit\u00e9 au sein des campus sont toujours de rigueur. Pour acc\u00e9der aux campus sociaux, les \u00e9tudiants doivent, obligatoirement, se munir de leur carte d\u2019\u00e9tudiant en cours de validit\u00e9, les membres du personnel de leur carte professionnelle et les usagers de leur pi\u00e8ce d\u2019identification nationale.La Direction du COUD souhaite ainsi aux \u00e9tudiants un tr\u00e8s bon retour et les appelle \u00e0 un bon usage de leurs r\u00e9sidences. Samba SY,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T16:05:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-07T16:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a\"},\"headline\":\"UCAD : Les campus rouvrent le 9 Octobre.\",\"datePublished\":\"2022-10-07T16:05:13+00:00\",\"dateModified\":\"2022-10-07T16:05:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\"},\"wordCount\":174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.public.sn\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png\",\"keywords\":[\"campus\",\"reouverture\",\"Ucad\"],\"articleSection\":[\"ACTUALIT\u00c9S\",\"\u00c9DUCATION\",\"S\u00c9N\u00c9GAL\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\",\"url\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\",\"name\":\"UCAD : Les campus rouvrent le 9 Octobre. - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\/\/www.public.sn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png\",\"datePublished\":\"2022-10-07T16:05:13+00:00\",\"dateModified\":\"2022-10-07T16:05:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage\",\"url\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png\",\"contentUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png\",\"width\":700,\"height\":330,\"caption\":\"publicsn\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.public.sn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UCAD : Les campus rouvrent le 9 Octobre.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.public.sn\/#website\",\"url\":\"https:\/\/www.public.sn\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.public.sn\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.public.sn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.public.sn\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\/\/www.public.sn\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\/\/www.public.sn\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.public.sn\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"sameAs\":[\"http:\/\/www.public.sn\"],\"url\":\"https:\/\/www.public.sn\/index.php\/author\/admin7324\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UCAD : Les campus rouvrent le 9 Octobre. - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/","og_locale":"fr_FR","og_type":"article","og_title":"UCAD : Les campus rouvrent le 9 Octobre. - LE PUBLIC","og_description":"Dimanche 09 Octobre 2022 \u00e0 09 heures. C\u2019est la date fix\u00e9e par la direction du COUD pour la r\u00e9ouverture des campus sociaux de Dakar. Le communiqu\u00e9 pr\u00e9cise que les \u00e9tudiants codifi\u00e9s au titre de l\u2019ann\u00e9e universitaire 2021\/2022 peuvent se rapprocher des services en charge de l\u2019h\u00e9bergement pour remplir les formalit\u00e9s administratives avant de regagner leur chambre jusqu\u2019\u00e0 la fin des examens pr\u00e9vus dans les diff\u00e9rents \u00e9tablissements. Apr\u00e8s la fin des examens, de nouvelles codifications vont se faire. Toutefois il est rappel\u00e9 \u00e0 tous que les mesures de s\u00e9curit\u00e9 au sein des campus sont toujours de rigueur. Pour acc\u00e9der aux campus sociaux, les \u00e9tudiants doivent, obligatoirement, se munir de leur carte d\u2019\u00e9tudiant en cours de validit\u00e9, les membres du personnel de leur carte professionnelle et les usagers de leur pi\u00e8ce d\u2019identification nationale.La Direction du COUD souhaite ainsi aux \u00e9tudiants un tr\u00e8s bon retour et les appelle \u00e0 un bon usage de leurs r\u00e9sidences. Samba SY,","og_url":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/","og_site_name":"LE PUBLIC","article_published_time":"2022-10-07T16:05:13+00:00","article_modified_time":"2022-10-07T16:05:14+00:00","og_image":[{"width":700,"height":330,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png","type":"image\/png"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a"},"headline":"UCAD : Les campus rouvrent le 9 Octobre.","datePublished":"2022-10-07T16:05:13+00:00","dateModified":"2022-10-07T16:05:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/"},"wordCount":174,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png","keywords":["campus","reouverture","Ucad"],"articleSection":["ACTUALIT\u00c9S","\u00c9DUCATION","S\u00c9N\u00c9GAL"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/","url":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/","name":"UCAD : Les campus rouvrent le 9 Octobre. - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png","datePublished":"2022-10-07T16:05:13+00:00","dateModified":"2022-10-07T16:05:14+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png","width":700,"height":330,"caption":"publicsn"},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2022\/10\/07\/ucad-les-campus-rouvrent-le-9-octobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"UCAD : Les campus rouvrent le 9 Octobre."}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/e3f4a11b037d4203902db148f9bc8d5a","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6c030db45db2883c075085c5d6c6258654a801a93766b49af0b82d4f454e2a5?s=96&d=mm&r=g","caption":"LA REDACTION"},"sameAs":["http:\/\/www.public.sn"],"url":"https:\/\/www.public.sn\/index.php\/author\/admin7324\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/10\/ucad.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/3892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=3892"}],"version-history":[{"count":2,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/3892\/revisions"}],"predecessor-version":[{"id":3902,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/3892\/revisions\/3902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/3901"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=3892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=3892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=3892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}