{"id":9037,"date":"2022-11-17T13:38:09","date_gmt":"2022-11-17T13:38:09","guid":{"rendered":"https:\/\/www.public.sn\/?p=9037"},"modified":"2022-11-17T13:38:11","modified_gmt":"2022-11-17T13:38:11","slug":"vote-du-budget-guy-marius-budget-door-la","status":"publish","type":"post","link":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/","title":{"rendered":"Vote du budget : Guy Marius : \u00ab\u00a0Budget door la\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les d\u00e9put\u00e9s ont proc\u00e9d\u00e9 ce Jeudi \u00e0 l\u2019ouverture de l\u2019Examen du vote du budget de l\u2019ann\u00e9e 2024. Occasion pour certains de poser les revendications des popuations et pour d\u2019autres de vanter les r\u00e9alisation du pr\u00e9sident de la R\u00e9publique.<\/p><div id=\"publi-392417836\" class=\"publi-paragraphe1 publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Voici quelques interventions de quelques  parlementaires<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">l &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cheikh Abdou Mback\u00e9 Doly&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9put\u00e9 f\u00e9licite d\u2019embl\u00e9e le ministre de Finances Moustapha Ba ainsi que ses collaborateurs pour le travail qu\u2019ils accomplissent pour le S\u00e9n\u00e9gal. Il demande ainsi aux imp\u00f4ts et domaine de redoubler d\u2019efforts pour que le monde rural puisse disposer de moyens pour leur survie. La mission du FMI a \u00e9t\u00e9 une r\u00e9ussite mais il faut interpeller les populations sur leur v\u00e9cu quotidien. Les paysans sont fatigu\u00e9s, les \u00e9leveurs ont des probl\u00e8mes pour et la p\u00eache rencontre beaucoup de difficult\u00e9s car les conventions ont fini par piller la mer. La dette publique est excessive et il faudra prendre des mesures.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mady Danfakha&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le d\u00e9put\u00e9 les chiffres sont moins importants mais leur impact sur le v\u00e9cu des s\u00e9n\u00e9galais. A Saraya le taux d\u2019\u00e9lectricit\u00e9 \u00e9tait presque nul mais pr\u00e9s de 3000 lampadaires ont \u00e9t\u00e9 convoy\u00e9 vers la localit\u00e9 et Saraya va en disposer 1200. Le nombre de kilom\u00e8tres a r\u00e9aliser par d\u00e9partement et la modernisation des villes religieuses mais il faut en inclure les villages religieux dans certaines r\u00e9gions et il faut penser a am\u00e9liorer le quotidien des s\u00e9n\u00e9galais. Les cotonculteurs sont dans d\u2019\u00e9normes difficult\u00e9s et quelles sont les dispositions prises contre les attaques des mouches. Karim Wade sera l\u00e0 en 2024 pour continuer l\u2019\u0153uvre du pr\u00e9sident Macky Sall<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Coura Ndiaye&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">la d\u00e9put\u00e9e r\u00e9it\u00e8re ses f\u00e9licitations et au pr\u00e9sident au regard des performances r\u00e9ussies par le pr\u00e9sident et qui ont valu les f\u00e9licitations du FMI. Et cela s\u2019est fait avec l\u2019implication de tous. C\u2019est un budget de solution qui doit s\u2019adosser \u00e0 ce qui est r\u00e9alisable. La situation \u00e9conomique, la covid et la guerre entre l\u2019Ukraine et la Russie n\u2019ont pas obstru\u00e9 les performances du pr\u00e9sident de la R\u00e9publique. La subvention de plus de 4000 Milliards,35 Milliards pour les bourses de solidarit\u00e9 familiale et la baisse du budget de la pr\u00e9sidence. Lors u conseil des ministre du 13 Avril le pr\u00e9sident avait annonce un nouveau h\u00f4pital de niveau 3 a Mbour et des explications sur l\u2019endettement du S\u00e9n\u00e9gal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ndiaga Niang&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est revenu sur l\u2019inflation et \u00e0 la baisse des prix des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9. Les s\u00e9n\u00e9galais sont fatigu\u00e9 d\u2019entendre parler croissance car ils n\u2019y croient pas et rien n\u2019a \u00e9t\u00e9 vu. Cette croissance est hexog\u00e8ne et non pas endog\u00e8ne car votre communication doit \u00eatre revue. Une les entreprises s\u00e9n\u00e9galaises puissent se sentir dans cette croissance. Les moteurs hors bord des p\u00eacheurs ne sont pas accessibles \u00e0 tous les p\u00eacheurs du littoral avec votre subvention d\u2019un million. Les p\u00eacheurs doivent \u00eatre soutenus car leur m\u00e9tier est noble et la mer est de plus en plus pill\u00e9e. Le ministre de la p\u00eache r\u00e9v\u00e8le que pour 13 Milliards on a brad\u00e9 nos c\u00f4tes mais la mer doit \u00eatre surveill\u00e9e. Les p\u00eacheurs artisanaux doivent \u00eatre impliqu\u00e9s dans la surveillance<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sokhna Ba Numero 2&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Bugdet est plus de 6400 Milliard et il faut que cela impacte sur le v\u00e9cu des s\u00e9n\u00e9galais. Le taux de croissance \u00e9tait de 6% avant de passer selon vos chiffres \u00e0 10.1 en 2024. L\u2019inflation qui se poursuit et les agriculteurs qui avancent qui disent qu\u2019ils auront plus de pailles que d\u2019arachide. Il existe des institutions budg\u00e9tivores telles que le HCCT et le CESE qui n\u2019ont aucune utilit\u00e9 alors que des enfants des iles du Saloum traversent des ponts d\u00e9labr\u00e9s pour se rendre \u00e0 l\u2019\u00e9cole il faut revoir l\u2019utilit\u00e9 de ces institutions qui doivent m\u00eame \u00eatre dissoutes. Les avis consultatifs ne sont pas pris en compte par le pr\u00e9sident et l\u2019argent doit \u00eatre inject\u00e9 ailleurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Souhane Ciss\u00e9<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9put\u00e9 appelle les parlementaires \u00e0 \u00eatre sereins. De 2012 a maintenant le pr\u00e9sident \u00e0 fait des choses aucun pr\u00e9sident n\u2019a r\u00e9ussi. Sur le cas de la Casamance, i est bon que la localit\u00e9 puisse disposer d\u2019\u00e9lectricit\u00e9 c\u2019est le cas \u00e0 S\u00e9noba. Dans le d\u00e9partement de Bounkiling il faut que les villages soient \u00e9lectrifi\u00e9s. Nous sollicitons votre appui. Et des r\u00e9gions comme Niamacouta doivent \u00eatre cit\u00e9 parmi les sites religieux du S\u00e9n\u00e9gal. Le pont Faraf\u00e9gn\u00e9, la boucle du blouff et du Boudi\u00e9 sont des r\u00e9alisations concr\u00e8tes m\u00eame si certaines routes doivent \u00eatre bitum\u00e9es comme l\u2019avaient promis le pr\u00e9sident de la R\u00e9publique. Et pour les bourses familiales et la couverture maladie universelle il faut remettre des salaires aux maitres coraniques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guy Maruis Sagna&nbsp;:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lib\u00e9rez les d\u00e9tenus politiques, lib\u00e9rez pape Al\u00e9 Niang. Ce sont les premiers mots de Guy Marius Sagna. La bont\u00e9 du pr\u00e9sident c\u2019est de distribuer des charrettes et des semoirs qui ne repr\u00e9sentent m\u00eame pas une machine pour un village. Le pr\u00e9sident d\u00e9tourne les fonds du S\u00e9n\u00e9gal. Le budget avance que le paysan paye des imp\u00f4ts alors que son ami milliardaire isra\u00e9lien ne paye rien et c\u2019est le cas de plusieurs fran\u00e7ais qui disposent d\u2019exon\u00e9ration fiscale. Voila pourquoi beaucoup de village comme Boutoukou kamara kounta, m\u00e9dina Yoro Foula, Ndindi etc&nbsp; c\u2019est un budget de \u00ab&nbsp;doorkatt&nbsp;\u00bb avec le premier ministre qui a 500 millions c\u2019est du door . au moment ou des auxiliaire de police sont pay\u00e9s 90.000<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est un budget copain et un budget coquin. Vous faites des exon\u00e9rations alors qu\u2019on paye des dettes et cela n\u2019est pas normal. 2345 de dette c\u2019est une honte alors qu\u2019on donne des cadeaux fiscaux alors qu\u2019ils sont beaucoup plus riches que nos paysans<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Idrissa Bald\u00e9<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ceux qui disent que l\u2019agriculture ne marche ne connaissent rien du monde rural De 84 a404 villages \u00e9lectrifi\u00e9s par an sous le magist\u00e8re du pr\u00e9sident de la R\u00e9publique. Je voterai ce budget pour la r\u00e9alisation du bitumage Kolda Salik\u00e9ni\u00e9 de Dabo \u00e0 Koumba Karang et parce qu\u2019il prend en compte les pr\u00e9occupations du monde paysan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mamadou Ciss\u00e9<\/strong>;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le S\u00e9n\u00e9gal est bien sur la voie de l\u2019\u00e9mergence \u00e0 cause des r\u00e9alisations du pr\u00e9sident de la R\u00e9publique. Le monde rural est bien appuy\u00e9 par le chef de l\u2019Etat. Nous sommes des paysans et personnes ne parlera pour notre compte. On ne parle plus de charrette mais de tracteur. Personne n\u2019osait imaginer que le S\u00e9n\u00e9gal serait \u00e0 cet \u00e9tape mais aujourd\u2019hui il y\u2019a des efforts. Certains ne croient en rien car ils veulent juste tromper les paysans qui doivent \u00eatre plus soutenus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Seydou Dianko\u00a0:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pr\u00e9sident a subventionn\u00e9 le mat\u00e9riel agricole et certains ne parlent que de politiques. Ceux qui ont b\u00e9n\u00e9fici\u00e9 de l\u2019exon\u00e9ration ont cr\u00e9es des usines et des emplois. Les r\u00e9alisations du pr\u00e9sident de la R\u00e9publique n\u2019ont jamais \u00e9t\u00e9 aussi visibles et \u00e0 l\u2019avantage des paysans. Des f\u00e9licitations s\u2019imposent pour la douane qui r\u00e9alis\u00e9 des prises de marchandises frauduleuses et doivent \u00eatre renforc\u00e9s en mat\u00e9riel car la douane fait des r\u00e9sultats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nicolas Ndiaye\u00a0:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le peuple a eu des acquis fondamentaux et le parlement existe depuis 66 ans et marche sans interruption et nous faisons partie des premiers en Afrique car certains pays limitrophes ont connu des interruptions. La d\u00e9mocratie marche au S\u00e9n\u00e9gal car dans cette assembl\u00e9e il y\u2019a le pouvoir, la majorit\u00e9 et les non-inscrits. \u00a0Et sur les acquis basique le S\u00e9n\u00e9gal n\u2019a pas de probl\u00e8me ethnique, confr\u00e9rique ou religieux. Donc il y\u2019a une d\u00e9mocratie qui existe depuis Abdou Diouf, Abdoulaye Wade et aujourd\u2019hui Macky Sall.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Samba SY.<\/p>\n<div id=\"publi-315230168\" class=\"publi-apres-le-contenu publi-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"publi-adlabel\">Publicit\u00e9<\/div><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4089586018074219\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-4089586018074219\" \ndata-ad-slot=\"2087940154\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les d\u00e9put\u00e9s ont proc\u00e9d\u00e9 ce Jeudi \u00e0 l\u2019ouverture de l\u2019Examen du vote du budget de l\u2019ann\u00e9e 2024. Occasion pour certains de poser les revendications des popuations et pour d\u2019autres de vanter les r\u00e9alisation du pr\u00e9sident de la R\u00e9publique. Voici quelques interventions de quelques parlementaires: l &nbsp; Cheikh Abdou Mback\u00e9 Doly&nbsp;: Le d\u00e9put\u00e9 f\u00e9licite d\u2019embl\u00e9e le ministre de Finances Moustapha Ba ainsi que ses collaborateurs pour le travail qu\u2019ils accomplissent pour le S\u00e9n\u00e9gal. Il demande ainsi aux imp\u00f4ts et domaine de redoubler d\u2019efforts pour que le monde rural puisse disposer de moyens pour leur survie. La mission du FMI a \u00e9t\u00e9 une r\u00e9ussite mais il faut interpeller les populations sur leur v\u00e9cu quotidien. Les paysans sont fatigu\u00e9s, les \u00e9leveurs ont des probl\u00e8mes pour et la p\u00eache rencontre beaucoup de difficult\u00e9s car les conventions ont fini par piller la mer. La dette publique est excessive et il faudra prendre des mesures. Mady Danfakha&nbsp;: Pour le d\u00e9put\u00e9 les chiffres sont moins importants mais leur impact sur le v\u00e9cu des s\u00e9n\u00e9galais. A Saraya le taux d\u2019\u00e9lectricit\u00e9 \u00e9tait presque nul mais pr\u00e9s de 3000 lampadaires ont \u00e9t\u00e9 convoy\u00e9 vers la localit\u00e9 et Saraya va en disposer 1200. Le nombre de kilom\u00e8tres a r\u00e9aliser par d\u00e9partement et la modernisation des villes religieuses mais il faut en inclure les villages religieux dans certaines r\u00e9gions et il faut penser a am\u00e9liorer le quotidien des s\u00e9n\u00e9galais. Les cotonculteurs sont dans d\u2019\u00e9normes difficult\u00e9s et quelles sont les dispositions prises contre les attaques des mouches. Karim Wade sera l\u00e0 en 2024 pour continuer l\u2019\u0153uvre du pr\u00e9sident Macky Sall Coura Ndiaye&nbsp;: la d\u00e9put\u00e9e r\u00e9it\u00e8re ses f\u00e9licitations et au pr\u00e9sident au regard des performances r\u00e9ussies par le pr\u00e9sident et qui ont valu les f\u00e9licitations du FMI. Et cela s\u2019est fait avec l\u2019implication de tous. C\u2019est un budget de solution qui doit s\u2019adosser \u00e0 ce qui est r\u00e9alisable. La situation \u00e9conomique, la covid et la guerre entre l\u2019Ukraine et la Russie n\u2019ont pas obstru\u00e9 les performances du pr\u00e9sident de la R\u00e9publique. La subvention de plus de 4000 Milliards,35 Milliards pour les bourses de solidarit\u00e9 familiale et la baisse du budget de la pr\u00e9sidence. Lors u conseil des ministre du 13 Avril le pr\u00e9sident avait annonce un nouveau h\u00f4pital de niveau 3 a Mbour et des explications sur l\u2019endettement du S\u00e9n\u00e9gal Ndiaga Niang&nbsp;: Est revenu sur l\u2019inflation et \u00e0 la baisse des prix des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9. Les s\u00e9n\u00e9galais sont fatigu\u00e9 d\u2019entendre parler croissance car ils n\u2019y croient pas et rien n\u2019a \u00e9t\u00e9 vu. Cette croissance est hexog\u00e8ne et non pas endog\u00e8ne car votre communication doit \u00eatre revue. Une les entreprises s\u00e9n\u00e9galaises puissent se sentir dans cette croissance. Les moteurs hors bord des p\u00eacheurs ne sont pas accessibles \u00e0 tous les p\u00eacheurs du littoral avec votre subvention d\u2019un million. Les p\u00eacheurs doivent \u00eatre soutenus car leur m\u00e9tier est noble et la mer est de plus en plus pill\u00e9e. Le ministre de la p\u00eache r\u00e9v\u00e8le que pour 13 Milliards on a brad\u00e9 nos c\u00f4tes mais la mer doit \u00eatre surveill\u00e9e. Les p\u00eacheurs artisanaux doivent \u00eatre impliqu\u00e9s dans la surveillance Sokhna Ba Numero 2&nbsp;: Le Bugdet est plus de 6400 Milliard et il faut que cela impacte sur le v\u00e9cu des s\u00e9n\u00e9galais. Le taux de croissance \u00e9tait de 6% avant de passer selon vos chiffres \u00e0 10.1 en 2024. L\u2019inflation qui se poursuit et les agriculteurs qui avancent qui disent qu\u2019ils auront plus de pailles que d\u2019arachide. Il existe des institutions budg\u00e9tivores telles que le HCCT et le CESE qui n\u2019ont aucune utilit\u00e9 alors que des enfants des iles du Saloum traversent des ponts d\u00e9labr\u00e9s pour se rendre \u00e0 l\u2019\u00e9cole il faut revoir l\u2019utilit\u00e9 de ces institutions qui doivent m\u00eame \u00eatre dissoutes. Les avis consultatifs ne sont pas pris en compte par le pr\u00e9sident et l\u2019argent doit \u00eatre inject\u00e9 ailleurs. Souhane Ciss\u00e9 Le d\u00e9put\u00e9 appelle les parlementaires \u00e0 \u00eatre sereins. De 2012 a maintenant le pr\u00e9sident \u00e0 fait des choses aucun pr\u00e9sident n\u2019a r\u00e9ussi. Sur le cas de la Casamance, i est bon que la localit\u00e9 puisse disposer d\u2019\u00e9lectricit\u00e9 c\u2019est le cas \u00e0 S\u00e9noba. Dans le d\u00e9partement de Bounkiling il faut que les villages soient \u00e9lectrifi\u00e9s. Nous sollicitons votre appui. Et des r\u00e9gions comme Niamacouta doivent \u00eatre cit\u00e9 parmi les sites religieux du S\u00e9n\u00e9gal. Le pont Faraf\u00e9gn\u00e9, la boucle du blouff et du Boudi\u00e9 sont des r\u00e9alisations concr\u00e8tes m\u00eame si certaines routes doivent \u00eatre bitum\u00e9es comme l\u2019avaient promis le pr\u00e9sident de la R\u00e9publique. Et pour les bourses familiales et la couverture maladie universelle il faut remettre des salaires aux maitres coraniques. Guy Maruis Sagna&nbsp;: Lib\u00e9rez les d\u00e9tenus politiques, lib\u00e9rez pape Al\u00e9 Niang. Ce sont les premiers mots de Guy Marius Sagna. La bont\u00e9 du pr\u00e9sident c\u2019est de distribuer des charrettes et des semoirs qui ne repr\u00e9sentent m\u00eame pas une machine pour un village. Le pr\u00e9sident d\u00e9tourne les fonds du S\u00e9n\u00e9gal. Le budget avance que le paysan paye des imp\u00f4ts alors que son ami milliardaire isra\u00e9lien ne paye rien et c\u2019est le cas de plusieurs fran\u00e7ais qui disposent d\u2019exon\u00e9ration fiscale. Voila pourquoi beaucoup de village comme Boutoukou kamara kounta, m\u00e9dina Yoro Foula, Ndindi etc&nbsp; c\u2019est un budget de \u00ab&nbsp;doorkatt&nbsp;\u00bb avec le premier ministre qui a 500 millions c\u2019est du door . au moment ou des auxiliaire de police sont pay\u00e9s 90.000 C\u2019est un budget copain et un budget coquin. Vous faites des exon\u00e9rations alors qu\u2019on paye des dettes et cela n\u2019est pas normal. 2345 de dette c\u2019est une honte alors qu\u2019on donne des cadeaux fiscaux alors qu\u2019ils sont beaucoup plus riches que nos paysans Idrissa Bald\u00e9: Ceux qui disent que l\u2019agriculture ne marche ne connaissent rien du monde rural De 84 a404 villages \u00e9lectrifi\u00e9s par an sous le magist\u00e8re du pr\u00e9sident de la R\u00e9publique. Je voterai ce budget pour la r\u00e9alisation du bitumage Kolda Salik\u00e9ni\u00e9 de Dabo \u00e0 Koumba Karang et parce qu\u2019il prend en compte les pr\u00e9occupations du monde paysan. Mamadou Ciss\u00e9; Le S\u00e9n\u00e9gal est bien sur la voie de l\u2019\u00e9mergence \u00e0 cause des r\u00e9alisations du pr\u00e9sident de la R\u00e9publique. Le monde rural est bien appuy\u00e9 par le chef de l\u2019Etat. Nous sommes des paysans<\/p>\n","protected":false},"author":7,"featured_media":9038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[375,3,1],"tags":[3012,2262,3011],"class_list":["post-9037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-politique","category-non-classe","tag-parlementaire","tag-rapport","tag-vote-budget","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vote du budget : Guy Marius : &quot;Budget door la&quot; - LE PUBLIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vote du budget : Guy Marius : &quot;Budget door la&quot; - LE PUBLIC\" \/>\n<meta property=\"og:description\" content=\"Les d\u00e9put\u00e9s ont proc\u00e9d\u00e9 ce Jeudi \u00e0 l\u2019ouverture de l\u2019Examen du vote du budget de l\u2019ann\u00e9e 2024. Occasion pour certains de poser les revendications des popuations et pour d\u2019autres de vanter les r\u00e9alisation du pr\u00e9sident de la R\u00e9publique. Voici quelques interventions de quelques parlementaires: l &nbsp; Cheikh Abdou Mback\u00e9 Doly&nbsp;: Le d\u00e9put\u00e9 f\u00e9licite d\u2019embl\u00e9e le ministre de Finances Moustapha Ba ainsi que ses collaborateurs pour le travail qu\u2019ils accomplissent pour le S\u00e9n\u00e9gal. Il demande ainsi aux imp\u00f4ts et domaine de redoubler d\u2019efforts pour que le monde rural puisse disposer de moyens pour leur survie. La mission du FMI a \u00e9t\u00e9 une r\u00e9ussite mais il faut interpeller les populations sur leur v\u00e9cu quotidien. Les paysans sont fatigu\u00e9s, les \u00e9leveurs ont des probl\u00e8mes pour et la p\u00eache rencontre beaucoup de difficult\u00e9s car les conventions ont fini par piller la mer. La dette publique est excessive et il faudra prendre des mesures. Mady Danfakha&nbsp;: Pour le d\u00e9put\u00e9 les chiffres sont moins importants mais leur impact sur le v\u00e9cu des s\u00e9n\u00e9galais. A Saraya le taux d\u2019\u00e9lectricit\u00e9 \u00e9tait presque nul mais pr\u00e9s de 3000 lampadaires ont \u00e9t\u00e9 convoy\u00e9 vers la localit\u00e9 et Saraya va en disposer 1200. Le nombre de kilom\u00e8tres a r\u00e9aliser par d\u00e9partement et la modernisation des villes religieuses mais il faut en inclure les villages religieux dans certaines r\u00e9gions et il faut penser a am\u00e9liorer le quotidien des s\u00e9n\u00e9galais. Les cotonculteurs sont dans d\u2019\u00e9normes difficult\u00e9s et quelles sont les dispositions prises contre les attaques des mouches. Karim Wade sera l\u00e0 en 2024 pour continuer l\u2019\u0153uvre du pr\u00e9sident Macky Sall Coura Ndiaye&nbsp;: la d\u00e9put\u00e9e r\u00e9it\u00e8re ses f\u00e9licitations et au pr\u00e9sident au regard des performances r\u00e9ussies par le pr\u00e9sident et qui ont valu les f\u00e9licitations du FMI. Et cela s\u2019est fait avec l\u2019implication de tous. C\u2019est un budget de solution qui doit s\u2019adosser \u00e0 ce qui est r\u00e9alisable. La situation \u00e9conomique, la covid et la guerre entre l\u2019Ukraine et la Russie n\u2019ont pas obstru\u00e9 les performances du pr\u00e9sident de la R\u00e9publique. La subvention de plus de 4000 Milliards,35 Milliards pour les bourses de solidarit\u00e9 familiale et la baisse du budget de la pr\u00e9sidence. Lors u conseil des ministre du 13 Avril le pr\u00e9sident avait annonce un nouveau h\u00f4pital de niveau 3 a Mbour et des explications sur l\u2019endettement du S\u00e9n\u00e9gal Ndiaga Niang&nbsp;: Est revenu sur l\u2019inflation et \u00e0 la baisse des prix des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9. Les s\u00e9n\u00e9galais sont fatigu\u00e9 d\u2019entendre parler croissance car ils n\u2019y croient pas et rien n\u2019a \u00e9t\u00e9 vu. Cette croissance est hexog\u00e8ne et non pas endog\u00e8ne car votre communication doit \u00eatre revue. Une les entreprises s\u00e9n\u00e9galaises puissent se sentir dans cette croissance. Les moteurs hors bord des p\u00eacheurs ne sont pas accessibles \u00e0 tous les p\u00eacheurs du littoral avec votre subvention d\u2019un million. Les p\u00eacheurs doivent \u00eatre soutenus car leur m\u00e9tier est noble et la mer est de plus en plus pill\u00e9e. Le ministre de la p\u00eache r\u00e9v\u00e8le que pour 13 Milliards on a brad\u00e9 nos c\u00f4tes mais la mer doit \u00eatre surveill\u00e9e. Les p\u00eacheurs artisanaux doivent \u00eatre impliqu\u00e9s dans la surveillance Sokhna Ba Numero 2&nbsp;: Le Bugdet est plus de 6400 Milliard et il faut que cela impacte sur le v\u00e9cu des s\u00e9n\u00e9galais. Le taux de croissance \u00e9tait de 6% avant de passer selon vos chiffres \u00e0 10.1 en 2024. L\u2019inflation qui se poursuit et les agriculteurs qui avancent qui disent qu\u2019ils auront plus de pailles que d\u2019arachide. Il existe des institutions budg\u00e9tivores telles que le HCCT et le CESE qui n\u2019ont aucune utilit\u00e9 alors que des enfants des iles du Saloum traversent des ponts d\u00e9labr\u00e9s pour se rendre \u00e0 l\u2019\u00e9cole il faut revoir l\u2019utilit\u00e9 de ces institutions qui doivent m\u00eame \u00eatre dissoutes. Les avis consultatifs ne sont pas pris en compte par le pr\u00e9sident et l\u2019argent doit \u00eatre inject\u00e9 ailleurs. Souhane Ciss\u00e9 Le d\u00e9put\u00e9 appelle les parlementaires \u00e0 \u00eatre sereins. De 2012 a maintenant le pr\u00e9sident \u00e0 fait des choses aucun pr\u00e9sident n\u2019a r\u00e9ussi. Sur le cas de la Casamance, i est bon que la localit\u00e9 puisse disposer d\u2019\u00e9lectricit\u00e9 c\u2019est le cas \u00e0 S\u00e9noba. Dans le d\u00e9partement de Bounkiling il faut que les villages soient \u00e9lectrifi\u00e9s. Nous sollicitons votre appui. Et des r\u00e9gions comme Niamacouta doivent \u00eatre cit\u00e9 parmi les sites religieux du S\u00e9n\u00e9gal. Le pont Faraf\u00e9gn\u00e9, la boucle du blouff et du Boudi\u00e9 sont des r\u00e9alisations concr\u00e8tes m\u00eame si certaines routes doivent \u00eatre bitum\u00e9es comme l\u2019avaient promis le pr\u00e9sident de la R\u00e9publique. Et pour les bourses familiales et la couverture maladie universelle il faut remettre des salaires aux maitres coraniques. Guy Maruis Sagna&nbsp;: Lib\u00e9rez les d\u00e9tenus politiques, lib\u00e9rez pape Al\u00e9 Niang. Ce sont les premiers mots de Guy Marius Sagna. La bont\u00e9 du pr\u00e9sident c\u2019est de distribuer des charrettes et des semoirs qui ne repr\u00e9sentent m\u00eame pas une machine pour un village. Le pr\u00e9sident d\u00e9tourne les fonds du S\u00e9n\u00e9gal. Le budget avance que le paysan paye des imp\u00f4ts alors que son ami milliardaire isra\u00e9lien ne paye rien et c\u2019est le cas de plusieurs fran\u00e7ais qui disposent d\u2019exon\u00e9ration fiscale. Voila pourquoi beaucoup de village comme Boutoukou kamara kounta, m\u00e9dina Yoro Foula, Ndindi etc&nbsp; c\u2019est un budget de \u00ab&nbsp;doorkatt&nbsp;\u00bb avec le premier ministre qui a 500 millions c\u2019est du door . au moment ou des auxiliaire de police sont pay\u00e9s 90.000 C\u2019est un budget copain et un budget coquin. Vous faites des exon\u00e9rations alors qu\u2019on paye des dettes et cela n\u2019est pas normal. 2345 de dette c\u2019est une honte alors qu\u2019on donne des cadeaux fiscaux alors qu\u2019ils sont beaucoup plus riches que nos paysans Idrissa Bald\u00e9: Ceux qui disent que l\u2019agriculture ne marche ne connaissent rien du monde rural De 84 a404 villages \u00e9lectrifi\u00e9s par an sous le magist\u00e8re du pr\u00e9sident de la R\u00e9publique. Je voterai ce budget pour la r\u00e9alisation du bitumage Kolda Salik\u00e9ni\u00e9 de Dabo \u00e0 Koumba Karang et parce qu\u2019il prend en compte les pr\u00e9occupations du monde paysan. Mamadou Ciss\u00e9; Le S\u00e9n\u00e9gal est bien sur la voie de l\u2019\u00e9mergence \u00e0 cause des r\u00e9alisations du pr\u00e9sident de la R\u00e9publique. Le monde rural est bien appuy\u00e9 par le chef de l\u2019Etat. Nous sommes des paysans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/\" \/>\n<meta property=\"og:site_name\" content=\"LE PUBLIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-17T13:38:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-17T13:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"268\" \/>\n\t<meta property=\"og:image:height\" content=\"188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LA REDACTION\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"LA REDACTION\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/\"},\"author\":{\"name\":\"LA REDACTION\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/cb76c8e1b8becc6be61fb5e92d6d0224\"},\"headline\":\"Vote du budget : Guy Marius : \u00ab\u00a0Budget door la\u00a0\u00bb\",\"datePublished\":\"2022-11-17T13:38:09+00:00\",\"dateModified\":\"2022-11-17T13:38:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/\"},\"wordCount\":1399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/assemblee-nationale.jpg\",\"keywords\":[\"parlementaire\",\"rapport\",\"vote budget\"],\"articleSection\":[\"ACTUALIT\u00c9S\",\"POLITIQUE\",\"S\u00c9N\u00c9GAL\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/\",\"name\":\"Vote du budget : Guy Marius : \\\"Budget door la\\\" - LE PUBLIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/assemblee-nationale.jpg\",\"datePublished\":\"2022-11-17T13:38:09+00:00\",\"dateModified\":\"2022-11-17T13:38:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/assemblee-nationale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/assemblee-nationale.jpg\",\"width\":268,\"height\":188,\"caption\":\"publicsn\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/2022\\\/11\\\/17\\\/vote-du-budget-guy-marius-budget-door-la\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.public.sn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vote du budget : Guy Marius : \u00ab\u00a0Budget door la\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#website\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"name\":\"LE PUBLIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.public.sn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#organization\",\"name\":\"LE PUBLIC\",\"url\":\"https:\\\/\\\/www.public.sn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"contentUrl\":\"https:\\\/\\\/www.public.sn\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-LOGO-PUBLIC.SN_.png\",\"width\":682,\"height\":192,\"caption\":\"LE PUBLIC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.public.sn\\\/#\\\/schema\\\/person\\\/cb76c8e1b8becc6be61fb5e92d6d0224\",\"name\":\"LA REDACTION\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g\",\"caption\":\"LA REDACTION\"},\"url\":\"https:\\\/\\\/www.public.sn\\\/index.php\\\/author\\\/editeurpsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vote du budget : Guy Marius : \"Budget door la\" - LE PUBLIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/","og_locale":"fr_FR","og_type":"article","og_title":"Vote du budget : Guy Marius : \"Budget door la\" - LE PUBLIC","og_description":"Les d\u00e9put\u00e9s ont proc\u00e9d\u00e9 ce Jeudi \u00e0 l\u2019ouverture de l\u2019Examen du vote du budget de l\u2019ann\u00e9e 2024. Occasion pour certains de poser les revendications des popuations et pour d\u2019autres de vanter les r\u00e9alisation du pr\u00e9sident de la R\u00e9publique. Voici quelques interventions de quelques parlementaires: l &nbsp; Cheikh Abdou Mback\u00e9 Doly&nbsp;: Le d\u00e9put\u00e9 f\u00e9licite d\u2019embl\u00e9e le ministre de Finances Moustapha Ba ainsi que ses collaborateurs pour le travail qu\u2019ils accomplissent pour le S\u00e9n\u00e9gal. Il demande ainsi aux imp\u00f4ts et domaine de redoubler d\u2019efforts pour que le monde rural puisse disposer de moyens pour leur survie. La mission du FMI a \u00e9t\u00e9 une r\u00e9ussite mais il faut interpeller les populations sur leur v\u00e9cu quotidien. Les paysans sont fatigu\u00e9s, les \u00e9leveurs ont des probl\u00e8mes pour et la p\u00eache rencontre beaucoup de difficult\u00e9s car les conventions ont fini par piller la mer. La dette publique est excessive et il faudra prendre des mesures. Mady Danfakha&nbsp;: Pour le d\u00e9put\u00e9 les chiffres sont moins importants mais leur impact sur le v\u00e9cu des s\u00e9n\u00e9galais. A Saraya le taux d\u2019\u00e9lectricit\u00e9 \u00e9tait presque nul mais pr\u00e9s de 3000 lampadaires ont \u00e9t\u00e9 convoy\u00e9 vers la localit\u00e9 et Saraya va en disposer 1200. Le nombre de kilom\u00e8tres a r\u00e9aliser par d\u00e9partement et la modernisation des villes religieuses mais il faut en inclure les villages religieux dans certaines r\u00e9gions et il faut penser a am\u00e9liorer le quotidien des s\u00e9n\u00e9galais. Les cotonculteurs sont dans d\u2019\u00e9normes difficult\u00e9s et quelles sont les dispositions prises contre les attaques des mouches. Karim Wade sera l\u00e0 en 2024 pour continuer l\u2019\u0153uvre du pr\u00e9sident Macky Sall Coura Ndiaye&nbsp;: la d\u00e9put\u00e9e r\u00e9it\u00e8re ses f\u00e9licitations et au pr\u00e9sident au regard des performances r\u00e9ussies par le pr\u00e9sident et qui ont valu les f\u00e9licitations du FMI. Et cela s\u2019est fait avec l\u2019implication de tous. C\u2019est un budget de solution qui doit s\u2019adosser \u00e0 ce qui est r\u00e9alisable. La situation \u00e9conomique, la covid et la guerre entre l\u2019Ukraine et la Russie n\u2019ont pas obstru\u00e9 les performances du pr\u00e9sident de la R\u00e9publique. La subvention de plus de 4000 Milliards,35 Milliards pour les bourses de solidarit\u00e9 familiale et la baisse du budget de la pr\u00e9sidence. Lors u conseil des ministre du 13 Avril le pr\u00e9sident avait annonce un nouveau h\u00f4pital de niveau 3 a Mbour et des explications sur l\u2019endettement du S\u00e9n\u00e9gal Ndiaga Niang&nbsp;: Est revenu sur l\u2019inflation et \u00e0 la baisse des prix des denr\u00e9es de premi\u00e8re n\u00e9cessit\u00e9. Les s\u00e9n\u00e9galais sont fatigu\u00e9 d\u2019entendre parler croissance car ils n\u2019y croient pas et rien n\u2019a \u00e9t\u00e9 vu. Cette croissance est hexog\u00e8ne et non pas endog\u00e8ne car votre communication doit \u00eatre revue. Une les entreprises s\u00e9n\u00e9galaises puissent se sentir dans cette croissance. Les moteurs hors bord des p\u00eacheurs ne sont pas accessibles \u00e0 tous les p\u00eacheurs du littoral avec votre subvention d\u2019un million. Les p\u00eacheurs doivent \u00eatre soutenus car leur m\u00e9tier est noble et la mer est de plus en plus pill\u00e9e. Le ministre de la p\u00eache r\u00e9v\u00e8le que pour 13 Milliards on a brad\u00e9 nos c\u00f4tes mais la mer doit \u00eatre surveill\u00e9e. Les p\u00eacheurs artisanaux doivent \u00eatre impliqu\u00e9s dans la surveillance Sokhna Ba Numero 2&nbsp;: Le Bugdet est plus de 6400 Milliard et il faut que cela impacte sur le v\u00e9cu des s\u00e9n\u00e9galais. Le taux de croissance \u00e9tait de 6% avant de passer selon vos chiffres \u00e0 10.1 en 2024. L\u2019inflation qui se poursuit et les agriculteurs qui avancent qui disent qu\u2019ils auront plus de pailles que d\u2019arachide. Il existe des institutions budg\u00e9tivores telles que le HCCT et le CESE qui n\u2019ont aucune utilit\u00e9 alors que des enfants des iles du Saloum traversent des ponts d\u00e9labr\u00e9s pour se rendre \u00e0 l\u2019\u00e9cole il faut revoir l\u2019utilit\u00e9 de ces institutions qui doivent m\u00eame \u00eatre dissoutes. Les avis consultatifs ne sont pas pris en compte par le pr\u00e9sident et l\u2019argent doit \u00eatre inject\u00e9 ailleurs. Souhane Ciss\u00e9 Le d\u00e9put\u00e9 appelle les parlementaires \u00e0 \u00eatre sereins. De 2012 a maintenant le pr\u00e9sident \u00e0 fait des choses aucun pr\u00e9sident n\u2019a r\u00e9ussi. Sur le cas de la Casamance, i est bon que la localit\u00e9 puisse disposer d\u2019\u00e9lectricit\u00e9 c\u2019est le cas \u00e0 S\u00e9noba. Dans le d\u00e9partement de Bounkiling il faut que les villages soient \u00e9lectrifi\u00e9s. Nous sollicitons votre appui. Et des r\u00e9gions comme Niamacouta doivent \u00eatre cit\u00e9 parmi les sites religieux du S\u00e9n\u00e9gal. Le pont Faraf\u00e9gn\u00e9, la boucle du blouff et du Boudi\u00e9 sont des r\u00e9alisations concr\u00e8tes m\u00eame si certaines routes doivent \u00eatre bitum\u00e9es comme l\u2019avaient promis le pr\u00e9sident de la R\u00e9publique. Et pour les bourses familiales et la couverture maladie universelle il faut remettre des salaires aux maitres coraniques. Guy Maruis Sagna&nbsp;: Lib\u00e9rez les d\u00e9tenus politiques, lib\u00e9rez pape Al\u00e9 Niang. Ce sont les premiers mots de Guy Marius Sagna. La bont\u00e9 du pr\u00e9sident c\u2019est de distribuer des charrettes et des semoirs qui ne repr\u00e9sentent m\u00eame pas une machine pour un village. Le pr\u00e9sident d\u00e9tourne les fonds du S\u00e9n\u00e9gal. Le budget avance que le paysan paye des imp\u00f4ts alors que son ami milliardaire isra\u00e9lien ne paye rien et c\u2019est le cas de plusieurs fran\u00e7ais qui disposent d\u2019exon\u00e9ration fiscale. Voila pourquoi beaucoup de village comme Boutoukou kamara kounta, m\u00e9dina Yoro Foula, Ndindi etc&nbsp; c\u2019est un budget de \u00ab&nbsp;doorkatt&nbsp;\u00bb avec le premier ministre qui a 500 millions c\u2019est du door . au moment ou des auxiliaire de police sont pay\u00e9s 90.000 C\u2019est un budget copain et un budget coquin. Vous faites des exon\u00e9rations alors qu\u2019on paye des dettes et cela n\u2019est pas normal. 2345 de dette c\u2019est une honte alors qu\u2019on donne des cadeaux fiscaux alors qu\u2019ils sont beaucoup plus riches que nos paysans Idrissa Bald\u00e9: Ceux qui disent que l\u2019agriculture ne marche ne connaissent rien du monde rural De 84 a404 villages \u00e9lectrifi\u00e9s par an sous le magist\u00e8re du pr\u00e9sident de la R\u00e9publique. Je voterai ce budget pour la r\u00e9alisation du bitumage Kolda Salik\u00e9ni\u00e9 de Dabo \u00e0 Koumba Karang et parce qu\u2019il prend en compte les pr\u00e9occupations du monde paysan. Mamadou Ciss\u00e9; Le S\u00e9n\u00e9gal est bien sur la voie de l\u2019\u00e9mergence \u00e0 cause des r\u00e9alisations du pr\u00e9sident de la R\u00e9publique. Le monde rural est bien appuy\u00e9 par le chef de l\u2019Etat. Nous sommes des paysans","og_url":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/","og_site_name":"LE PUBLIC","article_published_time":"2022-11-17T13:38:09+00:00","article_modified_time":"2022-11-17T13:38:11+00:00","og_image":[{"width":268,"height":188,"url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg","type":"image\/jpeg"}],"author":"LA REDACTION","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"LA REDACTION","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#article","isPartOf":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/"},"author":{"name":"LA REDACTION","@id":"https:\/\/www.public.sn\/#\/schema\/person\/cb76c8e1b8becc6be61fb5e92d6d0224"},"headline":"Vote du budget : Guy Marius : \u00ab\u00a0Budget door la\u00a0\u00bb","datePublished":"2022-11-17T13:38:09+00:00","dateModified":"2022-11-17T13:38:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/"},"wordCount":1399,"commentCount":0,"publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg","keywords":["parlementaire","rapport","vote budget"],"articleSection":["ACTUALIT\u00c9S","POLITIQUE","S\u00c9N\u00c9GAL"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/","url":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/","name":"Vote du budget : Guy Marius : \"Budget door la\" - LE PUBLIC","isPartOf":{"@id":"https:\/\/www.public.sn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#primaryimage"},"image":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#primaryimage"},"thumbnailUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg","datePublished":"2022-11-17T13:38:09+00:00","dateModified":"2022-11-17T13:38:11+00:00","breadcrumb":{"@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#primaryimage","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg","width":268,"height":188,"caption":"publicsn"},{"@type":"BreadcrumbList","@id":"https:\/\/www.public.sn\/index.php\/2022\/11\/17\/vote-du-budget-guy-marius-budget-door-la\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.public.sn\/"},{"@type":"ListItem","position":2,"name":"Vote du budget : Guy Marius : \u00ab\u00a0Budget door la\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.public.sn\/#website","url":"https:\/\/www.public.sn\/","name":"LE PUBLIC","description":"","publisher":{"@id":"https:\/\/www.public.sn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public.sn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.public.sn\/#organization","name":"LE PUBLIC","url":"https:\/\/www.public.sn\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/","url":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","contentUrl":"https:\/\/www.public.sn\/wp-content\/uploads\/2024\/05\/cropped-LOGO-PUBLIC.SN_.png","width":682,"height":192,"caption":"LE PUBLIC"},"image":{"@id":"https:\/\/www.public.sn\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.public.sn\/#\/schema\/person\/cb76c8e1b8becc6be61fb5e92d6d0224","name":"LA REDACTION","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2dce5ddd34b8fef0180efe03aa2a9bee7d953856048f9a16b298190a3178407c?s=96&d=mm&r=g","caption":"LA REDACTION"},"url":"https:\/\/www.public.sn\/index.php\/author\/editeurpsn\/"}]}},"jetpack_featured_media_url":"https:\/\/www.public.sn\/wp-content\/uploads\/2022\/11\/assemblee-nationale.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/9037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/comments?post=9037"}],"version-history":[{"count":2,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/9037\/revisions"}],"predecessor-version":[{"id":9040,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/posts\/9037\/revisions\/9040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media\/9038"}],"wp:attachment":[{"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/media?parent=9037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/categories?post=9037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public.sn\/index.php\/wp-json\/wp\/v2\/tags?post=9037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}